{"id":75789,"date":"2015-02-05T07:10:20","date_gmt":"2015-02-05T10:10:20","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=75789"},"modified":"2015-02-06T14:07:37","modified_gmt":"2015-02-06T17:07:37","slug":"petrobras-anuncia-nomes-de-diretores-que-renunciaram-aos-cargos","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/petrobras-anuncia-nomes-de-diretores-que-renunciaram-aos-cargos\/","title":{"rendered":"Petrobras anuncia nomes de diretores que renunciaram aos cargos"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Do G1, em S\u00e3o Paulo<\/em><\/p>\n<p style=\"text-align: justify;\">A Petrobras divulgou comunicado na noite desta quarta-feira (4) com os nomes dos cinco diretores que, junto com a presidente da empresa, Gra\u00e7a Foster, apresentaram ren\u00fancia de seus cargos. S\u00e3o eles: Almir Guilherme Barbassa (Diretor Financeiro e de Relacionamento com Investidores), Jos\u00e9 Miranda Formigli (Diretor de Explora\u00e7\u00e3o e Produ\u00e7\u00e3o), Jos\u00e9 Carlos Cosenza (Diretor de Abastecimento), Jos\u00e9 Alcides Santoro (Diretor de G\u00e1s e Energia) e Jos\u00e9 Ant\u00f4nio de Figueiredo (Diretor de Engenharia, Tecnologia e Materiais).<\/p>\n<div id=\"attachment_75790\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/Gra\u00e7a-Foster.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-75790\" class=\"size-full wp-image-75790\" alt=\"Presidente-executiva da Petrobras, Gra\u00e7a Foster, em foto de ter\u00e7a-feira (3) ap\u00f3s encontro com a presidente Dilma Rousseff. (Foto: Reuters\/Ueslei Marcelino )\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/Gra\u00e7a-Foster.jpg\" width=\"595\" height=\"446\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/Gra\u00e7a-Foster.jpg 595w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/Gra\u00e7a-Foster-300x224.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/Gra\u00e7a-Foster-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/Gra\u00e7a-Foster-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/Gra\u00e7a-Foster-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/Gra\u00e7a-Foster-269x201.jpg 269w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-75790\" class=\"wp-caption-text\">Presidente-executiva da Petrobras, Gra\u00e7a Foster, em foto de ter\u00e7a-feira (3) ap\u00f3s encontro com a presidente Dilma Rousseff. (Foto: Reuters\/Ueslei Marcelino )<\/p><\/div>\n<p style=\"text-align: justify;\">No comunicado, a Petrobras afirma que a ren\u00fancia da presidente e dos outros cinco diretores &#8220;ter\u00e1 efeito a partir de sexta-feira (6), data em que o Conselho de Administra\u00e7\u00e3o se reunir\u00e1 para eleger os novos membros da diretoria&#8221;.<\/p>\n<p style=\"text-align: justify;\">O Jo\u00e3o Adalberto Elek, da Diretoria de Govenan\u00e7a, e\u00a0Jos\u00e9 Eduardo Dutra, da Diretoria Corporativa e de Servi\u00e7os, n\u00e3o foram citados na lista.<\/p>\n<p style=\"text-align: justify;\">Os rumores sobre a sa\u00edda de Gra\u00e7a ao longo da ter\u00e7a-feira fizeram disparar as a\u00e7\u00f5es da Petrobras, que fecharam em alta de mais de 15% na Bovespa. Nesta quarta, os pap\u00e9is da petroleira chegaram a subir mais de 7%, mas reduziram o ritmo de alta. No final do preg\u00e3o, as a\u00e7\u00f5es preferenciais fecharam com leve avan\u00e7o de 0,2%.<\/p>\n<p style=\"text-align: justify;\">A sa\u00edda da diretoria acontece em meio \u00e0s investiga\u00e7\u00f5es da Opera\u00e7\u00e3o Lava Jato de um esc\u00e2ndalo de corrup\u00e7\u00e3o na estatal e \u00e0 dificuldade da atual gest\u00e3o da companhia para quantificar os preju\u00edzos com fraudes em contratos de obras durante anos.<\/p>\n<p style=\"text-align: justify;\">O governo vinha sofrendo press\u00e3o do mercado pela sa\u00edda da executiva, cuja gest\u00e3o foi marcada por graves den\u00fancias de corrup\u00e7\u00e3o e pelo ac\u00famulo de resultados negativos.<\/p>\n<p style=\"text-align: justify;\">Embora a maior parte dos problemas tenha sido agravada por decis\u00f5es feitas antes da chegada de Gra\u00e7a Foster \u00e0 presid\u00eancia da estatal, a executiva \u2013 ainda que n\u00e3o tenha sido implicada diretamente nas investiga\u00e7\u00f5es da Lava Jato \u2013 acabou perdendo as condi\u00e7\u00f5es pol\u00edticas para se manter no cargo.<\/p>\n<p style=\"text-align: justify;\"><strong>Sa\u00edda esperada<br \/>\n<\/strong><br \/>\nNa ter\u00e7a-feira, o colunista Gerson Camarotti adiantou que interlocutores da presidente Dilma Rousseff estavam em busca de um substituto para Gra\u00e7a no comando da Petrobras e disse que a substitui\u00e7\u00e3o seria feita quando for encontrado um perfil adequado.<\/p>\n<p>Gra\u00e7a passou a tarde de ter\u00e7a-feira reunida com a presidente Dilma Rousseff, mas nenhuma decis\u00e3o foi anunciada at\u00e9 a manh\u00e3 desta quarta.<\/p>\n<p><strong>Assista no v\u00eddeo ao lado: Thais Her\u00e9dia comenta a sa\u00edda de Gra\u00e7a Foster<\/strong><\/p>\n<p><strong>An\u00fancio a investidores<\/strong><br \/>\nQuando as a\u00e7\u00f5es de uma empresa oscilam muito em um dia, a Bovespa envia um of\u00edcio a ela questionando o que ocorreu. Nesta ter\u00e7a-feira, a bolsa questionou a Petrobras sobre a sa\u00edda de Gra\u00e7a Foster e pediu esclarecimentos, &#8220;o mais breve poss\u00edvel&#8221;, al\u00e9m de outras informa\u00e7\u00f5es consideradas importantes.<\/p>\n<p>A Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), que fiscaliza e disciplina o mercado, deu um limite para a resposta: 9h desta quarta-feira.<\/p>\n<p>\u00c0s 10h13, a Petrobras enviou um comunicado dizendo: &#8220;Em resposta a esta solicita\u00e7\u00e3o, a Petrobras informa que seu Conselho de Administra\u00e7\u00e3o se reunir\u00e1 na pr\u00f3xima sexta-feira, dia 06.02.2015, para eleger nova Diretoria face \u00e0 ren\u00fancia da Presidente e de cinco Diretores&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>Poss\u00edveis substitutos<br \/>\n<\/strong><br \/>\nEm coluna publicada nesta ter\u00e7a-feira (3), Thais Her\u00e9dia adiantou que dois nomes s\u00e3o os mais cotados para assumir a vaga de Gra\u00e7a: Roger Agnelli, que esteve no comando da Vale por mais de 10 anos; e Rodolfo Landim, ex-parceiro de Eike Batista e atual desafeto do empres\u00e1rio, com passagens pela Eletrobr\u00e1s e BR Distribuidora.<\/p>\n<p style=\"text-align: justify;\"><strong>.Acompanhe o SE Not\u00edcias no <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e no <a href=\"  https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Outros tr\u00eas nomes tamb\u00e9m apareceram entre os cotados para o posto nesta quarta: Henrique Meirelles, ex-presidente do BC; Murilo Ferreira, atual presidente da Vale; e Eduarda La Rocque, ex-secret\u00e1ria da Fazenda do munic\u00edpio do Rio de Janeiro.<\/p>\n<p style=\"text-align: justify;\">Segundo a colunista, Roger Agnelli tem forte liga\u00e7\u00e3o com o ex-presidente Lula, mas n\u00e3o \u00e9 bem visto pela presidente Dilma Rousseff. Agnelli foi demitido por ela no in\u00edcio do 2011.<\/p>\n<p style=\"text-align: justify;\">Rodolfo Landim \u00e9 conhecido e respeitado no mercado internacional de \u00f3leo e g\u00e1s, com mais de 30 anos no setor. O fato de ter sa\u00eddo brigado com Eike Batista antes mesmo da derrocada do ex-mega-empres\u00e1rio aumenta seu cacife. Hoje, o executivo toca a Mare Investimentos, um fundo de compra de participa\u00e7\u00e3o em empresas de \u00f3leo e g\u00e1s.<\/p>\n<p style=\"text-align: justify;\">H<strong>ist\u00f3rico<br \/>\n<\/strong><br \/>\nMaria das Gra\u00e7as Silva Foster assumiu a presid\u00eancia da petroleira em 13 de fevereiro de 2012. Ela foi a escolhida para substituir Jos\u00e9 Sergio Gabrielli, que estava h\u00e1 7 anos no comando da companhia.<\/p>\n<p style=\"text-align: justify;\">Funcion\u00e1ria de carreira da Petrobras, Gra\u00e7a Foster ingressou na Petrobras em 1978 e se tornou a primeira mulher do mundo a comandar uma empresa de petr\u00f3leo de grande porte. Ela foi eleita pela revista norte-americana \u201cFortune\u201d a executiva mais poderosa fora dos EUA e ficou em 4\u00ba lugar no ranking mundial.<\/p>\n<p style=\"text-align: justify;\">A chegada de Gra\u00e7a Foster \u00e0 presid\u00eancia foi vista inicialmente como a uma tentativa de implementa\u00e7\u00e3o de uma gest\u00e3o mais t\u00e9cnica e menos pol\u00edtica. Mas a companhia continuou submetendo a sua pol\u00edtica de pre\u00e7os \u00e0s determina\u00e7\u00f5es do seu controlador, o governo, que para tentar frear a infla\u00e7\u00e3o segurou os pre\u00e7os dos combust\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do G1, em S\u00e3o Paulo A Petrobras divulgou comunicado na noite desta quarta-feira (4) com os nomes dos cinco diretores que, junto com a presidente da empresa, Gra\u00e7a Foster, apresentaram ren\u00fancia de seus cargos. S\u00e3o eles: Almir Guilherme Barbassa (Diretor Financeiro e de Relacionamento com Investidores), Jos\u00e9 Miranda Formigli (Diretor de Explora\u00e7\u00e3o e Produ\u00e7\u00e3o), Jos\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-75789","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/75789"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=75789"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/75789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/75790"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=75789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=75789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=75789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}