{"id":74163,"date":"2014-12-23T12:36:53","date_gmt":"2014-12-23T15:36:53","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=74163"},"modified":"2014-12-23T12:36:53","modified_gmt":"2014-12-23T15:36:53","slug":"tarifa-do-transporte-coletivo-de-aracaju-passa-a-custar-r-270","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tarifa-do-transporte-coletivo-de-aracaju-passa-a-custar-r-270\/","title":{"rendered":"Tarifa do transporte coletivo de Aracaju passa a custar R$ 2,70"},"content":{"rendered":"<p style=\"text-align: justify;\">A partir desta ter\u00e7a-feira (23) a tarifa do transporte coletivo em Aracaju, passa a custar R$ 2,70. O reajuste foi aprovado na C\u00e2mara Municipal na semana passada e o decreto do prefeito Jo\u00e3o Alves Filho autorizando o aumento foi publicado no Di\u00e1rio Oficial do munic\u00edpio. O aumento foi de R$ 0,35.<\/p>\n<div id=\"attachment_74164\" style=\"width: 593px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/onibuspma11.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-74164\" class=\" wp-image-74164   \" alt=\"A partir da zero hora desta ter\u00e7a-feira 23, a tarifa do transporte coletivo de Aracaju passa a ser R$ 2,70. (Foto: Reprodu\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/onibuspma11.jpg\" width=\"583\" height=\"375\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/onibuspma11.jpg 800w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/onibuspma11-300x192.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/onibuspma11-342x219.jpg 342w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/><\/a><p id=\"caption-attachment-74164\" class=\"wp-caption-text\">A partir da zero hora desta ter\u00e7a-feira 23, a tarifa do transporte coletivo de Aracaju passa a ser R$ 2,70. (Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">O projeto havia sido entregue para vota\u00e7\u00e3o dos parlamentares somente na noite de ter\u00e7a-feira (16).<\/p>\n<p style=\"text-align: justify;\">Representantes do Movimento N\u00e3o Pago fizeram uma manifesta\u00e7\u00e3o em frente \u00e0 C\u00e2mara dos Vereadores de Aracaju (CMA) na manh\u00e3 desta quarta-feira (17), eles s\u00e3o contra a aprova\u00e7\u00e3o do projeto de lei que reajusta a passagem do \u00f4nibus que faz o transporte p\u00fablico na capital e \u00e1rea metropolitana de R$ 2,35 para R$ 2,70.<\/p>\n<p style=\"text-align: justify;\">\u201cEsse projeto do aumento da tarifa chega de forma absurda e desrespeitosa com o povo aracajuano. Ele foi entregue no calar da noite sem sequer discutir o assunto com a sociedade e sem a apresenta\u00e7\u00e3o das justificativas desse reajuste de 15%. A lei garante a audi\u00eancia da sociedade civil, da C\u00e2mara e da popula\u00e7\u00e3o sobre qualquer tema relacionado ao transporte p\u00fablico antes de alguma mudan\u00e7a. A situa\u00e7\u00e3o desse servi\u00e7o \u00e9 ca\u00f3tica, problem\u00e1tica e n\u00e3o melhorou quase nada no \u00faltimo ano\u201d, destaca o vereador Lucas Arib\u00e9 (PSB).<\/p>\n<p style=\"text-align: justify;\">Para Dem\u00e9trio Varj\u00e3o, assessor de comunica\u00e7\u00e3o do Movimento N\u00e3o Pago, quer que o projeto do aumento da passagem seja discutido pela sociedade antes de ir para vota\u00e7\u00e3o. \u201cMais uma vez tamb\u00e9m solicitamos acesso \u00e0s planilhas que justifiquem esse pedido, ainda n\u00e3o tivemos acesso aos mesmos dados utilizados como argumento no in\u00edcio de 2014. N\u00e3o tenho d\u00favida que ele ser\u00e1 baseado em fraudes como o mesmo apresentado no ano passado\u201d, afirma.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do G1, em Sergipe<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir desta ter\u00e7a-feira (23) a tarifa do transporte coletivo em Aracaju, passa a custar R$ 2,70. O reajuste foi aprovado na C\u00e2mara Municipal na semana passada e o decreto do prefeito Jo\u00e3o Alves Filho autorizando o aumento foi publicado no Di\u00e1rio Oficial do munic\u00edpio. O aumento foi de R$ 0,35. O projeto havia sido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":74164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-74163","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/74163"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=74163"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/74163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/74164"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=74163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=74163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=74163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}