{"id":74157,"date":"2014-12-23T12:14:39","date_gmt":"2014-12-23T15:14:39","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=74157"},"modified":"2014-12-23T12:14:39","modified_gmt":"2014-12-23T15:14:39","slug":"homem-e-baleado-em-tentativa-de-assalto-na-zona-de-expansao","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/homem-e-baleado-em-tentativa-de-assalto-na-zona-de-expansao\/","title":{"rendered":"Homem \u00e9 baleado em tentativa de assalto na Zona de Expans\u00e3o"},"content":{"rendered":"<p style=\"text-align: justify;\">Uma tentativa de roubo terminou com um homem baleado no in\u00edcio desta ter\u00e7a-feira (23). O fato aconteceu por volta das 07h da manh\u00e3, no entorno do povoado Robalo, Zona de Expans\u00e3o, quando dois rapazes tentaram assaltar um outro jovem que seguia numa motoneta \u2013 modelo Shineray.<\/p>\n<div id=\"attachment_74158\" style=\"width: 559px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/conteudo_2_45351_20141223101008_549969b0ce638.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-74158\" class=\" wp-image-74158 \" alt=\"Foto: WhatsApp\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/conteudo_2_45351_20141223101008_549969b0ce638.jpg\" width=\"549\" height=\"503\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/conteudo_2_45351_20141223101008_549969b0ce638.jpg 610w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/conteudo_2_45351_20141223101008_549969b0ce638-300x274.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/conteudo_2_45351_20141223101008_549969b0ce638-342x313.jpg 342w\" sizes=\"(max-width: 549px) 100vw, 549px\" \/><\/a><p id=\"caption-attachment-74158\" class=\"wp-caption-text\">Foto: WhatsApp<\/p><\/div>\n<p style=\"text-align: justify;\">Segundo informa\u00e7\u00f5es de populares passadas \u00e0 pol\u00edcia, ao notar a aproxima\u00e7\u00e3o dos bandidos o homem tentou fugir e foi baleado na coxa. Mesmo ferido, ainda de acordo com testemunhas, a v\u00edtima conseguiu chegar at\u00e9 um hipermercado da regi\u00e3o, sendo socorrido em seguida.<\/p>\n<p style=\"text-align: justify;\">O tenente coronel Carlos Rollemberg confirmou a ocorr\u00eancia e revela que a v\u00edtima foi encaminhada para o Hospital de Urg\u00eancia de Sergipe (HUSE), mas passa bem.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do A8SE<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook\u00a0<\/a><\/strong><em><br \/>\n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma tentativa de roubo terminou com um homem baleado no in\u00edcio desta ter\u00e7a-feira (23). O fato aconteceu por volta das 07h da manh\u00e3, no entorno do povoado Robalo, Zona de Expans\u00e3o, quando dois rapazes tentaram assaltar um outro jovem que seguia numa motoneta \u2013 modelo Shineray. Segundo informa\u00e7\u00f5es de populares passadas \u00e0 pol\u00edcia, ao notar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":74158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-74157","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/74157"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=74157"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/74157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/74158"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=74157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=74157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=74157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}