{"id":74150,"date":"2014-12-23T11:55:48","date_gmt":"2014-12-23T14:55:48","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=74150"},"modified":"2014-12-23T11:59:13","modified_gmt":"2014-12-23T14:59:13","slug":"corpo-do-radialista-iran-machado-e-sepultado-em-povoado-de-dores","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/corpo-do-radialista-iran-machado-e-sepultado-em-povoado-de-dores\/","title":{"rendered":"Corpo do radialista Iran Machado \u00e9 sepultado em povoado de Dores"},"content":{"rendered":"<p style=\"text-align: justify;\">O corpo do radialista Iran Machado foi sepultado na manh\u00e3 desta ter\u00e7a-feira (22) no Cemit\u00e9rio da Par\u00f3quia no Povoado Bravo Urubu, localizado no munic\u00edpio de Nossa Senhora das Dores, distante a 68 Km de Aracaju.<\/p>\n<div id=\"attachment_74151\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/caixao.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-74151\" class=\" wp-image-74151 \" alt=\"Corpo do radialista Iran Machado segue em cortejo para o cemit\u00e9rio (Foto: Jhonny Everton \/ TV Sergipe) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/caixao.jpg\" width=\"558\" height=\"419\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/caixao.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/caixao-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/caixao-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/caixao-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/caixao-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/caixao-269x201.jpg 269w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-74151\" class=\"wp-caption-text\">Corpo do radialista Iran Machado segue em cortejo para o cemit\u00e9rio (Foto: Jhonny Everton \/ TV Sergipe)<\/p><\/div>\n<p style=\"text-align: justify;\">Uma missa foi celebrada no in\u00edcio desta manh\u00e3 na casa da fam\u00edlia do comunicador no munic\u00edpio de Cumbe, em seguida o corpo seguiu em cortejo para o sepultamento.<\/p>\n<p style=\"text-align: justify;\">Amigos, familiares e esportistas participaram da cerim\u00f4nia e se despediram do &#8216;Rep\u00f3rter Mito&#8217;, como era carinhosamente chamado.<\/p>\n<p style=\"text-align: justify;\">O radialista Iran Machado foi assassinado na manh\u00e3 desta segunda-feira, em Itabaiana. De acordo com informa\u00e7\u00f5es da Pol\u00edcia Militar, ele foi morto a tiros na porta de sua resid\u00eancia, no Conjunto Francisco Teles de Mendon\u00e7a, quando chegava do trabalho.<\/p>\n<p style=\"text-align: justify;\">O crime vai ser investigado pelo delegado da cidade. Iran tinha 55 anos e trabalhava como rep\u00f3rter esportivo nas r\u00e1dios S\u00e3o Domingos FM e Capital do Agreste, al\u00e9m de prestar servi\u00e7os t\u00e9cnicos em outras emissoras.<\/p>\n<p style=\"text-align: justify;\">Iran Machado era conhecido por colecionar causos durante as transmiss\u00f5es esportivas. Sempre irreverente, cativava a torcida no est\u00e1dio e tinha um p\u00fablico fiel de ouvintes.<\/p>\n<p style=\"text-align: justify;\">Algumas de suas passagens marcantes no r\u00e1dio esportivo foram lembradas por ele e colegas de profiss\u00e3o em entrevista ao GloboEsporte.com em 2012. Consta que, certa vez, ele foi obrigado a fazer, sozinho, a narra\u00e7\u00e3o, os coment\u00e1rios e a reportagem de uma partida de futebol do Campeonato Sergipano porque seus companheiros de transmiss\u00e3o faltaram. Iran tamb\u00e9m j\u00e1 foi atacado por um enxame de abelhas em campo e entrou no gramado antes do encerramento de uma partida para entrevistar um jogador.<\/p>\n<p style=\"text-align: justify;\"><em>*Com informa\u00e7\u00f5es do Globoesporte.com\/se<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta no<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\"> Facebook\u00a0<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O corpo do radialista Iran Machado foi sepultado na manh\u00e3 desta ter\u00e7a-feira (22) no Cemit\u00e9rio da Par\u00f3quia no Povoado Bravo Urubu, localizado no munic\u00edpio de Nossa Senhora das Dores, distante a 68 Km de Aracaju. Uma missa foi celebrada no in\u00edcio desta manh\u00e3 na casa da fam\u00edlia do comunicador no munic\u00edpio de Cumbe, em seguida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":74151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-74150","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/74150"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=74150"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/74150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/74151"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=74150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=74150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=74150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}