{"id":73788,"date":"2014-12-13T06:50:24","date_gmt":"2014-12-13T09:50:24","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73788"},"modified":"2014-12-15T09:49:35","modified_gmt":"2014-12-15T12:49:35","slug":"empresarios-e-investidores-apoiam-reforma-e-modernizacao-do-estado","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/empresarios-e-investidores-apoiam-reforma-e-modernizacao-do-estado\/","title":{"rendered":"Empres\u00e1rios e investidores apoiam reforma e moderniza\u00e7\u00e3o do Estado"},"content":{"rendered":"<div align=\"justify\">\n<div id=\"attachment_73790\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/fies1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73790\" class=\"size-medium wp-image-73790\" alt=\"presidente do FIES, Eduardo Prado parabenizou o governador Jackson Barreto pelo projeto de moderniza\u00e7\u00e3o administrativa. (Foto: ASN)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/fies1-300x191.jpg\" width=\"300\" height=\"191\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/fies1-300x191.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/fies1-342x218.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/fies1.jpg 594w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-73790\" class=\"wp-caption-text\">presidente do FIES, Eduardo Prado parabenizou o governador Jackson Barreto pelo projeto de moderniza\u00e7\u00e3o administrativa. (Foto: ASN)<\/p><\/div>\n<p>Empres\u00e1rios e investidores sergipanos declararam apoio ao projeto de moderniza\u00e7\u00e3o e reforma administrativa do Governo. O ato ocorreu nesta sexta-feira, 12, durante almo\u00e7o que reuniu empres\u00e1rios do setor industrial, autoridades e o governador Jackson Barreto na sede da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Sergipe (FIES). Durante o almo\u00e7o, foi lan\u00e7ado o Guia de Oportunidades para Investidores.Na oportunidade, o presidente do FIES, Eduardo Prado parabenizou o governador Jackson Barreto pelo projeto de moderniza\u00e7\u00e3o administrativa e declarou o apoio da categoria \u00e0 iniciativa que pretende economizar R$ 249 milh\u00f5es por ano. \u201cJackson Barreto \u00e9 um verdadeiro estadista fazendo essa reforma que foi prometida por muitos e nunca havia sido executada. O governador tem o apoio da Federa\u00e7\u00e3o das Ind\u00fastrias de Sergipe\u201d, declarou.<\/p>\n<p>O projeto de medidas para modernizar o Estado e reduzir despesas foi apresentado \u00e0 imprensa na \u00faltima ter\u00e7a-feira, 09, e abrange a fus\u00e3o nove secret\u00e1rias e a extin\u00e7\u00e3o de todas as subsecretarias. Encaminhada para aprecia\u00e7\u00e3o e vota\u00e7\u00e3o dos deputados estaduais, a reforma extingue todos os cargos de Secret\u00e1rio Adjunto do governo e cria a fun\u00e7\u00e3o de Secret\u00e1rio Executivo em nove secretarias. Com os cortes, a meta \u00e9 economizar mais de R$ 20 milh\u00f5es por m\u00eas.<\/p>\n<p>Jackson Barreto agradeceu o apoio da FIES e real\u00e7ou a import\u00e2ncia do di\u00e1logo com a classe industrial para manter Sergipe nos trilhos do desenvolvimento.\u201cMuitas vezes \u00e9 preciso cortar na carne e ter a coragem de assumir o papel de modernizar o estado\u201d, disse Jackson, que agradeceu ainda o apoio da Associa\u00e7\u00e3o Comercial de Sergipe (Acese) na reforma administrativa.<\/p>\n<p>Segundo o presidente da Acese, Alexandre Porto, a moderniza\u00e7\u00e3o est\u00e1 sendo feita de forma corajosa pelo governador. \u201cAcho que a gente precisa ter a clara compreens\u00e3o de que a economia mudou e as rela\u00e7\u00f5es do poder publico t\u00eam mudado com o passar dos anos, \u00e9 preciso enquadrar a m\u00e1quina \u00e0 realidade atual. Acho que o governador Jackson Barreto est\u00e1 enfrentando um problema que vem ocorrendo h\u00e1 muitos anos no setor p\u00fabico de um modo geral, em todo o pa\u00eds, e que precisava ser feita em algum momento. O enxugamento da m\u00e1quina, a redu\u00e7\u00e3o dos cargos em comiss\u00e3o eram propostas discutidas pelas classes empresariais, ditas ao governador durante sua campanha. \u00c9 uma medida acertada\u201d, declarou.<\/p>\n<p><strong>Sindicalistas<\/strong><\/p>\n<p>Ao longo da semana, outras entidades defenderam a reforma. O Sindicato dos Servidores do Servi\u00e7o P\u00fablico do Estado (Sintrase), que representa quase 20 mil servidores, elogiou o projeto de conten\u00e7\u00e3o de despesas, que quando executado permitir\u00e1 a implanta\u00e7\u00e3o plena do Plano de Cargos, Sal\u00e1rios e Vencimentos (PCCV) da base do servi\u00e7o do p\u00fablico.<\/p>\n<p>\u201cSou a favor da reforma, sim. Precisamos realmente reformular a m\u00e1quina e saber como os servidores ficar\u00e3o. Concordo plenamente\u201d, afirmou o presidente da entidade, Waldir Rodrigues.<\/p>\n<p>J\u00e1 o presidente do Sindicato dos Servidores do Poder Judici\u00e1rio (Sindijus), Pl\u00ednio Pugliesi defende a redu\u00e7\u00e3o dos cargos comissionados e o fim das incorpora\u00e7\u00f5es salariais. \u201cTemos consenso no que diz respeito \u00e0 redu\u00e7\u00e3o de cargos e fim das incorpora\u00e7\u00f5es de cargos de comiss\u00e3o e fun\u00e7\u00f5es de confian\u00e7a. Essa \u00e9 uma luta antiga da categoria. Acreditamos que o governo precisa dialogar com os sindicatos para que a reforma deixe de ser temida pelos servidores e passe a ser constru\u00edda\u201d.<\/p>\n<p>Representante do Sindicato dos trabalhadores na \u00e1rea de Sa\u00fade, Augusto Couto acredita que a moderniza\u00e7\u00e3o da m\u00e1quina administrativa \u00e9 necess\u00e1ria. \u201cO governo tem que fazer o esfor\u00e7o para sair do limite prudencial. Acreditamos que a reforma ir\u00e1 modernizar o Estado e ajudar\u00e1 na implanta\u00e7\u00e3o de nosso Plano de Cargos\u201d, disse Couto, cujo sindicato representa 2.500 servidores da sa\u00fade, entre t\u00e9cnicos administrativos e auxiliares de enfermagem.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<\/div>\n<p><em>Secretaria de Estado da Comunica\u00e7\u00e3o Social<\/em><br \/>\n<em> Governo de Sergipe<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empres\u00e1rios e investidores sergipanos declararam apoio ao projeto de moderniza\u00e7\u00e3o e reforma administrativa do Governo. O ato ocorreu nesta sexta-feira, 12, durante almo\u00e7o que reuniu empres\u00e1rios do setor industrial, autoridades e o governador Jackson Barreto na sede da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Sergipe (FIES). Durante o almo\u00e7o, foi lan\u00e7ado o Guia de Oportunidades [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-73788","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73788"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73788"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/73790"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}