{"id":73781,"date":"2014-12-12T17:37:08","date_gmt":"2014-12-12T20:37:08","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73781"},"modified":"2014-12-13T07:13:56","modified_gmt":"2014-12-13T10:13:56","slug":"flanelinha-e-esfaqueado-na-entrada-do-mercado","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/flanelinha-e-esfaqueado-na-entrada-do-mercado\/","title":{"rendered":"Flanelinha \u00e9 esfaqueado na entrada do Mercado"},"content":{"rendered":"<div id=\"attachment_73782\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/1_news_66_0b751e7c1613db576e7088141a983095.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73782\" class=\" wp-image-73782 \" alt=\"Foto: Jadilson Sim\u00f5es\/ Equipe JC \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/1_news_66_0b751e7c1613db576e7088141a983095.jpg\" width=\"558\" height=\"369\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/1_news_66_0b751e7c1613db576e7088141a983095.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/1_news_66_0b751e7c1613db576e7088141a983095-300x198.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/1_news_66_0b751e7c1613db576e7088141a983095-342x226.jpg 342w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-73782\" class=\"wp-caption-text\">Foto: Jadilson Sim\u00f5es\/ Equipe JC<\/p><\/div>\n<p style=\"text-align: justify;\">Um flanelinha foi esfaqueado no estacionamento voltado para motos, em frente uma das entradas laterais do Mercado Municipal, Centro de Aracaju, na manh\u00e3 desta sexta-feira (12).<\/p>\n<p style=\"text-align: justify;\">A informa\u00e7\u00e3o \u00e9 que o homem teria recebido provoca\u00e7\u00f5es de outro flanelinha e foi esfaqueado na altura da costela e caminhou em dire\u00e7\u00e3o ao fundo do Mercado pedindo socorro.<\/p>\n<p style=\"text-align: justify;\">Segundo depoimentos de populares, o homem havia sido entubado e aparentava estar com soro nos dois bra\u00e7os. &#8221; Pela gravidade do atendimento, acredito que a facada tenha atingido o pulm\u00e3o&#8221;, observou a testemunha.<\/p>\n<p style=\"text-align: justify;\">De acordo com informa\u00e7\u00f5es do Guarda Municipal, Normando, a v\u00edtima foi atendida imediatamente pelo Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) , por\u00e9m, o respons\u00e1vel pelo crime tinha evadido do local.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do Jornal da Cidade<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um flanelinha foi esfaqueado no estacionamento voltado para motos, em frente uma das entradas laterais do Mercado Municipal, Centro de Aracaju, na manh\u00e3 desta sexta-feira (12). A informa\u00e7\u00e3o \u00e9 que o homem teria recebido provoca\u00e7\u00f5es de outro flanelinha e foi esfaqueado na altura da costela e caminhou em dire\u00e7\u00e3o ao fundo do Mercado pedindo socorro. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-73781","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73781"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73781"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/73782"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}