{"id":73679,"date":"2014-12-10T12:36:56","date_gmt":"2014-12-10T15:36:56","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73679"},"modified":"2014-12-10T13:11:17","modified_gmt":"2014-12-10T16:11:17","slug":"agricultor-do-pi-e-diagnosticado-com-febre-do-nilo-e-caso-e-o-1o-do-brasil","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/agricultor-do-pi-e-diagnosticado-com-febre-do-nilo-e-caso-e-o-1o-do-brasil\/","title":{"rendered":"Agricultor do PI \u00e9 diagnosticado com febre do Nilo e caso \u00e9 o 1\u00ba do Brasil"},"content":{"rendered":"<p style=\"text-align: justify;\">O Minist\u00e9rio de Sa\u00fade confirmou nesta ter\u00e7a-feira (9) que o Piau\u00ed registrou o primeiro caso de Febre do Nilo no Brasil. O fato estava sendo investigado desde agosto, quando o agricultor Francisco Raimundo de Lima apresentou encefalite e foi notificado como caso suspeito. Outras quatro pessoas apresentaram sintomas neurol\u00f3gicos considerados suspeitos, no entanto, os exames descartaram a possibilidade de febre do Nilo. O minist\u00e9rio ressalta que o fato \u00e9 isolado e n\u00e3o representa risco para uma epidemia.<\/p>\n<div id=\"attachment_73680\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/tecnicos.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73680\" class=\" wp-image-73680 \" alt=\"T\u00e9cnicos do Minist\u00e9rio da Sa\u00fade fizeram investiga\u00e7\u00f5es na regi\u00e3o Sul do Piau\u00ed(Foto: Reprodu\u00e7\u00e3o\/TV Clube) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/tecnicos.jpg\" width=\"558\" height=\"368\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/tecnicos.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/tecnicos-300x197.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/tecnicos-342x225.jpg 342w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-73680\" class=\"wp-caption-text\">T\u00e9cnicos do Minist\u00e9rio da Sa\u00fade fizeram investiga\u00e7\u00f5es na regi\u00e3o Sul do Piau\u00ed(Foto: Reprodu\u00e7\u00e3o\/TV Clube)<\/p><\/div>\n<p style=\"text-align: justify;\">A doen\u00e7a foi confirmada por meio de teste sorol\u00f3gico reagente para o v\u00edrus do Nilo Ocidental-VNO (IH e ELISA). De acordo com a coordenadora de epidemiologia da Secretaria Estadual de Sa\u00fade, Am\u00e1lia Costa, o paciente que reside na zona rural de Aroeiras do Itaim, Sul do Piau\u00ed, foi infectado pelo v\u00edrus. Al\u00e9m dos casos que apresentaram sintomas, foram realizados testes em mais 18 pessoas da regi\u00e3o e todos os resultados deram negativo.<\/p>\n<p style=\"text-align: justify;\">A febre do Nilo Ocidental \u00e9 uma infec\u00e7\u00e3o viral transmitida por meio da picada de mosquitos comuns, principalmente do g\u00eanero Culex (pernilongos). A doen\u00e7a \u00e9 origin\u00e1ria do Egito, norte da \u00c1frica, e cerca de 80% dos casos em humanos n\u00e3o apresentam sintomas.<\/p>\n<p style=\"text-align: justify;\">&#8220;A viremia em homens e outros mam\u00edferos \u00e9 breve e de baixa intensidade, considerada insuficiente para infectar mosquitos. Os hospedeiros naturais do v\u00edrus s\u00e3o aves silvestres&#8221;, diz o comunicado do Minist\u00e9rio da Sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">O paciente, que estava internado no Instituto de Doen\u00e7as Tropicais Natan Portela, em Teresina j\u00e1 teve alta e atualmente passa por reabilita\u00e7\u00e3o e fisioterapia para recuperar o seu estado de sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">Segundo Am\u00e1lia Costa, o paciente passou por tr\u00eas pesquisas virais para se comprovar a presen\u00e7a do v\u00edrus causador da doen\u00e7a.\u201cOs exames foram realizados ainda no m\u00eas de agosto quando o paciente deu entrada no Hospital Natan Portela. Na \u00e9poca ele apresentava dores de cabe\u00e7a, febre e rigidez no m\u00fasculo e uma poss\u00edvel infe\u00e7\u00e3o\u201d, relatou Am\u00e1lia Costa.<\/p>\n<p style=\"text-align: justify;\"><strong>A doen\u00e7a<\/strong><\/p>\n<p style=\"text-align: justify;\">Apenas 20% dos casos apresentam sintomas semelhantes aos da gripe, como febre, fadiga, dores de cabe\u00e7a e dores musculares ou articulares, e menos de 1% dos humanos infectados ficam gravemente doentes, sendo que a maioria dos casos graves acomete idosos.<\/p>\n<p style=\"text-align: justify;\">Os sintomas graves incluem febre alta, rigidez na nuca, desorienta\u00e7\u00e3o, tremores, fraqueza muscular e paralisia. As pessoas gravemente afetadas podem desenvolver encefalite (inflama\u00e7\u00e3o do c\u00e9rebro) ou meningite (inflama\u00e7\u00e3o das membranas do c\u00e9rebro ou da espinal medula). N\u00e3o existe tratamento espec\u00edfico para a Febre do Nilo. O tratamento do paciente infectado \u00e9 de suporte e envolve hospitaliza\u00e7\u00e3o, reposi\u00e7\u00e3o intravenosa de fluidos, suporte respirat\u00f3rio e preven\u00e7\u00e3o de infec\u00e7\u00f5es secund\u00e1rias.<\/p>\n<p style=\"text-align: justify;\"><strong>Controle<\/strong><\/p>\n<p style=\"text-align: justify;\">Equipes do Minist\u00e9rio da Sa\u00fade e da Secretaria Estadual de Sa\u00fade do Piau\u00ed ainda est\u00e3o na regi\u00e3o onde o caso foi confirmado. O trabalho consiste em visitas as propriedades rurais, com o objetivo de investigar a poss\u00edvel ocorr\u00eancia de novos casos, al\u00e9m de orientar a rede do SUS e avaliar a transmiss\u00e3o por meio da popula\u00e7\u00e3o animal de equ\u00eddeos e aves.<\/p>\n<p style=\"text-align: justify;\">Para as outras regi\u00f5es do pa\u00eds, a recomenda\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade \u00e9 alertar a rede de servi\u00e7os de sa\u00fade para ampliar a vigil\u00e2ncia de casos humanos suspeitos da febre, notificando o Minist\u00e9rio de Sa\u00fade em at\u00e9 24 horas. \u00c9 considerado caso suspeito, paciente com quadro de doen\u00e7a febril inespec\u00edfica, acompanhada de manifesta\u00e7\u00f5es neurol\u00f3gicas de causa desconhecida (compat\u00edveis com meningite, encefalite ou meningoencefalite).<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es de Catarina Costa do G1, Piau\u00ed<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio de Sa\u00fade confirmou nesta ter\u00e7a-feira (9) que o Piau\u00ed registrou o primeiro caso de Febre do Nilo no Brasil. O fato estava sendo investigado desde agosto, quando o agricultor Francisco Raimundo de Lima apresentou encefalite e foi notificado como caso suspeito. Outras quatro pessoas apresentaram sintomas neurol\u00f3gicos considerados suspeitos, no entanto, os exames [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-73679","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73679"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73679"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/73680"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}