{"id":73671,"date":"2014-12-10T11:22:52","date_gmt":"2014-12-10T14:22:52","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73671"},"modified":"2014-12-10T11:31:53","modified_gmt":"2014-12-10T14:31:53","slug":"luciano-bispo-se-defende-de-acusacoes-em-nota","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/luciano-bispo-se-defende-de-acusacoes-em-nota\/","title":{"rendered":"Luciano Bispo se defende de acusa\u00e7\u00f5es em Nota"},"content":{"rendered":"<p style=\"text-align: center;\"><b><span style=\"text-decoration: underline;\">Nota de Esclarecimento<\/span><\/b><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_40158\" style=\"width: 285px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/10\/Luciano-Bispo.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-40158\" class=\"size-full wp-image-40158\" alt=\"Deputado se defende de acusa\u00e7\u00f5es em Nota. (Foto: Reprodu\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/10\/Luciano-Bispo.jpg\" width=\"275\" height=\"183\" \/><\/a><p id=\"caption-attachment-40158\" class=\"wp-caption-text\">Deputado se defende de acusa\u00e7\u00f5es em Nota. (Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">A respeito da condena\u00e7\u00e3o em processo que envolve a constru\u00e7\u00e3o de um Frigor\u00edfico no Munic\u00edpio de Itabaiana, durante a administra\u00e7\u00e3o da Ex-prefeita Maria Mendon\u00e7a, no per\u00edodo entre <b><span style=\"text-decoration: underline;\"><span style=\"color: #ff0000;\">2005 e 2008<\/span><\/span><\/b>, esclarecemos a Sociedade sergipana que em nenhum momento eu adotei qualquer atitude que prejudicasse o meu Povo ou usasse de m\u00e1 f\u00e9 os recursos p\u00fablicos oriundos do Minist\u00e9rio da Agricultura.<\/p>\n<p style=\"text-align: justify;\">Quando chegamos \u00e0 Prefeitura, logo no in\u00edcio de 2009, recebemos uma correspond\u00eancia do Minist\u00e9rio da Agricultura cobrando a corre\u00e7\u00e3o de diversos problemas na execu\u00e7\u00e3o desta obra. Imediatamente mandamos fazer um levantamento t\u00e9cnico e ficou comprovado, inclusive pelo pr\u00f3prio Minist\u00e9rio, que a obra era imposs\u00edvel de ser constru\u00edda, devido a diverg\u00eancia entre o que o Governo Federal exigia e o recurso que foi solicitado. <span style=\"color: #ff0000;\"><b><span style=\"text-decoration: underline;\">A gest\u00e3o anterior pediu R$ 3 milh\u00f5es para construir um Frigor\u00edfico, que pelos moldes t\u00e9cnicos, era avaliado em R$ 20 milh\u00f5es<\/span><\/b>.<\/span><\/p>\n<p style=\"text-align: justify;\">Constatamos que os recursos aplicados, \u00fanica e exclusivamente pela Gest\u00e3o da Ex-Prefeita, <b><span style=\"text-decoration: underline;\"><span style=\"color: #ff0000;\">n\u00f3s n\u00e3o movimentamos um centavo desse recurso<\/span><\/span><\/b>, e n\u00e3o movimentamos por absoluta falta de condi\u00e7\u00e3o de dar continuidade \u00e0 constru\u00e7\u00e3o do Frigor\u00edfico. N\u00f3s tentamos sim, como \u00e9 dito na decis\u00e3o do Magistrado, mudar o objeto do recurso, mas tentamos fazer isso para conseguir melhorar o atual matadouro, mas fizemos isso de forma l\u00edcita, \u00e0s claras, dialogando com o Minist\u00e9rio da Agricultura. N\u00e3o obtivemos \u00eaxito.<\/p>\n<p style=\"text-align: justify;\"><b><span style=\"text-decoration: underline;\">Tomamos, por fim, a decis\u00e3o de ap\u00f3s diversas tratativas com o Minist\u00e9rio da Agricultura, entregar o caso a quem de direito, o Tribunal de Contas da Uni\u00e3o, por se tratar de recursos federais.<\/span><\/b><\/p>\n<p style=\"text-align: justify;\">Deste modo, consideramos a condena\u00e7\u00e3o pela devolu\u00e7\u00e3o de R$ 900 mil, imposta a mim, completamente injusta, uma vez que, repito, n\u00e3o usamos um s\u00f3 centavo desse recurso, n\u00e3o contratamos essa obra, e ap\u00f3s levantamento t\u00e9cnico sobre a viabilidade da mesma, conclu\u00edmos ser completamente invi\u00e1vel, o que foi acordado pelo pr\u00f3prio Minist\u00e9rio da Agricultura, em relat\u00f3rio de an\u00e1lise, assinado por t\u00e9cnicos.<\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><b>Luciano Bispo de Lima<br \/>\n<\/b>Deputado Estadual, Eleito (PMDB)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota de Esclarecimento &nbsp; A respeito da condena\u00e7\u00e3o em processo que envolve a constru\u00e7\u00e3o de um Frigor\u00edfico no Munic\u00edpio de Itabaiana, durante a administra\u00e7\u00e3o da Ex-prefeita Maria Mendon\u00e7a, no per\u00edodo entre 2005 e 2008, esclarecemos a Sociedade sergipana que em nenhum momento eu adotei qualquer atitude que prejudicasse o meu Povo ou usasse de m\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-73671","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73671"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73671"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/40158"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}