{"id":73650,"date":"2014-12-10T09:37:00","date_gmt":"2014-12-10T12:37:00","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73650"},"modified":"2014-12-10T09:48:35","modified_gmt":"2014-12-10T12:48:35","slug":"novo-codigo-penal-e-analisado-na-ccj","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/novo-codigo-penal-e-analisado-na-ccj\/","title":{"rendered":"Novo C\u00f3digo Penal \u00e9 analisado na CCJ"},"content":{"rendered":"<p style=\"text-align: justify;\">O senador Vital do R\u00eago (PMDB-PB) apresenta substitutivo ao projeto de reforma do C\u00f3digo Penal (PLS 236\/2012), em reuni\u00e3o neste momento na Comiss\u00e3o de Constitui\u00e7\u00e3o, Justi\u00e7a e Cidadania (CCJ).<\/p>\n<p style=\"text-align: justify;\">O texto tem por base anteprojeto elaborado por uma comiss\u00e3o de juristas instalada em 2011 no Senado, com o objetivo de atualizar o C\u00f3digo Penal, que \u00e9 de 1940. A proposta j\u00e1 passou por comiss\u00e3o especial de senadores, antes de chegar \u00e0 CCJ.<\/p>\n<p style=\"text-align: justify;\">O texto \u00e9 mais rigoroso na puni\u00e7\u00e3o a condenados, aumenta a pena m\u00ednima para crime de homic\u00eddio e inclui a pr\u00e1tica da corrup\u00e7\u00e3o na lista de crimes hediondos. Tamb\u00e9m aumenta os prazos para a progress\u00e3o de pena, situa\u00e7\u00e3o em que o condenado pode pleitear mudan\u00e7a para um regime de reclus\u00e3o menos severo.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s a vota\u00e7\u00e3o na CCJ, o projeto segue para delibera\u00e7\u00e3o do Plen\u00e1rio e depois deve ir \u00e0 an\u00e1lise da C\u00e2mara dos Deputados.<\/p>\n<p><i>Mais informa\u00e7\u00f5es em instantes<br \/>\n<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O senador Vital do R\u00eago (PMDB-PB) apresenta substitutivo ao projeto de reforma do C\u00f3digo Penal (PLS 236\/2012), em reuni\u00e3o neste momento na Comiss\u00e3o de Constitui\u00e7\u00e3o, Justi\u00e7a e Cidadania (CCJ). O texto tem por base anteprojeto elaborado por uma comiss\u00e3o de juristas instalada em 2011 no Senado, com o objetivo de atualizar o C\u00f3digo Penal, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-73650","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73650"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73650"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73650\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}