{"id":73483,"date":"2014-12-04T15:58:10","date_gmt":"2014-12-04T18:58:10","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73483"},"modified":"2014-12-04T15:58:37","modified_gmt":"2014-12-04T18:58:37","slug":"ceacs-passam-a-funcionar-de-segunda-a-sexta","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/ceacs-passam-a-funcionar-de-segunda-a-sexta\/","title":{"rendered":"Ceac\u2019s passam a funcionar de segunda a sexta"},"content":{"rendered":"<div id=\"attachment_64404\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-ceac_atendimento_140512.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-64404\" class=\"size-medium wp-image-64404\" alt=\"CEAC\u2019s  passa a funcionar de segunda a sexta. (Foto: Reprodu\u00e7\u00e3o\/Ilustrativa)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-ceac_atendimento_140512-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-ceac_atendimento_140512-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-ceac_atendimento_140512-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-ceac_atendimento_140512.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-64404\" class=\"wp-caption-text\">CEAC\u2019s passa a funcionar de segunda a sexta. (Foto: Reprodu\u00e7\u00e3o\/Ilustrativa)<\/p><\/div>\n<p style=\"text-align: justify;\">A partir deste s\u00e1bado, 6 de dezembro, os Centros de Atendimento ao Cidad\u00e3o (Ceac\u2019s), localizados na Rua do Turista, Rodovi\u00e1ria Nova e Shopping Riomar, n\u00e3o funcionar\u00e3o aos s\u00e1bados.<\/p>\n<p style=\"text-align: justify;\">O funcionamento nas tr\u00eas unidades de atendimento ser\u00e1 suspenso com base em estudos que foram desenvolvidos analisando o n\u00famero de atendimentos que vinham sendo realizados nesses locais. Segundo o relat\u00f3rio, o fluxo de servi\u00e7os solicitados aos s\u00e1bados correspondia a menos de 10% do que era feito em um dia da semana, n\u00e3o justificando a perman\u00eancia do servi\u00e7o.<\/p>\n<p style=\"text-align: justify;\">O Governo informa que as provid\u00eancias est\u00e3o sendo tomadas para remarcar o atendimento dos cidad\u00e3os que estavam agendados para serem recebidos no s\u00e1bado, remarcando-os para um dia na semana.<\/p>\n<p style=\"text-align: justify;\">Os Ceac\u2019s funcionam de segunda a sexta-feira, das 7h15 \u00e0s 17h45, ou seja, dez horas e meia por dia, totalizando, em m\u00e9dia, dois mil atendimentos di\u00e1rios.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: ASN<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir deste s\u00e1bado, 6 de dezembro, os Centros de Atendimento ao Cidad\u00e3o (Ceac\u2019s), localizados na Rua do Turista, Rodovi\u00e1ria Nova e Shopping Riomar, n\u00e3o funcionar\u00e3o aos s\u00e1bados. O funcionamento nas tr\u00eas unidades de atendimento ser\u00e1 suspenso com base em estudos que foram desenvolvidos analisando o n\u00famero de atendimentos que vinham sendo realizados nesses locais. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-73483","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73483"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73483"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/64404"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}