{"id":73413,"date":"2014-12-03T13:15:24","date_gmt":"2014-12-03T16:15:24","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73413"},"modified":"2014-12-03T13:15:24","modified_gmt":"2014-12-03T16:15:24","slug":"idosa-e-presa-com-21-trouxas-de-maconha-e-uma-pistola","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/idosa-e-presa-com-21-trouxas-de-maconha-e-uma-pistola\/","title":{"rendered":"Idosa \u00e9 presa com 21 trouxas de maconha e uma pistola"},"content":{"rendered":"<div id=\"attachment_73415\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/apreensao_cjjardim.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73415\" class=\" wp-image-73415 \" alt=\"Segundo a pol\u00edcia, adolescente flagrado com drogas informou o endere\u00e7o da traficante (Foto: Divulga\u00e7\u00e3o\/PM-SE) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/apreensao_cjjardim.jpg\" width=\"558\" height=\"419\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/apreensao_cjjardim.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/apreensao_cjjardim-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/apreensao_cjjardim-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/apreensao_cjjardim-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/apreensao_cjjardim-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/12\/apreensao_cjjardim-269x201.jpg 269w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-73415\" class=\"wp-caption-text\">Segundo a pol\u00edcia, adolescente flagrado com drogas informou o endere\u00e7o da traficante (Foto: Divulga\u00e7\u00e3o\/PM-SE)<\/p><\/div>\n<p style=\"text-align: justify;\">Uma idosa de 60 anos foi presa com 21 trouxas de maconha e uma pistola no Conjunto Jardim, em Nossa Senhora do Socorro, na Grande Aracaju, nesta ter\u00e7a-feira (2). Segundo a Pol\u00edcia Militar, a pris\u00e3o foi efetuada por uma equipe do Batalh\u00e3o de Radiopatrulha, que estava fazendo rondas no local.<\/p>\n<p style=\"text-align: justify;\">Ainda segundo a pol\u00edcia, a equipe abordou um menor de idade que estava portando drogas. Ao ser questionado pelos policiais sobre a origem do entorpecente, o adolescente acabou informando o endere\u00e7o da traficante.<\/p>\n<p style=\"text-align: justify;\">As drogas e a pistola foram apreendidas e a idosa encaminhada \u00e0 delegacia.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do G1, em Sergipe<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma idosa de 60 anos foi presa com 21 trouxas de maconha e uma pistola no Conjunto Jardim, em Nossa Senhora do Socorro, na Grande Aracaju, nesta ter\u00e7a-feira (2). Segundo a Pol\u00edcia Militar, a pris\u00e3o foi efetuada por uma equipe do Batalh\u00e3o de Radiopatrulha, que estava fazendo rondas no local. Ainda segundo a pol\u00edcia, a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-73413","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73413"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73413"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/73415"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}