{"id":73165,"date":"2014-11-27T16:13:45","date_gmt":"2014-11-27T19:13:45","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73165"},"modified":"2014-11-28T17:44:24","modified_gmt":"2014-11-28T20:44:24","slug":"concurso-para-policia-civil-acontece-neste-domingo-30","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/concurso-para-policia-civil-acontece-neste-domingo-30\/","title":{"rendered":"Concurso para Pol\u00edcia Civil acontece neste domingo, 30"},"content":{"rendered":"<div id=\"attachment_73167\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/ssp.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73167\" class=\"size-medium wp-image-73167\" alt=\"S\u00e3o 120 vagas distribu\u00eddas nos cargos de escriv\u00e3o e agente. (Foto: Ascom\/SSP)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/ssp-300x199.jpeg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/ssp-300x199.jpeg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/ssp-342x226.jpeg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/ssp.jpeg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-73167\" class=\"wp-caption-text\">S\u00e3o 120 vagas distribu\u00eddas nos cargos de escriv\u00e3o e agente. (Foto: Ascom\/SSP)<\/p><\/div>\n<p style=\"text-align: justify;\">Muito se tem discutido sobre a recomenda\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Estadual (MPE) que visa altera\u00e7\u00e3o no Edital de abertura referente ao concurso para preenchimento de vagas em cargos da Pol\u00edcia Civil, especificamente, a prova de aptid\u00e3o f\u00edsica para as pessoas com defici\u00eancia, que venham a ser aprovados na avalia\u00e7\u00e3o escrita.<\/p>\n<p style=\"text-align: justify;\">O certame em andamento e que tem como empresa realizadora o Instituto Brasileiro de Forma\u00e7\u00e3o e Capacita\u00e7\u00e3o (IBFC), primou pela garantia ampla e irrestrita dos direitos das pessoas com defici\u00eancia, reservando para os mesmos 20% das vagas de cada um dos cargos \u2013 agente de pol\u00edcia e escriv\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O crit\u00e9rio adotado no concurso encontra-se respaldado em regras e Princ\u00edpios Constitucionais, conforme orienta\u00e7\u00e3o da Procuradoria Geral do Estado. \u201cO Governo tem seguido todas as orienta\u00e7\u00f5es das inst\u00e2ncias respons\u00e1veis e respeitado sempre os direitos das pessoas com defici\u00eancia\u201d, informa F\u00e1bio Dantas, presidente da Comiss\u00e3o do Concurso da Pol\u00edcia Civil.<\/p>\n<p style=\"text-align: justify;\">\u00c9 importante ressaltar que outros concursos p\u00fablicos em andamento, sejam nas esferas estaduais ou federais, seguiram regras semelhantes \u00e0s adotadas pelo Governo de Sergipe na sele\u00e7\u00e3o de pessoas com defici\u00eancia.\u00a0 Sendo assim, continua mantida a prova escrita do referido concurso para o pr\u00f3ximo domingo, 30, conforme editais publicados.<\/p>\n<p style=\"text-align: justify;\"><strong>A\u00e7\u00e3o do MPE<\/strong><\/p>\n<p style=\"text-align: justify;\">No in\u00edcio do m\u00eas de novembro, as Secretarias de Estado do Planejamento, Or\u00e7amento e Gest\u00e3o (Seplag), e da Seguran\u00e7a P\u00fablica (SSP), receberam recomenda\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Estadual (MPE), que sugeriu a altera\u00e7\u00e3o no Edital do Concurso da Pol\u00edcia Civil de Sergipe para adequa\u00e7\u00e3o da prova de aptid\u00e3o f\u00edsica em rela\u00e7\u00e3o \u00e0s pessoas com defici\u00eancia.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s consulta a Procuradoria Geral do Estado (PGE), e ampla discuss\u00e3o com a institui\u00e7\u00e3o organizadora do concurso, o Governo do Estado respondeu a recomenda\u00e7\u00e3o do MPE, mantendo o edital publicado, por entender que o mesmo salvaguarda os direitos dos deficientes e que caso o altere nos termos propostos, estar\u00e1 ferindo os direitos dos demais candidatos que est\u00e3o concorrendo \u00e0s vagas a serem providas.<\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/\" target=\"_blank\">Twitter <\/a>e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Ag\u00eancia Sergipe de Not\u00edcias<\/em><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Muito se tem discutido sobre a recomenda\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Estadual (MPE) que visa altera\u00e7\u00e3o no Edital de abertura referente ao concurso para preenchimento de vagas em cargos da Pol\u00edcia Civil, especificamente, a prova de aptid\u00e3o f\u00edsica para as pessoas com defici\u00eancia, que venham a ser aprovados na avalia\u00e7\u00e3o escrita. O certame em andamento e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73167,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,7],"tags":[],"class_list":{"0":"post-73165","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-concursos","8":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73165"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73165"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/73167"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}