{"id":73154,"date":"2014-11-27T13:07:35","date_gmt":"2014-11-27T16:07:35","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=73154"},"modified":"2014-11-27T13:17:10","modified_gmt":"2014-11-27T16:17:10","slug":"prefeitura-de-itaporanga-inicia-construcao-de-escola-com-6-salas-no-povoado-sape","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/prefeitura-de-itaporanga-inicia-construcao-de-escola-com-6-salas-no-povoado-sape\/","title":{"rendered":"Prefeitura de Itaporanga inicia constru\u00e7\u00e3o de escola com 6 salas no Povoado Sap\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\">Come\u00e7aram na quinta-feira (22) as obras de constru\u00e7\u00e3o da Escola Municipal de Ensino Fundamental do Povoado Sap\u00e9, em Itaporanga D&#8217;Ajuda. Com \u00e1rea total de 4.800 metros quadrados, a escola ter\u00e1 seis salas de aulas com capacidade para 216 alunos por turno, contemplando um total de 648 alunos nos tr\u00eas turnos (manh\u00e3, tarde e noite).<\/p>\n<div id=\"attachment_73156\" style=\"width: 602px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0167.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73156\" class=\"size-full wp-image-73156\" alt=\" Na \u00faltima quinta-feira (21), a prefeita Gracinha autorizou o in\u00edcio imediato da constru\u00e7\u00e3o da escola. (Ascom\/Itaporanga)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0167.jpg\" width=\"592\" height=\"444\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0167.jpg 592w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0167-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0167-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0167-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0167-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0167-269x201.jpg 269w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><\/a><p id=\"caption-attachment-73156\" class=\"wp-caption-text\"><br \/>Na \u00faltima quinta-feira (21), a prefeita Gracinha autorizou o in\u00edcio imediato da constru\u00e7\u00e3o da escola. (Ascom\/Itaporanga)<\/p><\/div>\n<div id=\"attachment_73157\" style=\"width: 602px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0140.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73157\" class=\"size-full wp-image-73157\" alt=\" A \u00e1rea do terreno \u00e9 de 60x80 metros e a \u00e1rea a ser constru\u00edda \u00e9  de 4.800 metros quadrados.(Foto ilustrativa\/MEC)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0140.jpg\" width=\"592\" height=\"444\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0140.jpg 592w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0140-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0140-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0140-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0140-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0140-269x201.jpg 269w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><\/a><p id=\"caption-attachment-73157\" class=\"wp-caption-text\"><br \/>A \u00e1rea do terreno \u00e9 de 60&#215;80 metros e a \u00e1rea a ser constru\u00edda \u00e9 de 4.800 metros quadrados.(Foto ilustrativa\/MEC)<\/p><\/div>\n<p style=\"text-align: justify;\">De acordo com o secret\u00e1rio de Obras, Igor Garcez, um dos grandes diferenciais da escola est\u00e1 no moderno projeto arquitet\u00f4nico.<\/p>\n<p style=\"text-align: justify;\">&#8220;Essa \u00e9 a primeira escola de outras que vir\u00e3o. J\u00e1 temos cadastrados no SIMEC outros pedidos de constru\u00e7\u00e3o de escolas deste porte. Com certeza essa escola trar\u00e1 melhores condi\u00e7\u00f5es de ensino e aprendizado para os alunos da rede municipal. No que se refere ao projeto, a premissa b\u00e1sica foi a de criar uma linguagem ao mesmo tempo moderna e brasileira, mostrando as tradi\u00e7\u00f5es arquitet\u00f4nicas e espaciais de nosso Pai\u0301s, adaptada \u00e0s nossas condi\u00e7\u00f5es clim\u00e1ticas e culturais&#8221;, detalha o secret\u00e1rio.<\/p>\n<div id=\"attachment_73158\" style=\"width: 602px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0141.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73158\" class=\"size-full wp-image-73158\" alt=\" A Escola do Sap\u00e9 ser\u00e1 a primeira com 6 salas de aula na zona rural de Itaporanga. (Foto llustrativa\/MEC)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0141.jpg\" width=\"592\" height=\"444\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0141.jpg 592w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0141-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0141-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0141-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0141-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/IMG-20141126-WA0141-269x201.jpg 269w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><\/a><p id=\"caption-attachment-73158\" class=\"wp-caption-text\"><br \/>A Escola do Sap\u00e9 ser\u00e1 a primeira com 6 salas de aula na zona rural de Itaporanga. (Foto llustrativa\/MEC)<\/p><\/div>\n<p style=\"text-align: justify;\">Para a prefeita Maria das Gra\u00e7as (Gracinha), investir em educa\u00e7\u00e3o \u00e9 investir no futuro dos jovens. Ela observa que a educa\u00e7\u00e3o \u00e9 uma das prioridades da administra\u00e7\u00e3o &#8216;Faz Mais Por Voc\u00ea&#8217;.<\/p>\n<p style=\"text-align: justify;\">\u201cA nossa gest\u00e3o est\u00e1 construindo novas escolas com uma infraestrutura moderna. A conquista de uma nova escola em nosso munic\u00edpio \u00e9 gra\u00e7as \u00e0 dedica\u00e7\u00e3o de toda nossa equipe que apostou numa escola que ofere\u00e7a muito mais que qualidade de ensino, mas tamb\u00e9m conforto visando uma melhor condi\u00e7\u00e3o de aprendizagem. Estamos investindo na qualifica\u00e7\u00e3o de nossos professores e n\u00e3o pouparemos esfor\u00e7os para a melhoria da educa\u00e7\u00e3o em todos os sentidos. A educa\u00e7\u00e3o \u00e9 uma de nossas prioridades. Agrade\u00e7o a comunidade do Povoado Sap\u00e9 pela paci\u00eancia e retribuo dizendo aos moradores que continuarei trabalhando com todas as for\u00e7as por toda a nossa cidade\u201d, salienta a prefeita.<\/p>\n<p style=\"text-align: justify;\">A constru\u00e7\u00e3o da escola, que est\u00e1 gerando 150 empregos diretos e indiretos, dever\u00e1 ficar pronta em 12 meses . A escola que est\u00e1 sendo erguida no Povoado Sap\u00e9, distante 12 km da sede do munic\u00edpio, vai atender alunos dos povoados Sap\u00e9, Col\u00f4nia Sap\u00e9, Saco, Ch\u00e3, Gravat\u00e1, Tinga, Tapera e Moita Formosa.<\/p>\n<p style=\"text-align: justify;\">A empresa Engecon \u00e9 a respons\u00e1vel pela constru\u00e7\u00e3o do estabelecimento de ensino.<\/p>\n<p style=\"text-align: justify;\">por Ascom\/Itaporanga<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come\u00e7aram na quinta-feira (22) as obras de constru\u00e7\u00e3o da Escola Municipal de Ensino Fundamental do Povoado Sap\u00e9, em Itaporanga D&#8217;Ajuda. Com \u00e1rea total de 4.800 metros quadrados, a escola ter\u00e1 seis salas de aulas com capacidade para 216 alunos por turno, contemplando um total de 648 alunos nos tr\u00eas turnos (manh\u00e3, tarde e noite). De [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,1],"tags":[],"class_list":{"0":"post-73154","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73154"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=73154"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/73154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/73156"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=73154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=73154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=73154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}