{"id":72416,"date":"2014-11-10T15:04:16","date_gmt":"2014-11-10T18:04:16","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=72416"},"modified":"2014-11-11T14:09:46","modified_gmt":"2014-11-11T17:09:46","slug":"em-outubro-repasse-dos-royalties-do-petroleo-para-sergipe-foi-menor","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/em-outubro-repasse-dos-royalties-do-petroleo-para-sergipe-foi-menor\/","title":{"rendered":"Em outubro, repasse dos royalties do petr\u00f3leo para Sergipe foi menor"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\"><b>\u00a0<\/b><\/p>\n<p style=\"text-align: justify;\"><b>\u00a0<\/b><\/p>\n<div id=\"attachment_38905\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/08\/Petrobr\u00e1s.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38905\" class=\"size-medium wp-image-38905\" alt=\"Repasse dos royalties do petr\u00f3leo para Sergipe foi menor. (Foto: Arquivo SE Not\u00edcias)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/08\/Petrobr\u00e1s-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/08\/Petrobr\u00e1s-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/08\/Petrobr\u00e1s-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/08\/Petrobr\u00e1s-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/08\/Petrobr\u00e1s-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/08\/Petrobr\u00e1s-269x201.jpg 269w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/08\/Petrobr\u00e1s.jpg 590w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-38905\" class=\"wp-caption-text\">Repasse dos royalties do petr\u00f3leo para Sergipe foi menor. (Foto: Arquivo SE Not\u00edcias)<\/p><\/div>\n<p style=\"text-align: justify;\">An\u00e1lise realizada pelo Boletim Sergipe Econ\u00f4mico, uma parceria do N\u00facleo de Informa\u00e7\u00f5es Econ\u00f4micas (NIE) da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Sergipe (FIES) e do Departamento de Economia da UFS, com base nos dados da ANP, indicou que o pagamento de royalties do petr\u00f3leo e g\u00e1s natural, para o estado de Sergipe, no m\u00eas de outubro, chegou a R$ 13,1 milh\u00f5es, valor referente \u00e0 produ\u00e7\u00e3o do oitavo m\u00eas do ano. O repasse recebido no m\u00eas passado foi 12,2% menor que o registrado em outubro de 2013. No comparativo com o m\u00eas imediatamente anterior, setembro \u00faltimo, verificou-se queda de 2,9% no pagamento dos royalties.<\/p>\n<p style=\"text-align: justify;\">De janeiro a outubro, foram pagos R$ 142,1 milh\u00f5es em royalties referentes \u00e0 extra\u00e7\u00e3o de petr\u00f3leo e g\u00e1s em Sergipe. Esse valor est\u00e1 11,9% acima do registrado nos primeiros dez meses de 2013.<\/p>\n<p style=\"text-align: justify;\"><b><span style=\"font-size: medium;\">Royalties por Munic\u00edpio<\/span><\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">No d\u00e9cimo m\u00eas do ano, o munic\u00edpio de Japaratuba apresentou o maior recebimento de royalties no estado, chegando a R$ 3,2 milh\u00f5es. Em seguida aparecem Carm\u00f3polis e Aracaju que receberam R$ 3,1 milh\u00f5es e R$ 2,9 milh\u00f5es em royalties, respectivamente. O munic\u00edpio de Pirambu tamb\u00e9m merece destaque com receita de R$ 2,2 milh\u00f5es, referente \u00e0 extra\u00e7\u00e3o de petr\u00f3leo e g\u00e1s.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Unidade de Comunica\u00e7\u00e3o do Sistema FIES &#8211; Unicom\/FIES<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 An\u00e1lise realizada pelo Boletim Sergipe Econ\u00f4mico, uma parceria do N\u00facleo de Informa\u00e7\u00f5es Econ\u00f4micas (NIE) da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Sergipe (FIES) e do Departamento de Economia da UFS, com base nos dados da ANP, indicou que o pagamento de royalties do petr\u00f3leo e g\u00e1s natural, para o estado de Sergipe, no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-72416","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/72416"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=72416"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/72416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/38905"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=72416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=72416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=72416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}