{"id":72411,"date":"2014-11-10T14:38:17","date_gmt":"2014-11-10T17:38:17","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=72411"},"modified":"2014-11-10T14:38:17","modified_gmt":"2014-11-10T17:38:17","slug":"corpo-de-vitima-de-espancamento-e-encontrado-em-campo-de-futebol","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/corpo-de-vitima-de-espancamento-e-encontrado-em-campo-de-futebol\/","title":{"rendered":"Corpo de v\u00edtima de espancamento \u00e9 encontrado em campo de futebol"},"content":{"rendered":"<div id=\"attachment_72412\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/dsc_0927.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-72412\" class=\" wp-image-72412 \" alt=\"Corpo estava no mato pr\u00f3ximo a campo de futebol no bairro Santa Maria (Foto: Marina Fontenele\/G1) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/dsc_0927.jpg\" width=\"558\" height=\"419\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/dsc_0927.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/dsc_0927-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/dsc_0927-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/dsc_0927-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/dsc_0927-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/11\/dsc_0927-269x201.jpg 269w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-72412\" class=\"wp-caption-text\">Corpo estava no mato pr\u00f3ximo a campo de futebol no bairro Santa Maria (Foto: Marina Fontenele\/G1)<\/p><\/div>\n<p style=\"text-align: justify;\">Um homem de 26 anos foi encontrado morto no in\u00edcio da manh\u00e3 desta segunda-feira (10) em um campo de futebol improvisado que fica vizinho \u00e0 Rua Vit\u00f3ria, no Loteamento Marivan no bairro Santa Maria, na Zona Sul de Aracaju.<\/p>\n<p style=\"text-align: justify;\">De acordo com informa\u00e7\u00f5es do Instituto M\u00e9dico Legal (IML) o corpo apresenta sinais de espancamento com ferimentos concentrados na cabe\u00e7a da v\u00edtima.<\/p>\n<p style=\"text-align: justify;\">O delegado Ant\u00f4nio S\u00e9rgio Ara\u00fajo Pinto, do Departamento de Homic\u00eddios e Prote\u00e7\u00e3o \u00e0 Pessoa (DHPP), deu in\u00edcio \u00e0s investiga\u00e7\u00f5es. \u201cComo ainda \u00e9 muito recente ainda n\u00e3o temos mais informa\u00e7\u00f5es sobre o caso, mas as dilig\u00eancias j\u00e1 come\u00e7aram com a an\u00e1lise do local do crime\u201d, afirma. A fam\u00edlia do rapaz j\u00e1 esteve no IML para fazer o reconhecimento.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es de Marina Fontenele do\u00a0G1, em Sergipe<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 26 anos foi encontrado morto no in\u00edcio da manh\u00e3 desta segunda-feira (10) em um campo de futebol improvisado que fica vizinho \u00e0 Rua Vit\u00f3ria, no Loteamento Marivan no bairro Santa Maria, na Zona Sul de Aracaju. De acordo com informa\u00e7\u00f5es do Instituto M\u00e9dico Legal (IML) o corpo apresenta sinais de espancamento com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":72412,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-72411","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/72411"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=72411"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/72411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/72412"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=72411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=72411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=72411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}