{"id":71097,"date":"2014-10-10T17:19:36","date_gmt":"2014-10-10T20:19:36","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=71097"},"modified":"2014-10-10T17:19:36","modified_gmt":"2014-10-10T20:19:36","slug":"jackson-77-do-orcamento-para-saudeeducacao-e-seguranca","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/jackson-77-do-orcamento-para-saudeeducacao-e-seguranca\/","title":{"rendered":"Jackson: 77% do or\u00e7amento para sa\u00fade,educa\u00e7\u00e3o e seguran\u00e7a"},"content":{"rendered":"<div id=\"attachment_56326\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/WB-1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56326\" class=\"size-full wp-image-56326\" alt=\"(Foto: Wellington Barreto\/ASN)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/WB-1.jpg\" width=\"300\" height=\"207\" \/><\/a><p id=\"caption-attachment-56326\" class=\"wp-caption-text\">(Foto: Wellington Barreto\/ASN)<\/p><\/div>\n<p style=\"text-align: justify;\">O governador Jackson Barreto priorizar\u00e1 em 2015 as \u00e1reas de sa\u00fade, educa\u00e7\u00e3o e seguran\u00e7a. Para isso, ele enviou a proposta da Lei Or\u00e7ament\u00e1ria Anual (LOA) para Assembleia Legislativa que prev\u00ea 77% (R$ 6,6 bilh\u00f5es) do or\u00e7amento anual para essas \u00e1reas. O valor total do or\u00e7amento \u00e9 de R$ 8,625 bilh\u00f5es.<\/p>\n<p style=\"text-align: justify;\">A Lei Or\u00e7ament\u00e1ria Anual 2015 (LOA) \u00e9 o instrumento atrav\u00e9s do qual \u00e9 feita toda a aloca\u00e7\u00e3o de gastos do Governo, delimitados por \u00f3rg\u00e3os, setores e territ\u00f3rios. \u00c9 tamb\u00e9m a LOA que detalha melhor as a\u00e7\u00f5es existentes no Plano Plurianual em vig\u00eancia (PPA\/2012-2015).<\/p>\n<p style=\"text-align: justify;\">\u201cNossa prioridade \u00e9 reformular toda a m\u00e1quina administrativa para cuidar das pessoas. Evidente que as quest\u00f5es levantadas pela sociedade n\u00f3s vamos levar em considera\u00e7\u00e3o, que s\u00e3o as \u00e1reas da sa\u00fade, seguran\u00e7a, educa\u00e7\u00e3o\u201d, declarou Jackson Barreto.<\/p>\n<p style=\"text-align: justify;\">O valor previsto para o pr\u00f3ximo ano foi fixado em R$ 8,625 bilh\u00f5es, valor este que representa um crescimento de 4,06% em rela\u00e7\u00e3o ao or\u00e7ado 2014, que estava previsto em R$ 8,288 bilh\u00f5es. Segundo o superintendente de Programa\u00e7\u00e3o Econ\u00f4mica e Or\u00e7amento do Governo, Guilherme Rebou\u00e7as, as principais fontes de receita de Sergipe s\u00e3o advindas do Fundo de Participa\u00e7\u00e3o dos Estados (FPE) e do ICMS. \u201cIsso representa 74% do total do or\u00e7amento para 2015. As outras receitas s\u00e3o provenientes de outras fontes, como conv\u00eanios, opera\u00e7\u00f5es de cr\u00e9dito e outros\u201d, completa.<\/p>\n<p style=\"text-align: justify;\">A LOA 2015 tamb\u00e9m teve como par\u00e2metros fundamentais na sua elabora\u00e7\u00e3o a melhoria na qualidade dos gastos do Estado; a prioriza\u00e7\u00e3o dos investimentos por meio das opera\u00e7\u00f5es de cr\u00e9dito; diminui\u00e7\u00e3o de gastos com custeio; prioriza\u00e7\u00e3o de recursos para as atividades fins; e incentivo a busca por novas fontes de financiamento e parcerias. \u201cPor\u00e9m devemos estar atentos as restri\u00e7\u00f5es ficais que exigem uma maior aten\u00e7\u00e3o com gastos de pessoal\u201d, refor\u00e7a o superintendente de or\u00e7amento.<\/p>\n<p style=\"text-align: justify;\"><strong>Aplica\u00e7\u00e3o dos recursos<\/strong><\/p>\n<p style=\"text-align: justify;\">Para 2015 as pretens\u00f5es e prioridades do Governo s\u00e3o claras quanto a seu foco principal de atua\u00e7\u00e3o. Oito \u00e1reas de grande impacto social ser\u00e3o as mais beneficiadas. S\u00e3o elas: sa\u00fade, educa\u00e7\u00e3o, seguran\u00e7a p\u00fablica, transporte, saneamento b\u00e1sico, agricultura, assist\u00eancia social e urbaniza\u00e7\u00e3o. Delas, 77% dos recursos est\u00e3o alocados apenas nas tr\u00eas primeiras.<\/p>\n<p style=\"text-align: justify;\">\u201cPara 2015 teremos um aporte maior de recursos do Governo em diversas \u00e1reas, como sa\u00fade, educa\u00e7\u00e3o, seguran\u00e7a e assist\u00eancia social. Por exemplo: entre 2014 e 2015 o Governo prev\u00ea um crescimento de 8% dos recursos investidos em seguran\u00e7a p\u00fablica. Um valor que chega a 70 milh\u00f5es a mais apenas nos recursos do tesouro\u201d, argumenta o secret\u00e1rio de Estado do Planejamento, Or\u00e7amento e Gest\u00e3o, Jo\u00e3o Augusto Gama.<\/p>\n<p style=\"text-align: justify;\">Vale destacar, que o objetivo do Governo \u00e9 promover no pr\u00f3ximo ano um investimento de aproximadamente 1,87 bilh\u00f5es, advindos essencialmente das Opera\u00e7\u00f5es de Cr\u00e9dito j\u00e1 contratadas e dos Conv\u00eanios efetivados pelo Estado. \u00c9 fundamental pontuar que esse volume de investimentos s\u00f3 foi poss\u00edvel gra\u00e7as ao esfor\u00e7o permanente do Governo em criar, apesar das limita\u00e7\u00f5es de ordem econ\u00f4mica e financeira, as pr\u00e9-condi\u00e7\u00f5es essenciais para obter o aval do Governo Federal para contrair empr\u00e9stimos internos e externos com as institui\u00e7\u00f5es de fomento.<\/p>\n<p style=\"text-align: justify;\">\u201cA id\u00e9ia que norteou a elabora\u00e7\u00e3o desse or\u00e7amento foi de adotar um maior rigor na previs\u00e3o das receitas conjugado a uma forte conten\u00e7\u00e3o de despesas, para assim poder investir cada vez mais no bem estar dos sergipanos\u201d, enfatiza Gama.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Secom<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Jackson Barreto priorizar\u00e1 em 2015 as \u00e1reas de sa\u00fade, educa\u00e7\u00e3o e seguran\u00e7a. Para isso, ele enviou a proposta da Lei Or\u00e7ament\u00e1ria Anual (LOA) para Assembleia Legislativa que prev\u00ea 77% (R$ 6,6 bilh\u00f5es) do or\u00e7amento anual para essas \u00e1reas. O valor total do or\u00e7amento \u00e9 de R$ 8,625 bilh\u00f5es. A Lei Or\u00e7ament\u00e1ria Anual 2015 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-71097","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/71097"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=71097"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/71097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/56326"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=71097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=71097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=71097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}