{"id":70706,"date":"2014-10-02T14:25:12","date_gmt":"2014-10-02T17:25:12","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=70706"},"modified":"2014-10-02T14:25:12","modified_gmt":"2014-10-02T17:25:12","slug":"homofobia-disque-100-recebe-mais-denuncias-em-4-dias-que-em-3-anos","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/homofobia-disque-100-recebe-mais-denuncias-em-4-dias-que-em-3-anos\/","title":{"rendered":"Homofobia: disque 100 recebe mais den\u00fancias em 4 dias que em 3 anos"},"content":{"rendered":"<div id=\"attachment_66180\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/images1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-66180\" class=\"size-medium wp-image-66180\" alt=\"Disque 100 recebeu 6 mil den\u00fancias de homofobia.  (Foto: Reprodu\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/images1-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/images1-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/images1-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/images1.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-66180\" class=\"wp-caption-text\">Disque 100 recebeu 6 mil den\u00fancias de homofobia. (Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">Em apenas quatro dias, o servi\u00e7o telef\u00f4nico Direitos Humanos \u2013 Disque 100 recebeu 6 mil den\u00fancias de homofobia, em rela\u00e7\u00e3o \u00e0s declara\u00e7\u00f5es do candidato \u00e0 Presid\u00eancia da Rep\u00fablica Levy Fidelix (PRTB). O n\u00famero de chamadas \u00e9 maior que o registrado nos \u00faltimos tr\u00eas anos, segundo balan\u00e7o da Secretaria de Direitos Humanos da Presid\u00eancia da Rep\u00fablica (SDH-PR), que mant\u00e9m o servi\u00e7o. Em 2011, foram 1.159 den\u00fancias; em 2012, 3.031; e em 2013, 1.695. Ao todo, foram 5.885 casos nesses tr\u00eas anos. O primeiro semestre de 2014 mostrava que o n\u00famero vinha diminuindo. Entre janeiro e junho, foram 537 casos relatados, 48,56% menos do que os 1.044 contabilizados no mesmo per\u00edodo do ano anterior. Segundo a SDH, nos \u00faltimos anos, as den\u00fancias foram motivadas por casos como viol\u00eancia f\u00edsica, viol\u00eancia psicol\u00f3gica, discrimina\u00e7\u00e3o e neglig\u00eancia. J\u00e1 todas as den\u00fancias feitas entre domingo (28) e hoje (1\u00ba) foram relacionadas \u00e0s declara\u00e7\u00f5es do candidato.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s ser questionado pela candidata Luciana Genro (PSOL) sobre o casamento entre pessoas do mesmo sexo, em debate na TV Record, no \u00faltimo domingo, Levy Fidelix classificou a homossexualidade como dist\u00farbio psicol\u00f3gico, comparou homossexuais a ped\u00f3filos e chegou a conclamar a sociedade a \u201cenfrentar\u201d l\u00e9sbicas, gays, bissexuais, travestis, transexuais e transg\u00eaneros (LGBT). \u201cVamos ter coragem, n\u00f3s somos maioria, vamos enfrentar essa minoria\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">A Ag\u00eancia Brasil procurou discutir o aumento das den\u00fancias com a SDH, mas a secretaria n\u00e3o se pronunciar\u00e1 institucionalmente sobre o caso, por causa das veda\u00e7\u00f5es eleitorais.<\/p>\n<p style=\"text-align: justify;\">Outras formas de manifesta\u00e7\u00e3o foram levadas a cabo, nos \u00faltimos dias, como o ato p\u00fablico, ontem (30), na Avenida Paulista , em S\u00e3o Paulo, e os organizadores est\u00e1 convocando um &#8220;beija\u00e7o&#8221; para o pr\u00f3ximo s\u00e1bado. O ponto de encontro ser\u00e1 a casa de Fidelix, em rep\u00fadio \u00e0s ideias do candidato. Al\u00e9m disso, \u201cn\u00e3o vamos perder a oportunidade para ensinar ao Levy que nosso sexo n\u00e3o \u00e9 s\u00f3 sistema excretor. \u00c9 prazer, desejo, fantasia e faz parte de nossas identidades de g\u00eanero e orienta\u00e7\u00e3o sexual\u201d, diz o texto da convocat\u00f3ria.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m das manifesta\u00e7\u00f5es, as declara\u00e7\u00f5es tamb\u00e9m motivaram pelo menos tr\u00eas a\u00e7\u00f5es judiciais, que est\u00e3o sendo analisadas pelo Tribunal Superior Eleitoral.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ag\u00eancia Brasil<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em apenas quatro dias, o servi\u00e7o telef\u00f4nico Direitos Humanos \u2013 Disque 100 recebeu 6 mil den\u00fancias de homofobia, em rela\u00e7\u00e3o \u00e0s declara\u00e7\u00f5es do candidato \u00e0 Presid\u00eancia da Rep\u00fablica Levy Fidelix (PRTB). O n\u00famero de chamadas \u00e9 maior que o registrado nos \u00faltimos tr\u00eas anos, segundo balan\u00e7o da Secretaria de Direitos Humanos da Presid\u00eancia da Rep\u00fablica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":66180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-70706","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/70706"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=70706"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/70706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/66180"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=70706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=70706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=70706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}