{"id":70618,"date":"2014-09-30T15:49:51","date_gmt":"2014-09-30T18:49:51","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=70618"},"modified":"2014-09-30T15:56:48","modified_gmt":"2014-09-30T18:56:48","slug":"policia-desarticula-quadrilha-que-agia-no-baixo-sao-francisco","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/policia-desarticula-quadrilha-que-agia-no-baixo-sao-francisco\/","title":{"rendered":"Pol\u00edcia desarticula quadrilha que agia no baixo S\u00e3o Francisco"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_70620\" style=\"width: 290px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/conteudo_2_43636_20140930111143_542aba1f3da41.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-70620\" class=\"size-full wp-image-70620\" alt=\"Pol\u00edcia apresenta acusados. (Foto: SSP\/SE)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/conteudo_2_43636_20140930111143_542aba1f3da41.jpg\" width=\"280\" height=\"186\" \/><\/a><p id=\"caption-attachment-70620\" class=\"wp-caption-text\">Pol\u00edcia apresenta acusados. (Foto: SSP\/SE)<\/p><\/div>\n<p style=\"text-align: justify;\">Opera\u00e7\u00e3o realizada pela Pol\u00edcia Civil, com apoio dos Destacamentos da Pol\u00edcia Militar de Japoat\u00e3 e de S\u00e3o Francisco, desarticulou integrantes de quadrilha acusada de praticar roubos e desmanches de motocicletas, tr\u00e1fico de drogas e homic\u00eddio no Baixo S\u00e3o Francisco.<\/p>\n<p style=\"text-align: justify;\">De acordo com o delegado Ant\u00f4nio Wellington, a opera\u00e7\u00e3o recebeu o nome de \u201cOpera\u00e7\u00e3o Desmanche\u201d, em alus\u00e3o ao grande n\u00famero de motocicletas roubadas e depois desmanchadas para vender as pe\u00e7as. \u201cIniciamos as investiga\u00e7\u00f5es para apurar o grande n\u00famero de roubos de motocicletas na regi\u00e3o, por isso, pedimos v\u00e1rios mandados de busca e apreens\u00e3o que deferidos e cumpridos entre a ter\u00e7a-feira (25) e esta segunda-feira (29)\u201d, explicou.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de roubos de motocicletas, a pol\u00edcia tamb\u00e9m abriu um inqu\u00e9rito policial para apurar um homic\u00eddio que teve como v\u00edtima Wellington Francisco dos Santos, conhecido por &#8216;Nininho&#8217;, ocorrido no dia 7 de janeiro deste ano na cidade de S\u00e3o Francisco. \u201cDescobrimos que a ordem para matar Nininho foi dada por Genilson Santos de Melo, conhecido por &#8216;Gordo, Johny ou Jonathan&#8217;, que estava detido no pres\u00eddio \u00e0 \u00e9poca do crime. A v\u00edtima era usu\u00e1ria de drogas e estava devendo dinheiro aos traficantes\u201d, destacou.<\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9m foi apurado que o executor do homic\u00eddio foi o l\u00edder da quadrilha em Japoat\u00e3, Bruno Newton Marinho, 22 anos, vulgo &#8216;Bruno Cross&#8217;. \u201cEle recebeu a ordem e uniu o \u00fatil ao agrad\u00e1vel, pois descobriu que sua namorada lhe traia com Nininho. Ele pediu a uma mulher que atra\u00edsse a v\u00edtima para um local desabitado e o matou com v\u00e1rios tiros\u201d.<\/p>\n<p style=\"text-align: justify;\">Bruno Cross foi preso preventivamente sob a acusa\u00e7\u00e3o dos crimes de homic\u00eddio, tr\u00e1fico de drogas, roubo, recepta\u00e7\u00e3o de motos e associa\u00e7\u00e3o criminosa. Bruno Cross tinha como bra\u00e7o direito Jo\u00e3o Fl\u00e1vio de Oliveira Ramos, o &#8216;Sap\u00e3o&#8217;, que tamb\u00e9m foi preso preventivamente.<\/p>\n<p style=\"text-align: justify;\">Ainda foram presos preventivamente, Luana Cristina Santos, 18 anos, e Alexandre Barros Santana, 31, o &#8216;Capit\u00e3o&#8217;, acusados de colaborarem com o agrupamento criminoso.<\/p>\n<p><strong>Hist\u00f3rico<\/strong><\/p>\n<p style=\"text-align: justify;\">Bruno Cross e Fl\u00e1vio t\u00eam passagens pela pol\u00edcia pelo crime de recepta\u00e7\u00e3o e com eles foram apreendidos um rev\u00f3lver calibre 38 e 17 muni\u00e7\u00f5es, maconha e pe\u00e7as de motocicletas; Alexandre tem passagem por homic\u00eddio, Genilson continua preso em uma penitenci\u00e1ria do Estado e a Pol\u00edcia Civil acredita que ele tem liga\u00e7\u00e3o com criminosos que agem dentro dos pres\u00eddios de S\u00e3o Paulo.<\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>Informa\u00e7\u00f5es da SSP\/SE<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Opera\u00e7\u00e3o realizada pela Pol\u00edcia Civil, com apoio dos Destacamentos da Pol\u00edcia Militar de Japoat\u00e3 e de S\u00e3o Francisco, desarticulou integrantes de quadrilha acusada de praticar roubos e desmanches de motocicletas, tr\u00e1fico de drogas e homic\u00eddio no Baixo S\u00e3o Francisco. De acordo com o delegado Ant\u00f4nio Wellington, a opera\u00e7\u00e3o recebeu o nome de \u201cOpera\u00e7\u00e3o Desmanche\u201d, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-70618","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/70618"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=70618"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/70618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/70620"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=70618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=70618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=70618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}