{"id":70603,"date":"2014-09-30T07:54:52","date_gmt":"2014-09-30T10:54:52","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=70603"},"modified":"2014-09-30T07:54:52","modified_gmt":"2014-09-30T10:54:52","slug":"hospital-universitario-e-beneficiado-com-r-22-milhoes","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/hospital-universitario-e-beneficiado-com-r-22-milhoes\/","title":{"rendered":"Hospital Universit\u00e1rio \u00e9 beneficiado com R$ 2,2 milh\u00f5es"},"content":{"rendered":"<div id=\"attachment_57820\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/ufs_fachada_foto_ascom.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-57820\" class=\"size-medium wp-image-57820\" alt=\"Hospital universit\u00e1rio de Aracaj\u00fa tem refor\u00e7o de R$ 2,2 milh\u00f5es.(Foto: Arquivo\/Ascom)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/ufs_fachada_foto_ascom-300x211.jpg\" width=\"300\" height=\"211\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/ufs_fachada_foto_ascom-300x211.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/ufs_fachada_foto_ascom-342x241.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/ufs_fachada_foto_ascom.jpg 595w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-57820\" class=\"wp-caption-text\">Hospital universit\u00e1rio de Aracaj\u00fa tem refor\u00e7o de R$ 2,2 milh\u00f5es.(Foto: Arquivo\/Ascom)<\/p><\/div>\n<p style=\"text-align: justify;\">O Minist\u00e9rio da Sa\u00fade liberou R$ 2,2 milh\u00f5es para o Hospital Universit\u00e1rio de Aracaj\u00fa (SE). O recurso \u00e9 destinado \u00e0s a\u00e7\u00f5es que integram o Programa Nacional de Reestrutura\u00e7\u00e3o dos Hospitais Universit\u00e1rios (REHUF), desenvolvido e financiado em parceria com o Minist\u00e9rio da Educa\u00e7\u00e3o. Para todo pa\u00eds, o recurso total \u00e9 de R$ 150,4 milh\u00f5es. Os valores s\u00e3o definidos junto com as institui\u00e7\u00f5es e levam em conta os indicadores e metas de desempenho de cada local. Com esse incentivo, os hospitais universit\u00e1rios podem adquirir equipamentos como aparelhos para exames de imagem, realizar pequenas reformas ou comprar materiais de limpeza, entre outros itens.<\/p>\n<p style=\"text-align: justify;\">Essa \u00e9 a quarta vez s\u00f3 neste ano que essas institui\u00e7\u00f5es de ensino superior de todo pa\u00eds recebem esse tipo de refor\u00e7o financeiro, totalizando R$ 391,1 milh\u00f5es. Ao todo, ser\u00e3o beneficiadas 39 institui\u00e7\u00f5es, localizadas em 29 cidades, sendo 21 capitais. At\u00e9 o final do ano, ser\u00e3o pagos RS 463,7 milh\u00f5es. As tr\u00eas portarias que liberam os R$ 150,4 milh\u00f5es, incluindo os R$ 2,2 milh\u00f5es destinados ao Hospital Universit\u00e1rio de Aracaj\u00fa, foram publicadas no Di\u00e1rio Oficial da Uni\u00e3o (D.O.U).<\/p>\n<p style=\"text-align: justify;\">Desde maio deste ano a at\u00e9 o in\u00edcio de setembro, j\u00e1 foram repassados R$ 240,7 milh\u00f5es para os hospitais do REHUF. Do total que ser\u00e1 liberado at\u00e9 o final de 2014, R$ 328,2 milh\u00f5es s\u00e3o para o custeio de atividades assistenciais e de ensino, obras e reformas e os outros R$ 140,9 milh\u00f5es, para a compra de equipamentos e melhoria de infraestrutura. &#8220;Com mais equipamentos, \u00e1rea f\u00edsica, ambi\u00eancia adequada e profissionais capacitados nos Hospitais, mais benef\u00edcios garantimos a popula\u00e7\u00e3o, seja por meio da redu\u00e7\u00e3o de tempo de espera para interna\u00e7\u00e3o ou mais rapidez na realiza\u00e7\u00e3o de consultas e exames. Ou seja, maior resolutividade na assist\u00eancia \u00e0 sa\u00fade, no menor tempo poss\u00edvel e de uma forma humanizada\u201d, ressaltou o Secret\u00e1rio de Aten\u00e7\u00e3o \u00e0 Sa\u00fade, Fausto Santos.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m dos recursos do REHUF para reestrutura\u00e7\u00e3o e revitaliza\u00e7\u00e3o dos hospitais universit\u00e1rios, o Minist\u00e9rio da Sa\u00fade repassa cerca de R$ 1,2 bilh\u00f5es por ano para o custeio da assist\u00eancia de m\u00e9dia e alta complexidade prestada por estes estabelecimentos durante o atendimento. Desde o in\u00edcio do programa, em 2010, o Minist\u00e9rio da Sa\u00fade j\u00e1 investiu mais de R$ 2 bilh\u00f5es em hospitais de ensino de todo pa\u00eds. Atualmente, 46 hospitais e outras duas unidades de sa\u00fade ligadas \u00e0s universidades fazem parte do REHUF. Essas institui\u00e7\u00f5es est\u00e3o localizadas em 33 cidades do pa\u00eds, sendo 24 capitais.<\/p>\n<p style=\"text-align: justify;\">Os hospitais universit\u00e1rios s\u00e3o vinculados \u00e0s institui\u00e7\u00f5es de ensino superior do Minist\u00e9rio da Educa\u00e7\u00e3o, respons\u00e1vel pelo pagamento dos profissionais concursados. J\u00e1 o Minist\u00e9rio da Sa\u00fade repassa recursos para o custeio dos servi\u00e7os prestados \u00e0 popula\u00e7\u00e3o nas unidades, recursos do REHUF, entre outros incentivos.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: MS<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio da Sa\u00fade liberou R$ 2,2 milh\u00f5es para o Hospital Universit\u00e1rio de Aracaj\u00fa (SE). O recurso \u00e9 destinado \u00e0s a\u00e7\u00f5es que integram o Programa Nacional de Reestrutura\u00e7\u00e3o dos Hospitais Universit\u00e1rios (REHUF), desenvolvido e financiado em parceria com o Minist\u00e9rio da Educa\u00e7\u00e3o. Para todo pa\u00eds, o recurso total \u00e9 de R$ 150,4 milh\u00f5es. Os valores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-70603","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/70603"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=70603"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/70603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/57820"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=70603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=70603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=70603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}