{"id":70282,"date":"2014-09-22T19:12:38","date_gmt":"2014-09-22T22:12:38","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=70282"},"modified":"2014-09-22T19:25:22","modified_gmt":"2014-09-22T22:25:22","slug":"70282","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/70282\/","title":{"rendered":"Pleno do TRE rejeita candidatura de Sukita"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_68415\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/sukita.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-68415\" class=\"size-medium wp-image-68415\" alt=\"Em decis\u00e3o un\u00e2nime, o TRE rejeitou a candidatura de Sukita a deputado pelo PSB    (Foto: Marina Fontenele\/G1)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/sukita-300x224.jpg\" width=\"300\" height=\"224\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/sukita-300x224.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/sukita-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/sukita-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/sukita-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/sukita-269x201.jpg 269w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/sukita.jpg 595w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-68415\" class=\"wp-caption-text\">Em decis\u00e3o un\u00e2nime, o TRE rejeitou a candidatura de Sukita.<br \/>(Foto: Marina Fontenele\/G1)<\/p><\/div>\n<p style=\"text-align: justify;\">O pleno do TRE, ao julgar na sess\u00e3o desta segunda-feira (22) \u00e0 tarde, o recurso proposto por Manuel Messias Sukita (PSB), de embargos declarat\u00f3rios que tinha como objetivo conseguir a anula\u00e7\u00e3o de sua ren\u00fancia \u00e0 candidatura, foi rejeitado por unanimidade (6&#215;0).<\/p>\n<p style=\"text-align: justify;\">Esta decis\u00e3o da Justi\u00e7a Eleitoral reconhece mais a idoneidade do documento de ren\u00fancia que foi entregue pelo PSB ao TRE, a pedido do pr\u00f3prio ex-prefeito, caso surgisse outro fato que atingisse a imagem do partido.<\/p>\n<p style=\"text-align: justify;\">Como consequ\u00eancia desta resolu\u00e7\u00e3o da Justi\u00e7a Eleitoral, a menos de 15 dias das elei\u00e7\u00f5es, para todos os efeitos legais, a candidatura de Sukita n\u00e3o existe, uma vez que a sua ren\u00fancia foi aceita pelo TRE, antes que o seu pedido de registro fosse julgado pela Corte.<\/p>\n<p style=\"text-align: justify;\">Na pr\u00e1tica, caso o ato de ren\u00fancia seja confirmado pelo TSE, at\u00e9 o dia 5\/10, todos os votos dados ao candidato Sukita ser\u00e3o nulos e n\u00e3o constar\u00e3o da totalidade da apura\u00e7\u00e3o a ser divulgada pela Justi\u00e7a Eleitoral ap\u00f3s o pleito.<\/p>\n<p>Se antes do dia 5\/10 o TSE julgar favor\u00e1vel ao candidato, tornando sem efeito a sua ren\u00fancia, o TRE de Sergipe passar\u00e1 ent\u00e3o a julgar o seu pedido de registro, sobre o qual pesam tr\u00eas fortes impugna\u00e7\u00f5es. Quem trabalha na \u00e1rea do direito eleitoral opina que em t\u00e3o curto prazo ser\u00e1 muito dif\u00edcil para Sukita reverter situa\u00e7\u00e3o t\u00e3o desfavor\u00e1vel.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta pelo <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p><strong><em>Informa\u00e7\u00f5es do Fax Aju<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O pleno do TRE, ao julgar na sess\u00e3o desta segunda-feira (22) \u00e0 tarde, o recurso proposto por Manuel Messias Sukita (PSB), de embargos declarat\u00f3rios que tinha como objetivo conseguir a anula\u00e7\u00e3o de sua ren\u00fancia \u00e0 candidatura, foi rejeitado por unanimidade (6&#215;0). Esta decis\u00e3o da Justi\u00e7a Eleitoral reconhece mais a idoneidade do documento de ren\u00fancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,1],"tags":[],"class_list":{"0":"post-70282","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/70282"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=70282"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/70282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/68415"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=70282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=70282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=70282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}