{"id":69913,"date":"2014-09-15T09:29:44","date_gmt":"2014-09-15T12:29:44","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=69913"},"modified":"2014-09-15T11:37:46","modified_gmt":"2014-09-15T14:37:46","slug":"tem-politico-querendo-comprar-voto-e-eleitor-querendo-vender","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tem-politico-querendo-comprar-voto-e-eleitor-querendo-vender\/","title":{"rendered":"\u201cTem pol\u00edtico querendo comprar voto e eleitor querendo vender\u201d"},"content":{"rendered":"<div id=\"attachment_42074\" style=\"width: 236px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/12\/F\u00e1bio-Henrique.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-42074\" class=\"size-full wp-image-42074\" alt=\"F\u00e1bio avaliou que o atual sistema eleitoral est\u00e1 esgotado e defendeu uma reforma pol\u00edtica. (Foto: Ascom\/Socorro)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/12\/F\u00e1bio-Henrique.jpg\" width=\"226\" height=\"150\" \/><\/a><p id=\"caption-attachment-42074\" class=\"wp-caption-text\">F\u00e1bio avaliou que o atual sistema eleitoral est\u00e1 esgotado e defendeu uma reforma pol\u00edtica. (Foto: Ascom\/Socorro)<\/p><\/div>\n<p style=\"text-align: justify;\">Nesta entrevista ao <a href=\"http:\/\/jornaldacidade.net\/politica-leitura\/78364\/tem-politico-querendo-comprar-voto-e-eleitor-querendo-vender.html#.VBb2F_ldVqU\" target=\"_blank\"><strong>JORNAL DA CIDADE<\/strong><\/a>, o prefeito do Munic\u00edpio de Nossa Senhora do Socorro, F\u00e1bio Henrique (PDT), afirmou que o desespero dos pol\u00edticos que est\u00e3o atr\u00e1s nas pesquisas pode gerar baixaria durante a campanha. Mas ele adverte que a sociedade n\u00e3o aceitar\u00e1 isso. Na conversa, F\u00e1bio avaliou que o atual sistema eleitoral est\u00e1 esgotado e defendeu uma reforma pol\u00edtica. Ele tamb\u00e9m disse que a candidatura da sua esposa, S\u00edlvia Fontes (PDT), que disputa vaga na Assembleia Legislativa, vai bem \u2013 e que ela \u00e9 a \u00fanica que representar\u00e1 o munic\u00edpio, de fato e direito. O prefeito tamb\u00e9m disse ter convic\u00e7\u00e3o na vit\u00f3ria do governador Jackson Barreto (PMDB), em Socorro e em Sergipe. Leia a seguir.<\/p>\n<p style=\"text-align: justify;\"><strong>JORNAL DA CIDADE &#8211; O processo eleitoral deste ano est\u00e1 mesmo sendo diferente?<\/strong><br \/>\nF\u00c1BIO HENRIQUE \u2013 Percebe-se uma diferen\u00e7a muito clara, percebe-se que esse modelo eleitoral cansou. Cansou a classe pol\u00edtica e cansou tamb\u00e9m o eleitor. Voc\u00ea percebe uma elei\u00e7\u00e3o com certa atipicidade, uma elei\u00e7\u00e3o fria, que faz com que a classe pol\u00edtica repense e fa\u00e7a definitivamente a reforma pol\u00edtica, que dorme nas gavetas do Congresso Nacional h\u00e1 muitos anos e infelizmente n\u00e3o \u00e9 feita. Ent\u00e3o, eu acho que a reforma pol\u00edtica \u00e9 fundamental, at\u00e9 para que o processo eleitoral se torne vi\u00e1vel no Brasil, porque da forma com est\u00e1, est\u00e1 ficando invi\u00e1vel, em todos os sentidos.<\/p>\n<p><strong>\u00a0JC &#8211; Muito se fala nesta elei\u00e7\u00e3o da influ\u00eancia do poder econ\u00f4mico. O senhor tem sentido isso, principalmente no munic\u00edpio de Nossa Senhora do Socorro?<\/strong><\/p>\n<p style=\"text-align: justify;\">FH \u2013 Dizer que n\u00e3o h\u00e1 influ\u00eancia do poder econ\u00f4mico no processo eleitoral seria negar o \u00f3bvio, o que est\u00e1 a\u00ed \u00e0s claras. Evidente que n\u00f3s temos \u00f3rg\u00e3os de controle e fiscaliza\u00e7\u00e3o que s\u00e3o muito eficientes, mas tudo isso s\u00f3 vai ser resolvido, ou diminuir, com a reforma pol\u00edtica: financiamento p\u00fablico de campanha, voto distrital misto e teses que acabem com a corrup\u00e7\u00e3o eleitoral. \u00c9 bom destacar que em muitos casos voc\u00ea tem o pol\u00edtico querendo comprar o voto e o eleitor querendo vender. N\u00e3o \u00e9 s\u00f3 o pol\u00edtico querendo comprar. Precisamos encontrar um mecanismo para acabar com isso, com o pol\u00edtico que compre o voto, mas acabar tamb\u00e9m com o eleitor que venda o voto, para que voc\u00ea tenha tamb\u00e9m uma elei\u00e7\u00e3o limpa.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0JC &#8211; Como est\u00e1 a disputa pelo governo estadual no Munic\u00edpio de Socorro?<\/strong><br \/>\nFH \u2013 Aqui em Socorro ocorre o fen\u00f4meno que vem se repetindo no Estado inteiro: a candidatura de Jackson Barreto est\u00e1 consolidada e enraizada, pela hist\u00f3ria que ele tem no Estado, e sobretudo aqui em Socorro. Jackson \u00e9 um pol\u00edtico que milita em Socorro, desde quando era prefeito de Aracaju. Ele conhece os problemas de Socorro, conhece as pessoas. E investiu muito em Socorro. O Governo do Estado tem uma a\u00e7\u00e3o muito forte na cidade de Socorro. Ent\u00e3o, n\u00f3s acreditamos muito no projeto de reelei\u00e7\u00e3o de Jackson Barreto, que \u00e9 importante at\u00e9 para que essa parceria possa continuar, para que as obras e investimentos que ainda precisam ser feitos possam acontecer. Tenho convic\u00e7\u00e3o da vit\u00f3ria do governador Jackson Barreto em Socorro e em Sergipe.<\/p>\n<p style=\"text-align: justify;\"><strong>JC &#8211; Foi essa parceria com a prefeitura que fez o senhor se definir pela candidatura de Jackson Barreto?<\/strong><br \/>\nFH \u2013 Eu diria que essa parceria foi o fator preponderante. Seria uma injusti\u00e7a da parte do nosso agrupamento pol\u00edtico n\u00e3o votar em Jackson Barreto, por tudo aquilo que ele fez pelo Munic\u00edpio de Socorro. E evidentemente que a hist\u00f3ria de Jackson na pol\u00edtica de Sergipe tamb\u00e9m pesou, no momento de tomar uma decis\u00e3o como essa, t\u00e3o importante.<\/p>\n<p style=\"text-align: justify;\"><strong>JC &#8211; Socorro fica ent\u00e3o dividida, com o deputado estadual Z\u00e9 Franco se unindo a advers\u00e1rios?<\/strong><br \/>\nFH \u2013 Eu aprendi na vida pol\u00edtica a me preocupar com o nosso time e nossos amigos. A pol\u00edtica de Socorro hoje est\u00e1 muito clara e definida, ao contr\u00e1rio do que aconteceu em 2010, quando existiam apoios velados e outros declarados.Hojea situa\u00e7\u00e3o est\u00e1 definida, as pessoas sabem quem \u00e9 de um lado e quem \u00e9 do outro lado. O que posso assegurar \u00e9 que a maioria esmagadora do nosso agrupamento pol\u00edtico, incluindo vereadores e lideran\u00e7as, seguiu o caminho que n\u00f3s trilhamos. Foi um caminho \u00e0s claras, aberto. Fizemos um acordo muito claro com o governador, em favor do Socorro. Quem ama Socorro precisa estar com quem est\u00e1 cuidando de Socorro. E o governador Jackson Barreto tem tido muito carinho, aten\u00e7\u00e3o e respeito ao Munic\u00edpio de Socorro.<\/p>\n<p style=\"text-align: justify;\"><strong>JC &#8211; Como o senhor avalia essa situa\u00e7\u00e3o do deputado Jos\u00e9 Franco, que ainda n\u00e3o assumiu o comando da Assembleia Legislativa, de forma definitiva?<\/strong><br \/>\nFH \u2013 Prefiro n\u00e3o opinar sobre isso. Tenho muito respeito pelo deputado, fomos aliados pol\u00edticos por muitos anos e o fato de sermos hoje advers\u00e1rios n\u00e3o significa que sejamos inimigos. Eu desejo a ele sucesso, que ele possa assumir a Presid\u00eancia da Assembleia Legislativa de fato e de direito. N\u00e3o participei das discuss\u00f5es e dos entendimentos sobre a Assembleia e n\u00e3o me sinto \u00e0 vontade para opinar sobre isso.<\/p>\n<p style=\"text-align: justify;\">JC &#8211; Como est\u00e1 a movimenta\u00e7\u00e3o dos vereadores em Socorro? \u00c9 verdade que alguns mudaram de lado e querem retornar?<br \/>\nFH \u2013 Desconhe\u00e7o essa informa\u00e7\u00e3o de mudan\u00e7as. Alguns vereadores tomaram a decis\u00e3o de apoiar outra candidatura. N\u00e3o concordei, mas respeito a decis\u00e3o de cada um. Tentei mostrar que esse n\u00e3o era o melhor caminho, mas me mantenho firme com os 13 vereadores que optaram por votar em Jackson.<\/p>\n<p style=\"text-align: justify;\"><strong>JC &#8211; Como est\u00e1 a candidatura da sua esposa, S\u00edlvia Fontes?<\/strong><br \/>\nFH \u2013 Gra\u00e7as a Deus a candidatura de S\u00edlvia est\u00e1 muito bem. Evidente que elei\u00e7\u00e3o s\u00f3 se decide no dia, n\u00e3o tem elei\u00e7\u00e3o ganha, tenho dito isso aos meus companheiros. Precisamos trabalhar muito, sobretudo agora na reta final. S\u00edlvia \u00e9 um nome novo, uma mulher que trabalha, n\u00e3o tem desgaste e \u00e9 a \u00fanica candidatura que representa Socorro nesse processo eleitoral. E a maioria dos vereadores apoia a candidatura dela, junto com a popula\u00e7\u00e3o. Tem sido muito gratificante receber esse apoio, de sorte que acho que estamos indo bem. O povo de Socorro precisa ter um representante na Assembleia, de fato e de direito, que fale e defenda os interesses da nossa cidade \u2013 e naturalmente do Estado tamb\u00e9m.<\/p>\n<p style=\"text-align: justify;\"><strong>JC &#8211; Houve uma divis\u00e3o no PDT. Como o partido fica, no per\u00edodo p\u00f3s-elei\u00e7\u00e3o?<\/strong><br \/>\nFH \u2013 Naturalmente, a partir de 2015, o PDT passar\u00e1 por uma reformula\u00e7\u00e3o no Estado. A decis\u00e3o que o PDT tomou, \u00e9 bom que se frise, n\u00e3o foi uma decis\u00e3o de F\u00e1bio Henrique. A decis\u00e3o que tomamos foi respaldada pela maioria dos que faziam, naquele momento, a dire\u00e7\u00e3o do PDT. Alguns mudaram de posi\u00e7\u00e3o ou ent\u00e3o n\u00e3o seguiram aquilo que havia sido acordado. Mantive a minha coer\u00eancia, a minha posi\u00e7\u00e3o, tive todo o respaldo da dire\u00e7\u00e3o nacional do meu partido e ap\u00f3s a elei\u00e7\u00e3o o PDT passar\u00e1 por uma reformula\u00e7\u00e3o. N\u00e3o estou dizendo que o PDT vai expulsar ningu\u00e9m, n\u00e3o temos esse tipo de atitude, mas vamos procurar os companheiros para discutir a reformula\u00e7\u00e3o pol\u00edtica. Muitas outras pessoas vir\u00e3o, outros quadros com quem estamos construindo rela\u00e7\u00e3o pol\u00edtica. O PDT vai ser um partido forte em Sergipe, vamos ter candidato a prefeito, vice e vereador em v\u00e1rios munic\u00edpios do Estado. Anote, vamos ter uma chapa muito forte em Aracaju. Vamos disputar uma chapa forte de vereador e construir uma chapa inclusive para disputar a elei\u00e7\u00e3o majorit\u00e1ria.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0JC &#8211; Isso quer dizer que o senhor pode ser candidato a prefeito de Aracaju? Quais s\u00e3o seus planos para depois da conclus\u00e3o do mandato de prefeito?<\/strong><br \/>\nFH \u2013 Primeiro, o meu plano, no projeto pol\u00edtico, \u00e9 consolidar a elei\u00e7\u00e3o de Jackson Barreto, Rog\u00e9rio Carvalho, S\u00edlvia Fontes e Bosco Costa, que s\u00e3o os nossos candidatos. Projeto pol\u00edtico para o futuro s\u00f3 vamos discutir passada a elei\u00e7\u00e3o, vamos fazer uma avalia\u00e7\u00e3o do processo eleitoral, para ver o que vai acontecer. N\u00e3o sou pol\u00edtico profissional, sou profissional de r\u00e1dio e sou policial rodovi\u00e1rio federal concursado, mas gosto de fazer pol\u00edtica. Posso lhe adiantar \u00e9 que continuarei na pol\u00edtica N\u00e3o sei em que posi\u00e7\u00e3o ou disputando o que, mas continuarei participando ativamente.<\/p>\n<p style=\"text-align: justify;\"><strong>JC &#8211; Como profissional de imprensa e pol\u00edtico experiente, como o senhor avalia esse acirramento que vem sendo verificado na elei\u00e7\u00e3o em Sergipe?<\/strong><br \/>\nFH \u2013 Isso vai do desespero dos que est\u00e3o perdendo nas pesquisas. Acho que isso n\u00e3o constr\u00f3i, a sociedade n\u00e3o aceita mais isso. Essa pol\u00edtica do xingamento, da baixaria, isso j\u00e1 era. A sociedade hoje quer saber o que voc\u00ea fez e o que pretende fazer. A sociedade quer saber o seu passado, a sua hist\u00f3ria, se voc\u00ea \u00e9 ficha-limpa. Essa hist\u00f3ria de baixaria e xingamento, quem enveredar por esse caminho n\u00e3o vai obter sucesso.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0JC &#8211; O senhor j\u00e1 est\u00e1 vendo sinais de desespero em grupos pol\u00edticos?<\/strong><br \/>\nFH \u2013 Com a prov\u00e1vel vit\u00f3ria do nosso governador Jackson, naturalmente, o grupo advers\u00e1rio procura se movimentar. Isso \u00e9 democr\u00e1tico, \u00e9 do processo. O que n\u00e3o \u00e9 democr\u00e1tico \u00e9 enveredar por esse caminho de baixaria. Isso sou contra, espero que n\u00e3o aconte\u00e7a, espero que a elei\u00e7\u00e3o seja debatida e constru\u00edda no campo das ideias.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0JC &#8211; Quais as a\u00e7\u00f5es na prefeitura que o senhor destacaria neste \u00faltimo mandato?Como est\u00e1 a administra\u00e7\u00e3o de Socorro?<\/strong><br \/>\nFH \u2013 A administra\u00e7\u00e3o p\u00fablica, de uma forma geral, passa por um momento muito dif\u00edcil, de arrecada\u00e7\u00e3o ruim, de dificuldades enormes dos prefeitos. Mas Socorro paga o sal\u00e1rio dos funcion\u00e1rios dentro do m\u00eas trabalhado e n\u00e3o tem atrasos; paga o piso dos professores; paga o piso dos agentes de sa\u00fade (antes da aprova\u00e7\u00e3o da lei). Estamos discutindo plano de cargos e sal\u00e1rios. Temos uma s\u00e9rie de obras que vamos entregar, como pra\u00e7as, creches. Quando assumimos a prefeitura n\u00e3o tinha creche alguma e vamos deixar com onze creches, a primeira ser\u00e1 inaugurada em breve. Uma s\u00e9rie de obras de pavimenta\u00e7\u00e3o. Mesmo com todas as dificuldades, temos o que dizer, temos o que mostrar \u00e0 sociedade, com nosso trabalho de mudan\u00e7a no munic\u00edpio.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta entrevista ao JORNAL DA CIDADE, o prefeito do Munic\u00edpio de Nossa Senhora do Socorro, F\u00e1bio Henrique (PDT), afirmou que o desespero dos pol\u00edticos que est\u00e3o atr\u00e1s nas pesquisas pode gerar baixaria durante a campanha. Mas ele adverte que a sociedade n\u00e3o aceitar\u00e1 isso. Na conversa, F\u00e1bio avaliou que o atual sistema eleitoral est\u00e1 esgotado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,1],"tags":[],"class_list":{"0":"post-69913","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69913"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=69913"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/42074"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=69913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=69913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=69913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}