{"id":69847,"date":"2014-09-12T17:03:00","date_gmt":"2014-09-12T20:03:00","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=69847"},"modified":"2014-09-12T21:15:15","modified_gmt":"2014-09-13T00:15:15","slug":"prf-intensifica-combate-a-crimes-ambientais","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/prf-intensifica-combate-a-crimes-ambientais\/","title":{"rendered":"PRF intensifica combate a crimes ambientais"},"content":{"rendered":"<div id=\"attachment_69848\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1292014142547.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69848\" class=\"size-medium wp-image-69848\" alt=\"Foto: Ascom\/PRF\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1292014142547-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1292014142547-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1292014142547-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1292014142547-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1292014142547-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1292014142547-269x201.jpg 269w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1292014142547.jpg 620w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-69848\" class=\"wp-caption-text\">Foto: Ascom\/PRF<\/p><\/div>\n<p style=\"text-align: justify;\">A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) tem intensificado o trabalho de fiscaliza\u00e7\u00e3o nas rodovias sergipanas, com o objetivo de combater os crimes ambientais. Na \u00faltima quinta-feira (11), no munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o (SE), a 26 km da capital, agentes da PRF detiveram dois homens transportando irregularmente produtos perigosos.<\/p>\n<p style=\"text-align: justify;\">Durante fiscaliza\u00e7\u00e3o de rotina, ainda pela manh\u00e3, os policiais abordaram um bitrem, com placas de Minas Gerais, conduzido por um homem de 61 anos, que transportava ilegalmente 39.250 kg de borra de neutraliza\u00e7\u00e3o de \u00f3leo vegetal. De acordo com informa\u00e7\u00f5es da PRF, o material era transportado em tanques destinados ao transporte de combust\u00edveis, contaminando, assim, o produto que seria usado na produ\u00e7\u00e3o de ra\u00e7\u00e3o animal.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 no per\u00edodo da noite, os policiais abordaram uma carreta VOLVO\/FH440, com placas da Bahia, conduzida por um homem de 38 anos. A Pol\u00edcia encontrou 35.540 kg de xarope de Maltose que tamb\u00e9m estavam sendo transportados, de forma inadequada, em um tanque que \u00e9 utilizado para transporte de combust\u00edveis. Segundo a PRF, esse transporte inadequado contamina o produto, que depois seria utilizado na produ\u00e7\u00e3o de g\u00eanero aliment\u00edcio. Ap\u00f3s a constata\u00e7\u00e3o dos policiais, os condutores foram detidos com fulcro na lei de crimes ambientais (Lei 9.605\/98), art. 56, e suas respectivas cargas foram apreendidas. As ocorr\u00eancias foram encaminhadas \u00e0 delegacia.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es da Assessoria de Comunica\u00e7\u00e3o\/PRF<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) tem intensificado o trabalho de fiscaliza\u00e7\u00e3o nas rodovias sergipanas, com o objetivo de combater os crimes ambientais. Na \u00faltima quinta-feira (11), no munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o (SE), a 26 km da capital, agentes da PRF detiveram dois homens transportando irregularmente produtos perigosos. Durante fiscaliza\u00e7\u00e3o de rotina, ainda pela manh\u00e3, os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-69847","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69847"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=69847"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/69848"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=69847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=69847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=69847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}