{"id":69836,"date":"2014-09-12T15:04:28","date_gmt":"2014-09-12T18:04:28","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=69836"},"modified":"2014-09-13T17:56:19","modified_gmt":"2014-09-13T20:56:19","slug":"banco-do-nordeste-e-condenado-a-indenizacao-de-200-mil","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/banco-do-nordeste-e-condenado-a-indenizacao-de-200-mil\/","title":{"rendered":"Banco do Nordeste \u00e9 condenado a indeniza\u00e7\u00e3o de 200 mil"},"content":{"rendered":"<div id=\"attachment_69837\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/grande-bnb_fechado_270613.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69837\" class=\"size-medium wp-image-69837\" alt=\"Banco foi condenado (Foto: Reprodu\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/grande-bnb_fechado_270613-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/grande-bnb_fechado_270613-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/grande-bnb_fechado_270613-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/grande-bnb_fechado_270613.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-69837\" class=\"wp-caption-text\">Banco foi condenado (Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">Ap\u00f3s a\u00e7\u00e3o civil p\u00fablica proposta pelo Minist\u00e9rio P\u00fablico do Trabalho em Sergipe (MPT-SE), a Vara do Trabalho de Itabaiana condenou o Banco do Nordeste do Brasil S\/A (BNB) por n\u00e3o contratar adolescentes aprendizes, fraudar os controles de jornada de trabalho, suprimir o intervalo intrajornada para repouso ou alimenta\u00e7\u00e3o e exigir horas extras irregularmente.<\/p>\n<p style=\"text-align: justify;\">Com a condena\u00e7\u00e3o, o BNB est\u00e1 obrigado a, no prazo de 30 dias, comprovar a contrata\u00e7\u00e3o de aprendizes e a implanta\u00e7\u00e3o do registro de jornada com apontamento dos hor\u00e1rios de intervalo. Tamb\u00e9m ficou definido que o Banco deve prestar contas, no prazo de 60 dias, sobre a concess\u00e3o do intervalo interjornada e o registro das horas extras laboradas, bem como apresenta\u00e7\u00e3o dos contracheques com o pagamento das horas extras prestadas, sob pena do pagamento de multa di\u00e1ria de R$ 1 mil.<\/p>\n<p style=\"text-align: justify;\">Pelo descumprimento da legisla\u00e7\u00e3o trabalhista foi fixada indeniza\u00e7\u00e3o por dano moral coletivo no valor de R$ 200 mil, a ser revertida em favor de entidade posteriormente designada. O MPT n\u00e3o concorda com o valor estipulado e vai recorrer da senten\u00e7a.<\/p>\n<p style=\"text-align: justify;\">Para o procurador do Trabalho que acompanhou a a\u00e7\u00e3o, Jos\u00e9 Adilson Pereira da Costa, \u201co MPT requereu a t\u00edtulo de indeniza\u00e7\u00e3o por dano moral coletivo o equivalente a 0,1% (um d\u00e9cimo por cento) do capital social do BNB, o que perfaz a quantia de R$ 2.142.000,00. O valor definido na senten\u00e7a n\u00e3o satisfaz o objetivo que se almeja com a indeniza\u00e7\u00e3o por dano moral coletivo, que \u00e9 o de reprimir pr\u00e1ticas danosas \u00e0 coletividade, levando em considera\u00e7\u00e3o o porte econ\u00f4mico do infrator, bem como o de assegurar compensa\u00e7\u00e3o razo\u00e1vel pelas condutas il\u00edcitas praticadas, para que, inclusive, n\u00e3o voltem a ocorrer\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>BNB<\/strong><\/p>\n<p style=\"text-align: justify;\">Em nota enviada ao Portal Infonet, a assessoria de comunica\u00e7\u00e3o do banco informa que adotar\u00e1 as devidas provid\u00eancias. Confira o conte\u00fado na \u00edntegra: &#8220;o Banco do Nordeste informa que, t\u00e3o logo tenha pleno conhecimento do inteiro teor da decis\u00e3o judicial, adotar\u00e1 as provid\u00eancias processuais cab\u00edveis \u00e0 A\u00e7\u00e3o Civil P\u00fablica ajuizada pelo Minist\u00e9rio P\u00fablico do Trabalho do Estado de Sergipe.\u201d<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do Portal Infonet e das assessorias do MPT e do BNB<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a\u00e7\u00e3o civil p\u00fablica proposta pelo Minist\u00e9rio P\u00fablico do Trabalho em Sergipe (MPT-SE), a Vara do Trabalho de Itabaiana condenou o Banco do Nordeste do Brasil S\/A (BNB) por n\u00e3o contratar adolescentes aprendizes, fraudar os controles de jornada de trabalho, suprimir o intervalo intrajornada para repouso ou alimenta\u00e7\u00e3o e exigir horas extras irregularmente. Com a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,6],"tags":[],"class_list":{"0":"post-69836","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69836"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=69836"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/69837"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=69836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=69836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=69836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}