{"id":69706,"date":"2014-09-09T16:03:50","date_gmt":"2014-09-09T19:03:50","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=69706"},"modified":"2014-09-09T16:04:23","modified_gmt":"2014-09-09T19:04:23","slug":"ventos-fortes-e-chuvas-marcam-clima-de-se","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/ventos-fortes-e-chuvas-marcam-clima-de-se\/","title":{"rendered":"Ventos fortes e chuvas marcam clima de SE"},"content":{"rendered":"<div id=\"attachment_69707\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1_news_66_8281e21c5f9a29e18493f48f9148f8d1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69707\" class=\" wp-image-69707    \" alt=\"Foto: Andr\u00e9 Moreira\/ Equipe JC\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/1_news_66_8281e21c5f9a29e18493f48f9148f8d1-1024x680.jpg\" width=\"598\" height=\"397\" \/><\/a><p id=\"caption-attachment-69707\" class=\"wp-caption-text\">Foto: Andr\u00e9 Moreira\/ Equipe JC<\/p><\/div>\n<p style=\"text-align: justify;\">Chuvas e ventos fortes continuam atingir todo o estado nos pr\u00f3ximos dias, segundo o Centro de Meteorologia de Sergipe. Ainda na previs\u00e3o meteorol\u00f3gica, a temperatura m\u00ednima ser\u00e1 de 22\u00ba C no Litoral; 20\u00ba C no agreste; e 18\u00ba C no Sert\u00e3o. No \u00faltimo final semana, chuvas r\u00e1pidas e intensas foram registradas na regi\u00e3o Norte de Aracaju, al\u00e9m dos ventos forte que chegam a 50km\/h na capital e interior.<\/p>\n<p style=\"text-align: justify;\">De acordo com o coordenador do Centro de Meteorologia de Sergipe, Overland Amaral, no decorrer da semana as chuvas ser\u00e3o reduzidas. \u201cO tempo permanece nublado, com chuvas reduzidas durante a semana. Os ventos fortes do sudeste que circulam sob o ar continuam trazendo umidade para a parte continental e promovendo a eleva\u00e7\u00e3o de ondas, que podem chegar a tr\u00eas ou quatro metros em toda a costa sergipana. Hoje, 9, o clima permanece predominantemente nublado, o que deve seguir por toda a semana\u201d, explicou Overland Amaral.<\/p>\n<p style=\"text-align: justify;\">Apesar da grande ventania, nenhuma ocorr\u00eancia foi registrada pela Defesa Civil de Aracaju que permanece em alerta diante da possibilidade de mais chuvas. \u201cN\u00e3o tivemos qualquer registro referente \u00e0s chuvas, pois estas ocorreram rapidamente em toda a cidade, em alguns pontos com maior intensidade, por\u00e9m sem nenhuma consequ\u00eancia grave para a popula\u00e7\u00e3o. Em outras localidades, a chuva foi fina e, portanto, sem causar nenhuma altera\u00e7\u00e3o. Como ainda h\u00e1 previs\u00e3o de chuvas nos pr\u00f3ximos dias, continuaremos em alerta, monitorando as \u00e1reas de, no caso, alguma ocorr\u00eancia, iremos nos dirigir ao local\u201d, afirmou o coordenador geral da Defesa Civil Municipal, coronel Reginaldo Moura.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do Jornal da Cidade.net\u00a0<\/em><br \/>\n<strong><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chuvas e ventos fortes continuam atingir todo o estado nos pr\u00f3ximos dias, segundo o Centro de Meteorologia de Sergipe. Ainda na previs\u00e3o meteorol\u00f3gica, a temperatura m\u00ednima ser\u00e1 de 22\u00ba C no Litoral; 20\u00ba C no agreste; e 18\u00ba C no Sert\u00e3o. No \u00faltimo final semana, chuvas r\u00e1pidas e intensas foram registradas na regi\u00e3o Norte de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-69706","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69706"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=69706"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/69707"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=69706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=69706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=69706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}