{"id":69358,"date":"2014-09-01T14:28:02","date_gmt":"2014-09-01T17:28:02","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=69358"},"modified":"2014-09-02T18:31:03","modified_gmt":"2014-09-02T21:31:03","slug":"uma-pessoa-morre-e-outra-fica-ferida-por-disparos-de-arma-de-fogo-em-ribeiropolis","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/uma-pessoa-morre-e-outra-fica-ferida-por-disparos-de-arma-de-fogo-em-ribeiropolis\/","title":{"rendered":"Uma pessoa morre e outra fica ferida por disparos de arma de fogo em Ribeir\u00f3polis"},"content":{"rendered":"<p style=\"text-align: justify;\">Duas pessoas foram atingidas por disparos de arma de fogo, por volta das 10h da manh\u00e3 desta segunda-feira (1), no munic\u00edpio de Ribeir\u00f3polis, no agreste de Sergipe. Um homem de 44 anos morreu no local e outro ficou ferido.<\/p>\n<div id=\"attachment_69359\" style=\"width: 586px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/dce82c5ab02f12f61c778fe6639e2edd_g.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69359\" class=\" wp-image-69359 \" alt=\"Crime ocorreu pr\u00f3ximo ao cemit\u00e9rio da cidade. (Foto: Reprodu\u00e7\u00e3o\/Itnet)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/dce82c5ab02f12f61c778fe6639e2edd_g.jpg\" width=\"576\" height=\"432\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/dce82c5ab02f12f61c778fe6639e2edd_g.jpg 640w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/dce82c5ab02f12f61c778fe6639e2edd_g-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/dce82c5ab02f12f61c778fe6639e2edd_g-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/dce82c5ab02f12f61c778fe6639e2edd_g-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/dce82c5ab02f12f61c778fe6639e2edd_g-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/dce82c5ab02f12f61c778fe6639e2edd_g-269x201.jpg 269w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><p id=\"caption-attachment-69359\" class=\"wp-caption-text\">Crime ocorreu pr\u00f3ximo ao cemit\u00e9rio da cidade. (Foto: Reprodu\u00e7\u00e3o\/Itnet)<\/p><\/div>\n<p style=\"text-align: justify;\">De acordo com informa\u00e7\u00f5es da Pol\u00edcia Militar, o crime ocorreu nas imedia\u00e7\u00f5es do cemit\u00e9rio municipal. Morreu no local Jerson Barros, de 44 anos, morador do Povoado Queimadas no mesmo munic\u00edpio, e Jos\u00e9 Aduilson dos Santos, de 52 anos, ficou ferido e foi socorrido com vida e encaminhado ao hospital.<\/p>\n<p style=\"text-align: justify;\">Os elementos chegaram ao local efetuaram os disparos e em seguida fugiram para um destino ignorado. Testemunhas n\u00e3o conseguiram identificar os elementos e n\u00e3o souberam informar sobre o ve\u00edculo utilizado na a\u00e7\u00e3o criminosa.<\/p>\n<p style=\"text-align: justify;\">As motiva\u00e7\u00f5es do assassinato e da tentativa ser\u00e3o investigados pela Delegacia de Ribeir\u00f3polis. A ao receber o chamado, a PM se deslocou para o local para preservar a cena do crime.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es da reda\u00e7\u00e3o Itnet\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook\u00a0<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duas pessoas foram atingidas por disparos de arma de fogo, por volta das 10h da manh\u00e3 desta segunda-feira (1), no munic\u00edpio de Ribeir\u00f3polis, no agreste de Sergipe. Um homem de 44 anos morreu no local e outro ficou ferido. De acordo com informa\u00e7\u00f5es da Pol\u00edcia Militar, o crime ocorreu nas imedia\u00e7\u00f5es do cemit\u00e9rio municipal. Morreu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-69358","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69358"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=69358"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/69359"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=69358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=69358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=69358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}