{"id":69337,"date":"2014-09-01T09:49:21","date_gmt":"2014-09-01T12:49:21","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=69337"},"modified":"2014-09-02T08:02:51","modified_gmt":"2014-09-02T11:02:51","slug":"homens-explodem-caixa-eletronico-em-cristinapolis","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/homens-explodem-caixa-eletronico-em-cristinapolis\/","title":{"rendered":"Homens explodem caixa eletr\u00f4nico em Cristin\u00e1polis"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_69339\" style=\"width: 235px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/Banco.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69339\" class=\"size-medium wp-image-69339\" alt=\"ois ve\u00edculos, com cerca de tr\u00eas homens cada, fizeram parte da a\u00e7\u00e3o criminosa.(Foto: JCidade)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/Banco-225x300.jpg\" width=\"225\" height=\"300\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/Banco-225x300.jpg 225w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/Banco-342x455.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/Banco-300x399.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/09\/Banco.jpg 346w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><p id=\"caption-attachment-69339\" class=\"wp-caption-text\">Dois ve\u00edculos, com cerca de tr\u00eas homens cada, fizeram parte da a\u00e7\u00e3o criminosa.(Foto: JCidade)<\/p><\/div>\n<p style=\"text-align: justify;\">Na madrugada desta segunda-feira (1\u00ba), por volta das 3h, um caixa eletr\u00f4nico de uma ag\u00eancia do Banco do Brasil de Cristin\u00e1polis, a 115 km de Aracaju, foi explodido por homens ainda n\u00e3o identificados. Dois ve\u00edculos foram usados na a\u00e7\u00e3o criminosa e a pol\u00edcia j\u00e1 est\u00e1 em busca dos respons\u00e1veis.<\/p>\n<p style=\"text-align: justify;\">De acordo com o sargento Aroldo, um dos dois policiais que estavam na delegacia do munic\u00edpio no momento do ocorrido, testemunhas informaram que, cerca de tr\u00eas homens estavam em cada um dos ve\u00edculos. Uma caminhonete foi utilizada para a fuga ap\u00f3s a explos\u00e3o e um gol preto ficou em frente \u00e0 delegacia para vigiar a movimenta\u00e7\u00e3o policial.<\/p>\n<p style=\"text-align: justify;\">Ainda segundo o sargento, pelo que foi verificado inicialmente, os assaltantes conseguiram levar uma grande quantidade de dinheiro.<\/p>\n<p style=\"text-align: justify;\">Na manh\u00e3 de hoje, a ger\u00eancia do banco esteve no local e equipes da Pol\u00edcia Civil come\u00e7aram a se deslocar para iniciar o processo de investiga\u00e7\u00e3o.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p><em>Informa\u00e7\u00f5es do Jornal da Cidade<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Na madrugada desta segunda-feira (1\u00ba), por volta das 3h, um caixa eletr\u00f4nico de uma ag\u00eancia do Banco do Brasil de Cristin\u00e1polis, a 115 km de Aracaju, foi explodido por homens ainda n\u00e3o identificados. Dois ve\u00edculos foram usados na a\u00e7\u00e3o criminosa e a pol\u00edcia j\u00e1 est\u00e1 em busca dos respons\u00e1veis. De acordo com o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-69337","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69337"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=69337"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/69339"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=69337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=69337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=69337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}