{"id":69264,"date":"2014-08-29T17:34:31","date_gmt":"2014-08-29T20:34:31","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=69264"},"modified":"2014-08-31T15:40:00","modified_gmt":"2014-08-31T18:40:00","slug":"conscientizacao-sobre-fumo-passivo-no-dia-de-combate","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/conscientizacao-sobre-fumo-passivo-no-dia-de-combate\/","title":{"rendered":"Conscientiza\u00e7\u00e3o sobre fumo passivo no Dia de Combate"},"content":{"rendered":"<div id=\"attachment_69265\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/cigarro.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69265\" class=\"size-medium wp-image-69265\" alt=\"O fumo \u00e9 respons\u00e1vel por mais de 200 mil mortes por ano no BR. (Foto: Divulga\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/cigarro-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/cigarro-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/cigarro-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/cigarro-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/cigarro-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/cigarro-269x201.jpg 269w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/cigarro.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-69265\" class=\"wp-caption-text\">O fumo \u00e9 respons\u00e1vel por mais de 200 mil mortes por ano no BR. (Foto: Divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">No Dia Nacional de Combate ao Fumo, comemorado hoje,29, a conscientiza\u00e7\u00e3o sobre os males do fumo passivo ganha for\u00e7a ap\u00f3s pesquisas recentes sobre o tema. Segundo a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), o fumo \u00e9 respons\u00e1vel por mais de 200 mil mortes por ano no Brasil. Doen\u00e7as respirat\u00f3rias e cardiovasculares s\u00e3o as principais enfermidades causadas pelo cigarro e, em muitos casos, as v\u00edtimas sequer s\u00e3o fumantes.<\/p>\n<p style=\"text-align: justify;\">Estudo feito por pesquisadores da Universidade de York, no Reino Unido, e divulgado no m\u00eas passado mostra que part\u00edculas da fuma\u00e7a do tabaco no ambiente podem causar problemas de sa\u00fade e at\u00e9 c\u00e2ncer em n\u00e3o fumantes. As novas constata\u00e7\u00f5es lan\u00e7am luz sobre a quest\u00e3o e demandam campanhas espec\u00edficas sobre o assunto, de acordo com o vice-presidente da Sociedade Brasileira de Medicina de Fam\u00edlia e Comunidade, Daniel Knupp.<\/p>\n<p style=\"text-align: justify;\">\u201cHoje, a imagem geral do fumo na sociedade \u00e9 mais negativa, mesmo os n\u00e3o fumantes t\u00eam conhecimento da dimens\u00e3o do malef\u00edcio do cigarro no conv\u00edvio com o fumante, mas n\u00e3o uma dimens\u00e3o clara da magnitude desse risco\u201d, comentou Knupp. \u201c\u00c9 importante que os n\u00e3o fumantes tenham ci\u00eancia de que a incid\u00eancia de certas doen\u00e7as pode ser t\u00e3o elevada para eles quanto para o pr\u00f3prio fumante e tenham autonomia para cobrar o direito de um ambiente livre de tabaco\u201d, disse o m\u00e9dico.<\/p>\n<p style=\"text-align: justify;\">Para a diretora cl\u00ednica do Centro Paulista de Oncologia (CPO), Mariana Laloni, o que surpreendeu nos dados da pesquisa foi o fato de que mesmo em casas de n\u00e3o fumantes h\u00e1 um grau de subst\u00e2ncias t\u00f3xicas oriundas do cigarro capaz de causar c\u00e2ncer. \u201cJ\u00e1 sabemos que o maior prejudicado \u00e9 o fumante e j\u00e1 h\u00e1 v\u00e1rios estudos que mostram o impacto do efeito do tabaco para o fumante passivo no mesmo ambiente [do fumante]. Mas esse estudo mostra que a fuma\u00e7a exalada dos fumantes persiste no ambiente e aumenta o risco de doen\u00e7as para n\u00e3o fumantes\u201d, comentou Mariana.<\/p>\n<p style=\"text-align: justify;\">Uma divulga\u00e7\u00e3o maior de informa\u00e7\u00f5es sobre o assunto, segundo ela, pode contribuir para uma atitude mais respons\u00e1vel por parte de fumantes em locais p\u00fablicos e privados.<\/p>\n<p style=\"text-align: justify;\">A coordenadora de Vigil\u00e2ncia de Agravo e de Doen\u00e7as n\u00e3o Transmiss\u00edveis e Promo\u00e7\u00e3o da Sa\u00fade do Minist\u00e9rio da Sa\u00fade, Deborah Malta, explicou que as a\u00e7\u00f5es em curso para inibir o fumo em locais fechados t\u00eam obtido resultados significativos na queda da preval\u00eancia do fumo passivo.<\/p>\n<p style=\"text-align: justify;\">\u201cJ\u00e1 verificamos uma redu\u00e7\u00e3o do fumo passivo no domic\u00edlio, de 12,7% [em 2009] para 10,2% [em 2012]. No local de trabalho, caiu de 12,1% para 9,8%\u201d, acrescentou. Os dados s\u00e3o do estudo Vigil\u00e2ncia de Fatores de Risco e Prote\u00e7\u00e3o para Doen\u00e7as Cr\u00f4nicas por Inqu\u00e9rito Telef\u00f4nico (Vigitel) 2013.<\/p>\n<p style=\"text-align: justify;\">A regulamenta\u00e7\u00e3o da Lei Antifumo Nacional, cujas regras passam a valer a partir de 2 de dezembro, ter\u00e1 impacto ainda maior na queda do n\u00famero de n\u00e3o fumantes, que hoje s\u00e3o obrigados a inalar fuma\u00e7a de cigarro. Entre os pontos mais relevantes est\u00e1 a proibi\u00e7\u00e3o do fumo em locais de uso coletivo, p\u00fablicos ou privados (como hall e corredores de condom\u00ednio, restaurantes e clubes, mesmo que o ambiente esteja s\u00f3 parcialmente fechado por uma parede, divis\u00f3ria, teto ou at\u00e9 toldo). A norma tamb\u00e9m extingue os fum\u00f3dromos e acaba com a possibilidade de propaganda comercial de cigarros at\u00e9 mesmo nos pontos de venda.<\/p>\n<p style=\"text-align: justify;\">\u201cAl\u00e9m disso, o decreto prev\u00ea que o espa\u00e7o de advert\u00eancia nos ma\u00e7os seja ampliado em 30%. J\u00e1 temos 100% no espa\u00e7o frontal, 100% na lateral e ap\u00f3s 2015 teremos mais 30% no espa\u00e7o dos ma\u00e7os\u201d, lembrou Deborah.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ag\u00eancia Brasil<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No Dia Nacional de Combate ao Fumo, comemorado hoje,29, a conscientiza\u00e7\u00e3o sobre os males do fumo passivo ganha for\u00e7a ap\u00f3s pesquisas recentes sobre o tema. Segundo a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), o fumo \u00e9 respons\u00e1vel por mais de 200 mil mortes por ano no Brasil. Doen\u00e7as respirat\u00f3rias e cardiovasculares s\u00e3o as principais enfermidades causadas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69265,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310],"tags":[],"class_list":{"0":"post-69264","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69264"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=69264"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/69264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/69265"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=69264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=69264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=69264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}