{"id":68548,"date":"2014-08-15T08:00:16","date_gmt":"2014-08-15T11:00:16","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=68548"},"modified":"2014-08-16T13:04:49","modified_gmt":"2014-08-16T16:04:49","slug":"bell-marques-tem-guitarra-extraviada-pela-american-airlines-e-pede-ajuda-aos-seguidores","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/bell-marques-tem-guitarra-extraviada-pela-american-airlines-e-pede-ajuda-aos-seguidores\/","title":{"rendered":"Bell Marques tem guitarra extraviada pela American Airlines e pede ajuda aos seguidores"},"content":{"rendered":"<p>por Rafael Albuquerque, do Bahia Not\u00edcias<\/p>\n<div id=\"attachment_68549\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/bel.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-68549\" class=\"size-medium wp-image-68549\" alt=\"Bel pede ajuda aos seguidores. (Divulga\u00e7\u00e3o\/Bahia Not\u00edcias)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/bel-300x221.jpg\" width=\"300\" height=\"221\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/bel-300x221.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/bel-342x252.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/bel-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/bel-90x65.jpg 90w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/bel.jpg 380w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-68549\" class=\"wp-caption-text\">Bel pede ajuda aos seguidores. (Divulga\u00e7\u00e3o\/Bahia Not\u00edcias)<\/p><\/div>\n<p style=\"text-align: justify;\">O cantor Bell Marques n\u00e3o teve uma experi\u00eancia muito agrad\u00e1vel ap\u00f3s voo pela American Airlines. O artista voltou Nova Iorque com a fam\u00edlia e n\u00e3o recebeu a bagagem e a guitarra nova que estava trazendo. &#8220;Por falar em guitarra nova, ela tamb\u00e9m foi extraviada pela American Ariline, v\u00ea se pode.<\/p>\n<p style=\"text-align: justify;\">Toda a bagagem da minha fam\u00edlia foi extraviada&#8221;. Bell, que se apresenta neste s\u00e1bado (16) no Ax\u00e9 Brasil, avisou aos f\u00e3s que queria mostrar a guitarra nova, mas n\u00e3o poder\u00e1. Bell at\u00e9 pediu \u00a0ajuda para os seguidores retuitarem a mensagem em que cita a empresa e avisa: &#8220;Caramba, se eu chegar no Ax\u00e9 Brasil sem minha guitarra a @americanAirBR vai voar\u201d. Depois de passar esta quarta-feira (13) reclamando, o ex-vocalista do Chiclete resolveu tentar solucionar o problema atrav\u00e9s do Facebook da companhia a\u00e9rea.<\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta pelo <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Rafael Albuquerque, do Bahia Not\u00edcias O cantor Bell Marques n\u00e3o teve uma experi\u00eancia muito agrad\u00e1vel ap\u00f3s voo pela American Airlines. O artista voltou Nova Iorque com a fam\u00edlia e n\u00e3o recebeu a bagagem e a guitarra nova que estava trazendo. &#8220;Por falar em guitarra nova, ela tamb\u00e9m foi extraviada pela American Ariline, v\u00ea se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,22],"tags":[],"class_list":{"0":"post-68548","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-famosos"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68548"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=68548"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/68549"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=68548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=68548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=68548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}