{"id":68252,"date":"2014-08-09T06:37:27","date_gmt":"2014-08-09T09:37:27","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=68252"},"modified":"2014-08-09T06:47:33","modified_gmt":"2014-08-09T09:47:33","slug":"carreata-na-regiao-sul-marca-inicio-da-campanha-de-dilma-em-sergipe","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/carreata-na-regiao-sul-marca-inicio-da-campanha-de-dilma-em-sergipe\/","title":{"rendered":"Carreata na regi\u00e3o Sul marca in\u00edcio da campanha de Dilma em Sergipe"},"content":{"rendered":"<div id=\"attachment_56827\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/eliane1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56827\" class=\"size-full wp-image-56827\" alt=\"A ex-secret\u00e1ria Eliane Aquino coordena a campanha de Dilma em Sergipe.  (Foto de arquivo: Fl\u00e1vio Antunes\/G1)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/eliane1.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/eliane1.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/eliane1-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/eliane1-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/eliane1-269x201.jpg 269w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-56827\" class=\"wp-caption-text\">A ex-secret\u00e1ria Eliane Aquino coordena a campanha de Dilma em Sergipe. (Foto de arquivo: Fl\u00e1vio Antunes\/G1)<\/p><\/div>\n<p style=\"text-align: justify;\">Neste s\u00e1bado, 09, ser\u00e1 dada a largada oficial da campanha pela reelei\u00e7\u00e3o da Presidenta Dilma Rousseff em Sergipe. O primeiro ato ser\u00e1 uma carreata, com concentra\u00e7\u00e3o \u00e0s 9h, no bairro Cidade Nova, em Est\u00e2ncia. De l\u00e1, a mobiliza\u00e7\u00e3o tamb\u00e9m ir\u00e1 percorrer os munic\u00edpios de Santa Luzia do Itanhy e Indiaroba.<\/p>\n<p style=\"text-align: justify;\">Em todo o pa\u00eds, o s\u00e1bado ser\u00e1 marcado por diversos atos de apoio aos governos que v\u00eam mudando o Brasil nos \u00faltimos 12 anos e que ainda podem Mudar Mais! Em Sergipe, a carreata contar\u00e1 com a presen\u00e7a do Governador Jackson Barreto, candidato \u00e0 reelei\u00e7\u00e3o, da coordenadora estadual da Campanha da Presidenta Dilma, a ex-primeira dama Eliane Aquino, al\u00e9m de diversas lideran\u00e7as e candidatos da base aliada.<\/p>\n<p style=\"text-align: justify;\">\u201cGostaria de convidar a todos os sergipanos para, juntos, mostrarmos que queremos continuar no rumo certo, apoiando aqueles que j\u00e1 mostraram seu compromisso com a transforma\u00e7\u00e3o social da vida do nosso povo. N\u00e3o podemos retroceder\u201d, enfatizou Eliane Aquino.<\/p>\n<p style=\"text-align: justify;\"><strong>Agenda<\/strong> \u2013 A pr\u00f3xima semana ser\u00e1 marcada por uma s\u00e9rie de a\u00e7\u00f5es voltadas \u00e0 participa\u00e7\u00e3o social e envolvimento da popula\u00e7\u00e3o na campanha dos majorit\u00e1rios. Na ter\u00e7a-feira, 12, haver\u00e1 um grande ato com a juventude sergipana, com concentra\u00e7\u00e3o a partir das 16h na Pra\u00e7a do Farol, localizada pr\u00f3ximo \u00e0 Universidade Tiradentes, no bairro Farol\u00e2ndia, em Aracaju. De l\u00e1, o grupo segue em caminhada em dire\u00e7\u00e3o \u00e0 Pra\u00e7a da Juventude, no Conjunto Augusto Franco.<br \/>\nJ\u00e1 na quarta-feira, dia 13, haver\u00e1 uma caminhada envolvendo as mulheres sergipanas, com concentra\u00e7\u00e3o \u00e0s 11h, na Pra\u00e7a da Bandeira seguindo at\u00e9 o Cal\u00e7ad\u00e3o da Jo\u00e3o Pessoa, Centro de Aracaju.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Da Assessoria de Imprensa<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado, 09, ser\u00e1 dada a largada oficial da campanha pela reelei\u00e7\u00e3o da Presidenta Dilma Rousseff em Sergipe. O primeiro ato ser\u00e1 uma carreata, com concentra\u00e7\u00e3o \u00e0s 9h, no bairro Cidade Nova, em Est\u00e2ncia. De l\u00e1, a mobiliza\u00e7\u00e3o tamb\u00e9m ir\u00e1 percorrer os munic\u00edpios de Santa Luzia do Itanhy e Indiaroba. Em todo o pa\u00eds, o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-68252","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68252"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=68252"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/64733"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=68252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=68252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=68252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}