{"id":68234,"date":"2014-08-08T15:56:28","date_gmt":"2014-08-08T18:56:28","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=68234"},"modified":"2014-08-08T15:57:16","modified_gmt":"2014-08-08T18:57:16","slug":"tce-rejeita-contas-de-umbauba-do-ano-2010-pelo-gasto-excessivo-com-pessoal","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tce-rejeita-contas-de-umbauba-do-ano-2010-pelo-gasto-excessivo-com-pessoal\/","title":{"rendered":"TCE rejeita contas de Umba\u00faba do ano 2010 pelo gasto excessivo com pessoal"},"content":{"rendered":"<div id=\"attachment_68235\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/512b4d69d27bd2b0593a0cf0276e6e57.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-68235\" class=\"size-medium wp-image-68235\" alt=\" O conselheiro-relator, Ulices Andrade (Foto: Cleverton Ribeiro)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/512b4d69d27bd2b0593a0cf0276e6e57-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/512b4d69d27bd2b0593a0cf0276e6e57-300x200.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/512b4d69d27bd2b0593a0cf0276e6e57-342x228.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/512b4d69d27bd2b0593a0cf0276e6e57.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-68235\" class=\"wp-caption-text\"><br \/>O conselheiro-relator, Ulices Andrade (Foto: Cleverton Ribeiro)<\/p><\/div>\n<p style=\"text-align: justify;\">O gasto excessivo com Pessoal foi um dos fatores que levaram o Tribunal de Contas do Estado (TCE\/SE) a emitir parecer pr\u00e9vio pela rejei\u00e7\u00e3o das Contas Anuais da Prefeitura de Umba\u00faba, referentes ao exerc\u00edcio 2010, de interesse do ex-prefeito Anderson Fontes Farias. O processo relatado pelo conselheiro Ulices Andrade foi julgado na sess\u00e3o plen\u00e1ria da \u00faltima quinta-feira (7).<\/p>\n<p style=\"text-align: justify;\">Conforme o relat\u00f3rio apresentado ao colegiado, no exerc\u00edcio financeiro de 2010 a Prefeitura de Umba\u00faba gastou com pessoal o percentual de 61,75%, extrapolando o limite de 54% estabelecido pela Lei de Responsabilidade Fiscal (LRF). No mesmo per\u00edodo, foi constatada ainda a aplica\u00e7\u00e3o do percentual de 21,14% na Manuten\u00e7\u00e3o e Desenvolvimento do Ensino (MDE), abaixo do limite de 25%.<\/p>\n<p style=\"text-align: justify;\">De acordo com a equipe t\u00e9cnica do Tribunal, outras falhas n\u00e3o sanadas pela defesa do gestor foram a inexist\u00eancia de Audi\u00eancia P\u00fablica no processo de elabora\u00e7\u00e3o das Leis Or\u00e7ament\u00e1rias; a aus\u00eancia de documenta\u00e7\u00e3o completa acerca de despesas realizadas com publicidade, festas e eventos; e a n\u00e3o comprova\u00e7\u00e3o da exist\u00eancia de medidas adotadas com rela\u00e7\u00e3o \u00e0 acessibilidade.<\/p>\n<p style=\"text-align: justify;\">A decis\u00e3o un\u00e2nime do colegiado seguiu ainda o entendimento do Minist\u00e9rio P\u00fablico de Contas, que atrav\u00e9s de parecer do procurador Carlos Waldemar Resende Machado tamb\u00e9m se posicionou pela emiss\u00e3o de parecer pr\u00e9vio recomendando a rejei\u00e7\u00e3o das contas anuais.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: TCE\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> \u00a0e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook\u00a0<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O gasto excessivo com Pessoal foi um dos fatores que levaram o Tribunal de Contas do Estado (TCE\/SE) a emitir parecer pr\u00e9vio pela rejei\u00e7\u00e3o das Contas Anuais da Prefeitura de Umba\u00faba, referentes ao exerc\u00edcio 2010, de interesse do ex-prefeito Anderson Fontes Farias. O processo relatado pelo conselheiro Ulices Andrade foi julgado na sess\u00e3o plen\u00e1ria da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-68234","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68234"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=68234"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/68235"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=68234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=68234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=68234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}