{"id":68226,"date":"2014-08-08T15:29:07","date_gmt":"2014-08-08T18:29:07","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=68226"},"modified":"2014-08-10T20:04:29","modified_gmt":"2014-08-10T23:04:29","slug":"liminar-determina-que-prefeitura-de-sao-cristovao-adeque-estruturas-dos-conselhos-tutelaresliminar-determina-que-prefeitura-de-sao-cristovao-adeque-estruturas-dos-conselhos-tutelares","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/liminar-determina-que-prefeitura-de-sao-cristovao-adeque-estruturas-dos-conselhos-tutelaresliminar-determina-que-prefeitura-de-sao-cristovao-adeque-estruturas-dos-conselhos-tutelares\/","title":{"rendered":"Juiz determina que prefeitura de S\u00e3o Crist\u00f3v\u00e3o adeque estruturas dos Conselhos Tutelares"},"content":{"rendered":"<div id=\"attachment_52837\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/09\/JRR-0004.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-52837\" class=\"size-medium wp-image-52837\" alt=\" Prefeita poder\u00e1 pagar multa di\u00e1ria, de R$ 300,00(trezentos reais), por dia em caso de de descumprimento da decis\u00e3o. (Foto de arquivo: J\u00fanior Ramalho - Ascom\/PMSC)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/09\/JRR-0004-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/09\/JRR-0004-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/09\/JRR-0004-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/09\/JRR-0004.jpg 540w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-52837\" class=\"wp-caption-text\"><br \/>Prefeita poder\u00e1 pagar multa di\u00e1ria, de R$ 300,00(trezentos reais), por dia em caso de de descumprimento da decis\u00e3o. (Foto de arquivo: J\u00fanior Ramalho &#8211; Ascom\/PMSC)<\/p><\/div>\n<p style=\"text-align: justify;\">Em atendimento a A\u00e7\u00e3o Civil P\u00fablica, ingressada pelo Minist\u00e9rio P\u00fablico, o Juiz da Vara C\u00edvel da Comarca de S\u00e3o Crist\u00f3v\u00e3o, Manoel Costa Neto, determinou, em medida liminar, que o Munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o adeque as estruturas f\u00edsicas e de pessoal e com ferramentas m\u00ednimas de trabalho, os dois Distritos do Conselho Tutelar que atendem \u00e0s crian\u00e7as e adolescentes naquele munic\u00edpio.<\/p>\n<p style=\"text-align: justify;\">Dentre as medidas a serem adotadas, o magistrado determinou que a Prefeitura coloque \u00e0 disposi\u00e7\u00e3o exclusiva dos Conselhos Tutelares, servidores p\u00fablicos para exercerem atividades de secretaria, servi\u00e7os gerais de limpeza e de vigil\u00e2ncia; disponibilize pr\u00e9dios adequados, acess\u00edveis \u00e0s pessoas com defici\u00eancia, bem como constitua uma recep\u00e7\u00e3o e 03 salas, devidamente mobiliadas, com todos os equipamentos de inform\u00e1tica necess\u00e1rios e acesso \u00e0 internet; ceda mensalmente, todo o material de expediente e de limpeza que os Conselhos Tutelares necessitam; e coloque \u00e0 disposi\u00e7\u00e3o de cada Conselho, telefones fixo e celular, sem restri\u00e7\u00e3o de valores, monitorando mensalmente as liga\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">De acordo com o Juiz sentenciante, S\u00e3o Crist\u00f3v\u00e3o possui Conselheiros atuantes e comprometidos com a causa da crian\u00e7a, os quais necessitam de infra-estrutura para prestar suas atividades. \u201cUm estabelecimento com condi\u00e7\u00f5es insalubres, sem um local para uma entrevista reservada com crian\u00e7as, adolescentes e seus pais, sem pessoal de apoio, obrigando os Conselheiros a executar servi\u00e7os fora de sua esfera de atividade, sem material de expediente, sem material de limpeza adequado, sem telefone, sem computador, sem impressora, etc., enfim, manter Distritos de Conselhos Tutelares sem condi\u00e7\u00f5es de trabalho \u00e9 o mesmo que n\u00e3o possuir, representando apenas uma fachada de profundo mau gosto\u201d.<\/p>\n<p style=\"text-align: justify;\">Ainda, segundo o magistrado, o munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o deve fornecer, imediatamente, \u201cas m\u00ednimas condi\u00e7\u00f5es de trabalho para os Conselheiros Tutelares, que est\u00e3o trabalhando a muito sacrif\u00edcio, bem como fazer constar em sua Lei Or\u00e7ament\u00e1ria a previs\u00e3o de recursos necess\u00e1rios ao funcionamento do Conselho Tutelar\u201d, desempenhando, assim, sua miss\u00e3o de efetivar os direitos da crian\u00e7a e do adolescente garantidos pela Constitui\u00e7\u00e3o de 1988 com absoluta prioridade.<\/p>\n<p style=\"text-align: justify;\">\u201cFixo, multa di\u00e1ria, no quantum de R$ 300,00(trezentos reais), por dia de descumprimento, direta e pessoalmente \u00e0 Senhora Prefeita Municipal, a ser revertida em favor do Fundo Municipal dos Direitos da Crian\u00e7a e do Adolescente, sem preju\u00edzo do enquadramento no Crime de Desobedi\u00eancia\u201d.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p><em><strong>Da Assessoria de Imprensa TJ\/SE<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em atendimento a A\u00e7\u00e3o Civil P\u00fablica, ingressada pelo Minist\u00e9rio P\u00fablico, o Juiz da Vara C\u00edvel da Comarca de S\u00e3o Crist\u00f3v\u00e3o, Manoel Costa Neto, determinou, em medida liminar, que o Munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o adeque as estruturas f\u00edsicas e de pessoal e com ferramentas m\u00ednimas de trabalho, os dois Distritos do Conselho Tutelar que atendem \u00e0s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,6],"tags":[],"class_list":{"0":"post-68226","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68226"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=68226"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/52837"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=68226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=68226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=68226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}