{"id":68213,"date":"2014-08-08T12:11:17","date_gmt":"2014-08-08T15:11:17","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=68213"},"modified":"2014-08-09T14:08:41","modified_gmt":"2014-08-09T17:08:41","slug":"epidemia-de-ebola-e-emergencia-de-saude-publica-mundial-diz-oms","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/epidemia-de-ebola-e-emergencia-de-saude-publica-mundial-diz-oms\/","title":{"rendered":"Epidemia de ebola \u00e9 emerg\u00eancia de sa\u00fade p\u00fablica mundial, diz OMS"},"content":{"rendered":"<div id=\"attachment_68214\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/ebola-guine.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-68214\" class=\"size-medium wp-image-68214\" alt=\"A epidemia de ebola, que j\u00e1 causou a morte de cerca de mil pessoas desde o in\u00edcio do ano. (Foto: Reprodu\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/ebola-guine-300x203.jpg\" width=\"300\" height=\"203\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/ebola-guine-300x203.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/ebola-guine-342x231.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/ebola-guine.jpg 575w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-68214\" class=\"wp-caption-text\">A epidemia de ebola j\u00e1 causou a morte de cerca de mil pessoas desde o in\u00edcio do ano. (Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) decretou hoje,8, que a epidemia de febre hemorr\u00e1gica pelo v\u00edrus ebola, registrada em pelo menos quatro pa\u00edses da \u00c1frica Ocidental, \u00e9 emerg\u00eancia de sa\u00fade p\u00fablica de alcance mundial. &#8220;A OMS aceitou as conclus\u00f5es&#8221; da Comiss\u00e3o de Emerg\u00eancia Sanit\u00e1ria, que esteve reunida quarta,6, e quinta-feira desta semana em Genebra, informou a diretora-geral da organiza\u00e7\u00e3o, Margaret Chan. Segundo ela, a comiss\u00e3o foi un\u00e2nime em considerar que se verificam as condi\u00e7\u00f5es de uma emerg\u00eancia de sa\u00fade p\u00fablica de alcance mundial. Diante de uma situa\u00e7\u00e3o que continua a agravar-se, \u00e9 necess\u00e1ria uma resposta internacional coordenada para &#8220;travar e fazer recuar a propaga\u00e7\u00e3o internacional do ebola&#8221;, acrescentou.<\/p>\n<p style=\"text-align: justify;\">A epidemia de ebola, que j\u00e1 causou a morte de cerca de mil pessoas desde o in\u00edcio do ano, com mais de 1.700 casos suspeitos, \u00e9 a mais mais grave das \u00faltimas quatro d\u00e9cadas, destacou Chan. Ela disse que os pa\u00edses da \u00c1frica Ocidental mais atingidos &#8211; Lib\u00e9ria, Serra Leoa, Guin\u00e9-Conacri e Nig\u00e9ria &#8211; n\u00e3o t\u00eam meios para responder sozinhos \u00e0 doen\u00e7a e pediu \u00e0 comunidade internacional que forne\u00e7a o apoio necess\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">A comiss\u00e3o alertou que os Estados devem estar preparados para detectar e tratar casos de ebola, al\u00e9m de facilitar a retirada de cidad\u00e3os, em particular pessoal m\u00e9dico, que estiveram expostos ao v\u00edrus da febre hemorr\u00e1gica. A comiss\u00e3o lembrou que os chefes de Estado dos pa\u00edses afetados devem &#8220;decretar estado de emerg\u00eancia&#8221; e &#8220;dirigir-se pessoalmente \u00e0 na\u00e7\u00e3o para fornecer informa\u00e7\u00f5es sobre a situa\u00e7\u00e3o&#8221;.<\/p>\n<p style=\"text-align: justify;\">O respons\u00e1vel da OMS para a epidemia, Keiji Fukuda, adjunto de Margaret Chan, disse que a quarentena de pessoas suspeitas de infec\u00e7\u00e3o deve ser 30 dias, j\u00e1 que o tempo de incuba\u00e7\u00e3o \u00e9 21 dias. As pessoas que estiveram em contato com os doentes, \u00e0 exce\u00e7\u00e3o do pessoal m\u00e9dico equipado com roupa protetora, n\u00e3o devem ser autorizadas a viajar.<\/p>\n<p style=\"text-align: justify;\">Keiji Fukuda lembrou ainda que as tripula\u00e7\u00f5es de voos comerciais, que se desloquem a pa\u00edses afetados, devem receber forma\u00e7\u00e3o espec\u00edfica e material m\u00e9dico para prote\u00e7\u00e3o pessoal e dos passageiros. &#8220;Impedir as companhias a\u00e9reas de viajar para esses pa\u00edses iria afetar a sua economia&#8221;, observou Chan.<\/p>\n<p style=\"text-align: justify;\">A comiss\u00e3o recomendou tamb\u00e9m que todas as pessoas que saiam de pa\u00edses afetados sejam examinadas nos aeroportos, portos e principais postos fronteiri\u00e7os, mediante um question\u00e1rio e medi\u00e7\u00e3o da temperatura, devendo ser impedidos de viajar quaisquer casos suspeitos.<\/p>\n<p style=\"text-align: justify;\">O v\u00edrus j\u00e1 causou pelo menos 932 mortos e infectou mais de 1.700 pessoas desde que surgiu, no in\u00edcio do ano, na Guin\u00e9-Conacri, de acordo com a OMS. A Lib\u00e9ria, a Guin\u00e9-Conacri e Serra Leoa decretaram estado de emerg\u00eancia. O v\u00edrus do ebola \u00e9 transmitido por contato direto com o sangue, l\u00edquidos ou tecidos de pessoas ou animais infectados. A febre manifesta-se por meio de hemorragias, v\u00f4mitos e diarreias. A taxa de mortalidade varia entre 25% e 90% e n\u00e3o \u00e9 conhecida uma vacina contra a doen\u00e7a. O v\u00edrus foi detectado pela primeira vez em 1976 na Rep\u00fablica Democr\u00e1tica do Congo.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ag\u00eancia Brasil<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> \u00a0e curta pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook\u00a0<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) decretou hoje,8, que a epidemia de febre hemorr\u00e1gica pelo v\u00edrus ebola, registrada em pelo menos quatro pa\u00edses da \u00c1frica Ocidental, \u00e9 emerg\u00eancia de sa\u00fade p\u00fablica de alcance mundial. &#8220;A OMS aceitou as conclus\u00f5es&#8221; da Comiss\u00e3o de Emerg\u00eancia Sanit\u00e1ria, que esteve reunida quarta,6, e quinta-feira desta semana em Genebra, informou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,6],"tags":[],"class_list":{"0":"post-68213","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68213"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=68213"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/68214"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=68213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=68213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=68213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}