{"id":68102,"date":"2014-08-06T16:21:58","date_gmt":"2014-08-06T19:21:58","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=68102"},"modified":"2014-08-06T16:41:27","modified_gmt":"2014-08-06T19:41:27","slug":"audiencia-no-mpe-discute-melhorias-na-organizacao-das-torcidas-no-futebol-sergipano","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/audiencia-no-mpe-discute-melhorias-na-organizacao-das-torcidas-no-futebol-sergipano\/","title":{"rendered":"Audi\u00eancia no MPE discute melhorias na organiza\u00e7\u00e3o das torcidas no Futebol Sergipano"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div style=\"text-align: justify;\">\n<div id=\"attachment_40292\" style=\"width: 289px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/10\/MPE.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-40292\" class=\"size-full wp-image-40292\" alt=\"Audi\u00eancia no MP discute melhorias na organiza\u00e7\u00e3o das torcidas\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/10\/MPE.jpg\" width=\"279\" height=\"181\" \/><\/a><p id=\"caption-attachment-40292\" class=\"wp-caption-text\">Audi\u00eancia no MP discute melhorias na organiza\u00e7\u00e3o das torcidas<\/p><\/div>\n<p>No \u00faltimo dia 05 de agosto, a Promotora de Justi\u00e7a do 3\u00ba Setor, Dra. Maria Helena Sanches Lisboa Vinhas reuniu-se com o Presidente da Federa\u00e7\u00e3o Sergipana de Futebol, com o Diretor do Clube Esportivo Sergipe e com representantes da Diretoria de diversas Torcidas Organizadas de Sergipe. Pauta da reuni\u00e3o: discutir melhorias na organiza\u00e7\u00e3o do futebol Sergipano, em especial \u00e1s torcidas organizadas.<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Desde o surgimento da primeira Torcida Organizada, em 1969, a atua\u00e7\u00e3o dessas associa\u00e7\u00f5es recrudesce a cada ano. Hinos, uniformes, bandeiras e mascotes s\u00e3o utilizados pelos seus membros para incentivar o seu time nos gramados, bem como para criar uma identidade entre aqueles associados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span>Apesar do car\u00e1ter pac\u00edfico e idealizador do surgimento desses grupos, nos \u00faltimos anos foi vista uma crescente onda de brigas e tumultos nos est\u00e1dios e nas suas imedia\u00e7\u00f5es, iniciadas em grande parte por essas associa\u00e7\u00f5es de torcedores. As brigas n\u00e3o se limitam \u00e0 rivalidade entre clubes, como muitos pensam, mas ocorrem tamb\u00e9m entre membros das torcidas organizadas de um mesmo time, que fizeram da arquibancada uma disputa de territ\u00f3rio.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201c<span>Diante dessa realidade, questiona-se intensamente a responsabilidade de cada parte envolvida em um evento esportivo (clubes e torcida), pela seguran\u00e7a dentro dos est\u00e1dios e nos seus arredores. Como j\u00e1 bem pacificada a quest\u00e3o relativa \u00e0 responsabilidade das diretorias dos times, mais importante que se fa\u00e7a uma an\u00e1lise da responsabiliza\u00e7\u00e3o das torcidas organizadas\u201d, explicou a Promotora de Justi\u00e7a.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">Todos os presentes foram un\u00e2nimes em colaborar com o Minist\u00e9rio P\u00fablico, a fim de acabar com a viol\u00eancia nos est\u00e1dios e fazer valer o Estatuto do Torcedor, que dedica-se a normatiza\u00e7\u00e3o das atividades desportivas no Brasil.<\/p>\n<p style=\"text-align: justify;\">Ficou comprovado que as Torcidas Organizadas em Sergipe, na sua maioria, n\u00e3o possuem Estatuto Social devidamente registrado em cart\u00f3rio e, por conta disso, Dra. Maria Helena Sanches estipulou um prazo de 60 (sessenta) dias, para que as associa\u00e7\u00f5es apresentem os seguintes documentos: Estatuto Social registrado; Ata de posse e elei\u00e7\u00e3o da diretoria e nome e endere\u00e7o dos respectivos membros e rela\u00e7\u00e3o com nome, endere\u00e7o e telefone dos associados de cada torcida.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por M\u00f4nica Ribeiro<br \/>\nAssessora de Imprensa MP\/SE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; No \u00faltimo dia 05 de agosto, a Promotora de Justi\u00e7a do 3\u00ba Setor, Dra. Maria Helena Sanches Lisboa Vinhas reuniu-se com o Presidente da Federa\u00e7\u00e3o Sergipana de Futebol, com o Diretor do Clube Esportivo Sergipe e com representantes da Diretoria de diversas Torcidas Organizadas de Sergipe. Pauta da reuni\u00e3o: discutir melhorias na organiza\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,1,8],"tags":[],"class_list":{"0":"post-68102","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-esporte","8":"category-sem-categoria","9":"category-esporte-e-cultura"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68102"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=68102"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/68102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/40292"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=68102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=68102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=68102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}