{"id":67989,"date":"2014-08-04T17:16:08","date_gmt":"2014-08-04T20:16:08","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=67989"},"modified":"2014-08-04T17:20:53","modified_gmt":"2014-08-04T20:20:53","slug":"policia-prende-acusado-do-assassinato-de-idosa-em-areia-branca","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/policia-prende-acusado-do-assassinato-de-idosa-em-areia-branca\/","title":{"rendered":"Pol\u00edcia prende acusado do assassinato de idosa em Areia Branca"},"content":{"rendered":"<p><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_67992\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/preso.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-67992\" class=\"size-medium wp-image-67992\" alt=\"Jos\u00e9 Augusto de Assis, conhecido por \u201cGarrafinha\u201d, acusado de crime de homic\u00eddio. (SSP\/SE)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/preso-300x231.jpg\" width=\"300\" height=\"231\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/preso-300x231.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/preso-342x263.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/preso-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/preso.jpg 590w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-67992\" class=\"wp-caption-text\">Jos\u00e9 Augusto de Assis, conhecido por \u201cGarrafinha\u201d, acusado de crime de homic\u00eddio. (SSP\/SE)<\/p><\/div>\n<p style=\"text-align: justify;\">Policiais civis lotados na coordenadoria da Pol\u00edcia Civil do Interior (Copci), coordenados pelo delegado Dernival Eloi, prenderam no in\u00edcio da tarde na \u00faltima sexta-feira, 1\u00ba, em cumprimento a mandado de pris\u00e3o Jos\u00e9 Augusto de Assis, conhecido por \u201cGarrafinha\u201d, acusado de crime de homic\u00eddio.<\/p>\n<p style=\"text-align: justify;\">De acordo com o delegado, o mandado de pris\u00e3o preventiva foi expedido pelo Ju\u00edzo de Direito da Comarca da cidade de Areia Branca. Garrafinha \u00e9 acusado de matar\u00a0a idosa Maria de Lourdes Silva, de 76 anos de idade, no dia 25 de mar\u00e7o deste ano. \u201cO acusado morava de aluguel em um im\u00f3vel da v\u00edtima e o crime ocorreu por ocasi\u00e3o de uma cobran\u00e7a do valor do aluguel. Ele se irritou e matou a v\u00edtima mediante pauladas e ap\u00f3s o crime transportou o corpo da v\u00edtima em um carrinho de m\u00e3o e colocou embaixo de um \u00f4nibus na tentativa de criar uma cena de atropelamento\u201d,\u00a0ressaltou o delegado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Os policiais prenderam o homicida quando ele\u00a0estava na sua\u00a0resid\u00eancia, situada na sede do munic\u00edpio de Areia Branca. \u201cA delegada Lauana Guedes, respons\u00e1vel pelas investiga\u00e7\u00f5es, de imediato, desconfiou da vers\u00e3o apresentada por Garrafinha sobre o suposto atropelamento, e assim deu in\u00edcio as investiga\u00e7\u00f5es. Ele se encontra em uma das delegacias Metropolitanas aguardando transfer\u00eancia para o sistema prisional\u201d, concluiu o delegado Dernival Eloi.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Assessoria de Comunica\u00e7\u00e3o<br \/>\nSecretaria da Seguran\u00e7a P\u00fablica<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 &nbsp; Policiais civis lotados na coordenadoria da Pol\u00edcia Civil do Interior (Copci), coordenados pelo delegado Dernival Eloi, prenderam no in\u00edcio da tarde na \u00faltima sexta-feira, 1\u00ba, em cumprimento a mandado de pris\u00e3o Jos\u00e9 Augusto de Assis, conhecido por \u201cGarrafinha\u201d, acusado de crime de homic\u00eddio. De acordo com o delegado, o mandado de pris\u00e3o preventiva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1],"tags":[],"class_list":{"0":"post-67989","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67989"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=67989"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/67992"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=67989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=67989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=67989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}