{"id":67958,"date":"2014-08-04T14:00:31","date_gmt":"2014-08-04T17:00:31","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=67958"},"modified":"2014-08-04T14:01:53","modified_gmt":"2014-08-04T17:01:53","slug":"portaria-assegura-beneficio-a-trabalhadores-portuarios-sem-vinculo-trabalhista","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/portaria-assegura-beneficio-a-trabalhadores-portuarios-sem-vinculo-trabalhista\/","title":{"rendered":"Portaria assegura benef\u00edcio a trabalhadores portu\u00e1rios sem v\u00ednculo trabalhista"},"content":{"rendered":"<div id=\"attachment_59253\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/01\/Carteira-de-trabalho-20-12-07-567x340.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-59253\" class=\"size-medium wp-image-59253\" alt=\" (Foto: Reprodu\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/01\/Carteira-de-trabalho-20-12-07-567x340-300x179.jpg\" width=\"300\" height=\"179\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/01\/Carteira-de-trabalho-20-12-07-567x340-300x179.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/01\/Carteira-de-trabalho-20-12-07-567x340-342x205.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/01\/Carteira-de-trabalho-20-12-07-567x340.jpg 567w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-59253\" class=\"wp-caption-text\">(Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">Portaria interministerial publicada nesta segunda-feira (4) no Di\u00e1rio Oficial da Uni\u00e3o assegura assist\u00eancia mensal de um sal\u00e1rio m\u00ednimo aos portu\u00e1rios avulsos: trabalhadores contratados temporariamente pelas empresas portu\u00e1rias, sem v\u00ednculos trabalhistas. Ter\u00e3o direito ao benef\u00edcio portu\u00e1rios com mais de 60 anos e que n\u00e3o cumprirem os requisitos para aposentadorias por invalidez, por idade, por tempo de contribui\u00e7\u00e3o e especial, e que n\u00e3o t\u00eam meios para prover sua subsist\u00eancia.<\/p>\n<p style=\"text-align: justify;\">De acordo com a portaria, \u00e9 considerado trabalhador portu\u00e1rio avulso \u201caquele que possui domic\u00edlio no Brasil e cadastro ativo ou registro ativo junto ao \u00d3rg\u00e3o Gestor de M\u00e3o de Obra do Trabalho Portu\u00e1rio Avulso [Ogmo]\u201d.<\/p>\n<p style=\"text-align: justify;\">Para receber esse benef\u00edcio, o trabalhador precisa ter pelo menos quinze anos de cadastro ou registro ativo como portu\u00e1rio avulso, al\u00e9m de ter um \u00edndice de comparecimento de, no m\u00ednimo, 80% tanto das chamadas feitas pelo \u00f3rg\u00e3o gestor de m\u00e3o de obra como para os trabalhos aos quais tenha sido escalado.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de especificar como funcionar\u00e1 os processos de concess\u00e3o, manuten\u00e7\u00e3o, suspens\u00e3o, cassa\u00e7\u00e3o e revis\u00e3o do benef\u00edcio, a portaria alerta que ele n\u00e3o pode ser acumulado com qualquer outro tipo de benef\u00edcio no \u00e2mbito da seguridade social ou de outro regime, salvo os da assist\u00eancia m\u00e9dica e das pens\u00f5es especiais de natureza indenizat\u00f3ria.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ag\u00eancia Brasil\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e curta no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook\u00a0<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Portaria interministerial publicada nesta segunda-feira (4) no Di\u00e1rio Oficial da Uni\u00e3o assegura assist\u00eancia mensal de um sal\u00e1rio m\u00ednimo aos portu\u00e1rios avulsos: trabalhadores contratados temporariamente pelas empresas portu\u00e1rias, sem v\u00ednculos trabalhistas. Ter\u00e3o direito ao benef\u00edcio portu\u00e1rios com mais de 60 anos e que n\u00e3o cumprirem os requisitos para aposentadorias por invalidez, por idade, por tempo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-67958","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67958"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=67958"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/59253"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=67958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=67958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=67958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}