{"id":67945,"date":"2014-08-04T11:46:43","date_gmt":"2014-08-04T14:46:43","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=67945"},"modified":"2014-08-05T10:35:31","modified_gmt":"2014-08-05T13:35:31","slug":"em-pesquisa-dilma-desbanca-campos-em-pernambuco","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/em-pesquisa-dilma-desbanca-campos-em-pernambuco\/","title":{"rendered":"Em pesquisa, Dilma desbanca Campos em Pernambuco"},"content":{"rendered":"<div><em><strong>Marina Pinhoni, de\u00a0<img decoding=\"async\" alt=\"\" src=\"http:\/\/exame2.abrilm.com.br\/assets\/sources\/1\/content_assinatura-examecom.png?1297174672\" \/><\/strong><\/em><\/div>\n<p style=\"text-align: justify;\">Ainda pouco conhecido fora do Nordeste, o candidato \u00e0 Presid\u00eancia\u00a0<strong>Eduardo Campos<\/strong>\u00a0(PSB) tamb\u00e9m n\u00e3o venceria\u00a0<strong>Dilma Rousseff\u00a0<\/strong>(PT) em Pernambuco \u2013 estado que governou \u2013 caso as elei\u00e7\u00f5es fossem hoje.<\/p>\n<p style=\"text-align: justify;\">Segundo pesquisa divulgada nesta segunda-feira pelo Instituto de Pesquisa Maur\u00edcio de Nassau (IPMN), Dilma tem 40% das inten\u00e7\u00f5es de voto no estado, contra 30% de Campos.<\/p>\n<div id=\"attachment_67946\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/eduardo.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-67946\" class=\"size-full wp-image-67946\" alt=\"Dilma tem 40% das inten\u00e7\u00f5es de voto em Pernambuco, contra 30% de Campos. (Reuters\/Ichiro Guerra\/Montagem EXAME.com)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/eduardo.jpg\" width=\"590\" height=\"442\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/eduardo.jpg 590w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/eduardo-300x224.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/eduardo-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/eduardo-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/eduardo-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/eduardo-269x201.jpg 269w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/a><p id=\"caption-attachment-67946\" class=\"wp-caption-text\">Dilma tem 40% das inten\u00e7\u00f5es de voto em Pernambuco, contra 30% de Campos. (Reuters\/Ichiro Guerra\/Montagem EXAME.com)<\/p><\/div>\n<p style=\"text-align: justify;\">No entanto, o ex-governador leva grande vantagem contra\u00a0<strong>A\u00e9cio Neves<\/strong>\u00a0(PSDB), que, embora esteja em segundo nas pesquisas nacionais, aparece em terceiro no levantamento realizado em Pernambuco, com apenas 4%.<\/p>\n<p style=\"text-align: justify;\">Entre os tr\u00eas primeiros colocados, o tucano tamb\u00e9m \u00e9 o candidato menos conhecido: 39% dos eleitores nunca ouviram falar em A\u00e9cio, 43% declararam conhec\u00ea-lo pouco e 16% afirmaram que o conhecem muito bem.<\/p>\n<p style=\"text-align: justify;\">O representante do PSC, Pastor Everaldo, conta com 1% do eleitorado. Os\u00a0outros\u00a0candidatos n\u00e3o chegaram a pontuar. A quantidade de indecisos e de pessoas que declararam votar branco ou nulo \u00e9 de 26%.<\/p>\n<p style=\"text-align: justify;\"><strong>Governo Dilma<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">A pesquisa, que foi realizada nos dias 28 e 29 de julho, tamb\u00e9m aponta que a maioria dos entrevistados aprova o governo atual da presidente Dilma Rousseff, com 51% contra os 40% que desaprovam.<\/p>\n<p style=\"text-align: justify;\">Aproximadamente 36% dos eleitores consideram a gest\u00e3o como \u00f3tima ou boa, 35% como regular e 27% como ruim ou p\u00e9ssima. A margem de erro da pesquisa \u00e9 de dois pontos percentuais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marina Pinhoni, de\u00a0 Ainda pouco conhecido fora do Nordeste, o candidato \u00e0 Presid\u00eancia\u00a0Eduardo Campos\u00a0(PSB) tamb\u00e9m n\u00e3o venceria\u00a0Dilma Rousseff\u00a0(PT) em Pernambuco \u2013 estado que governou \u2013 caso as elei\u00e7\u00f5es fossem hoje. Segundo pesquisa divulgada nesta segunda-feira pelo Instituto de Pesquisa Maur\u00edcio de Nassau (IPMN), Dilma tem 40% das inten\u00e7\u00f5es de voto no estado, contra 30% de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-67945","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67945"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=67945"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/67946"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=67945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=67945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=67945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}