{"id":67922,"date":"2014-08-03T11:09:16","date_gmt":"2014-08-03T14:09:16","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=67922"},"modified":"2014-08-04T10:02:55","modified_gmt":"2014-08-04T13:02:55","slug":"carreta-tomba-na-br-101-e-deixa-transito-lento-em-nossa-senhora-do-socorro","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/carreta-tomba-na-br-101-e-deixa-transito-lento-em-nossa-senhora-do-socorro\/","title":{"rendered":"Carreta tomba na BR-101 e deixa tr\u00e2nsito lento, em Nossa Senhora do Socorro"},"content":{"rendered":"<h1><\/h1>\n<p style=\"text-align: justify;\">Por volta das 9h na altura do km 93 da BR 101, no munic\u00edpio de Nossa Senhora do Socorro, uma carreta de placa DPB 0769, licen\u00e7a de Minas Gerais com carregamento de biscoito, seguia no sentido Aracaju\/Salvador, tombou e invadiu a pista contr\u00e1ria. O tr\u00e1fego est\u00e1 muito lento, \u00a0funcionando com meia pista com sinaliza\u00e7\u00e3o de pare e siga, com dez minutos de libera\u00e7\u00e3o para cada lado. O acidente, que n\u00e3o deixou feridos, foi pr\u00f3ximo do local onde parte da pista de concreto cedeu,\u00a0o fluxo de ve\u00edculos est\u00e1 sendo controlado por pare\/siga.<\/p>\n<p>Equipes da PRF continuam no local para retirar o ve\u00edculo da pista.<\/p>\n<div id=\"attachment_67924\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/carreta.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-67924\" class=\"size-full wp-image-67924\" alt=\"Tombamento de carreta deixa tr\u00e2nsito lento na BR 101 em Sergipe. (Foto: PRF\/SE)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/carreta.jpg\" width=\"595\" height=\"334\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/carreta.jpg 595w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/carreta-300x168.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/carreta-342x191.jpg 342w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-67924\" class=\"wp-caption-text\">Tombamento de carreta deixa tr\u00e2nsito lento na BR 101 em Sergipe. (Foto: PRF\/SE)<\/p><\/div>\n<p style=\"text-align: justify;\">Por conta da pista de m\u00e3o dupla a Pol\u00edcia Rodovi\u00e1ria Federal (PRF)alerta aos motoristas que o trafego no local est\u00e1 lenta e requer cuidado dos condutores. Os condutores podem tamb\u00e9m desviar o tr\u00e2nsito pela Rodovia estadual Jo\u00e3o Bebe \u00c1gua ou pela Rodovia dos N\u00e1ufragos\/Ponte Joel Silveira.<\/p>\n<p style=\"text-align: justify;\">Com informa\u00e7\u00f5es da PRF\/SE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 9h na altura do km 93 da BR 101, no munic\u00edpio de Nossa Senhora do Socorro, uma carreta de placa DPB 0769, licen\u00e7a de Minas Gerais com carregamento de biscoito, seguia no sentido Aracaju\/Salvador, tombou e invadiu a pista contr\u00e1ria. O tr\u00e1fego est\u00e1 muito lento, \u00a0funcionando com meia pista com sinaliza\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,1],"tags":[],"class_list":{"0":"post-67922","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67922"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=67922"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/67924"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=67922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=67922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=67922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}