{"id":67878,"date":"2014-08-01T13:55:45","date_gmt":"2014-08-01T16:55:45","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=67878"},"modified":"2014-08-01T13:55:45","modified_gmt":"2014-08-01T16:55:45","slug":"tse-recebe-pedido-de-registro-do-partido-novo","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tse-recebe-pedido-de-registro-do-partido-novo\/","title":{"rendered":"TSE recebe pedido de registro do Partido Novo"},"content":{"rendered":"<p style=\"text-align: justify;\">O Tribunal Superior Eleitoral (TSE) recebeu na \u00faltima quinta-feira\u00a0o pedido de registro do Partido\u00a0Novo. Segundo o tribunal, o documento em forma\u00e7\u00e3o pede o uso da sigla NOVO e o n\u00famero 30.<\/p>\n<div id=\"attachment_67879\" style=\"width: 594px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/Partido-N.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-67879\" class=\"size-full wp-image-67879\" alt=\"MAIS UM PARTIDO  OFICIALIZOU PEDIDO DE REGISTRO NO TSE. (Divulga\u00e7\u00e3o\/TSE)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/Partido-N.jpg\" width=\"584\" height=\"532\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/Partido-N.jpg 584w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/Partido-N-300x273.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/08\/Partido-N-342x311.jpg 342w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/a><p id=\"caption-attachment-67879\" class=\"wp-caption-text\">MAIS UM PARTIDO OFICIALIZOU PEDIDO DE REGISTRO NO TSE. (Divulga\u00e7\u00e3o\/TSE)<\/p><\/div>\n<p style=\"text-align: justify;\">Mesmo com a grande quantidade de partidos, um grupo de pessoas ainda n\u00e3o se sentia bem representada. Diante disso, h\u00e1 aproximadamente tr\u00eas anos, esse mesmo grupo come\u00e7ou a pensar em um novo partido. A mobiliza\u00e7\u00e3o para cria\u00e7\u00e3o do \u201cPartido Novo\u201d aconteceu nas redes sociais e nas ruas de v\u00e1rias capitais do Brasil, principalmente.<\/p>\n<p style=\"text-align: justify;\">Composto por cidad\u00e3os, o partido come\u00e7a sem pol\u00edticos no grupo. \u201c\u00c9 o partido do cidad\u00e3o comum\u201d, explicou Claudio Barra, presidente do diret\u00f3rio do Distrito Federal. Uma das bandeiras levantadas pelo \u201cPartido Novo\u201d \u00e9 a da liberdade individual. Barra tamb\u00e9m explica que o partido entende que \u201co Estado n\u00e3o deve atropelar a vida das pessoas e das fam\u00edlias\u201d.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Superior Eleitoral (TSE) recebeu na \u00faltima quinta-feira\u00a0o pedido de registro do Partido\u00a0Novo. Segundo o tribunal, o documento em forma\u00e7\u00e3o pede o uso da sigla NOVO e o n\u00famero 30. Mesmo com a grande quantidade de partidos, um grupo de pessoas ainda n\u00e3o se sentia bem representada. Diante disso, h\u00e1 aproximadamente tr\u00eas anos, esse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-67878","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67878"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=67878"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/67879"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=67878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=67878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=67878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}