{"id":67477,"date":"2014-07-24T14:01:04","date_gmt":"2014-07-24T17:01:04","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=67477"},"modified":"2014-07-26T15:22:44","modified_gmt":"2014-07-26T18:22:44","slug":"ondas-podem-chegar-ate-3-metros-de-altura-em-sergipe-diz-meteorologista","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/ondas-podem-chegar-ate-3-metros-de-altura-em-sergipe-diz-meteorologista\/","title":{"rendered":"Ondas podem chegar at\u00e9 3 metros de altura em Sergipe, diz meteorologista"},"content":{"rendered":"<div id=\"attachment_67478\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/07\/praia_aruana_aracaju.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-67478\" class=\" wp-image-67478 \" alt=\"Embarca\u00e7\u00f5es de pequeno porte devem evitar sair para navega\u00e7\u00e3o. (Foto: Joelma Gon\u00e7alves\/G1)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/07\/praia_aruana_aracaju.jpg\" width=\"558\" height=\"419\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/07\/praia_aruana_aracaju.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/07\/praia_aruana_aracaju-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/07\/praia_aruana_aracaju-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/07\/praia_aruana_aracaju-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/07\/praia_aruana_aracaju-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/07\/praia_aruana_aracaju-269x201.jpg 269w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-67478\" class=\"wp-caption-text\">Embarca\u00e7\u00f5es de pequeno porte devem evitar sair para navega\u00e7\u00e3o. (Foto: Joelma Gon\u00e7alves\/G1)<\/p><\/div>\n<p style=\"text-align: justify;\">Os ventos com velocidade de at\u00e9 50km\/h podem provocar a forma\u00e7\u00e3o de ondas de at\u00e9 3 metros de altura no litoral sergipano, segundo o Centro de Meteorologia de Sergipe que traz uma previs\u00e3o para esta quinta-feira (24) e sexta-feira (25). O \u00f3rg\u00e3o tamb\u00e9m prev\u00ea a ocorr\u00eancia de ressaca, ou seja, o avan\u00e7o do mar na regi\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Nesses dois dias, o tempo volta a ficar parcialmente nublado com predomin\u00e2ncia de chuvas leves, de acordo com o \u00f3rg\u00e3o, em todo o estado. \u201cAs chuvas v\u00e3o acontecer s\u00f3 que de forma isolada\u201d, informa a meteorologista, Aline Oliver.<\/p>\n<p style=\"text-align: justify;\">A temperatura m\u00e1xima na regi\u00e3o Agreste e Sert\u00e3o deve ficar entre 28 \u00b0C e 29 \u00b0C e m\u00ednima 14 \u00b0C, j\u00e1 no Litoral a m\u00e1xima pode chegar a 29 \u00b0C e menor 21 \u00b0C.<\/p>\n<p style=\"text-align: justify;\"><strong>Fim de semana<\/strong><\/p>\n<p style=\"text-align: justify;\">Durante o s\u00e1bado (26) e domingo (27), o clima tamb\u00e9m fica parcialmente nublado. \u201cN\u00e3o h\u00e1 uma mudan\u00e7a que diferencie dos dias anteriores, apenas o registro de umidade durante todo o dia e noite\u201d, observa.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do G1SE\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta pelo<a href=\"https:\/\/www.facebook.com\/PortalSENoticias?ref=hl&amp;ref_type=bookmark\" target=\"_blank\"> Facebook\u00a0<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os ventos com velocidade de at\u00e9 50km\/h podem provocar a forma\u00e7\u00e3o de ondas de at\u00e9 3 metros de altura no litoral sergipano, segundo o Centro de Meteorologia de Sergipe que traz uma previs\u00e3o para esta quinta-feira (24) e sexta-feira (25). O \u00f3rg\u00e3o tamb\u00e9m prev\u00ea a ocorr\u00eancia de ressaca, ou seja, o avan\u00e7o do mar na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,6],"tags":[],"class_list":{"0":"post-67477","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67477"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=67477"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/67477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/67478"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=67477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=67477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=67477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}