{"id":66276,"date":"2014-06-27T05:58:47","date_gmt":"2014-06-27T08:58:47","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=66276"},"modified":"2014-06-27T06:58:20","modified_gmt":"2014-06-27T09:58:20","slug":"66276","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/66276\/","title":{"rendered":"Cavalgada da Nova Descoberta acontece neste domingo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_66278\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0564.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-66278\" class=\"size-medium wp-image-66278\" alt=\"Circuito de Cavalgadas de Itaporanga atrai milhares de pessoas. (Foto: Ascom)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0564-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0564-300x200.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0564-342x228.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0564.jpg 571w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-66278\" class=\"wp-caption-text\">Circuito de Cavalgadas de Itaporanga atrai milhares de pessoas. (Foto: Ascom)<\/p><\/div>\n<p style=\"text-align: justify;\">Teve prosseguimento na ter\u00e7a-feira (24) o Circuito de Cavalgadas de Itaporanga D\u2019Ajuda, um dos eventos do calend\u00e1rio dos festejos juninos do munic\u00edpio mais importantes do interior do Estado. Saindo do Povoado Salvadorzinho, por volta das 17, a Cavalgada foi puxada pelo Trio Ospal ao som de Gal\u00e3 das Vaquejadas.<\/p>\n<p style=\"text-align: justify;\">Na Pra\u00e7a da Rodovi\u00e1ria, no Centro de Itaporanga, uma multid\u00e3o aguardava a Cavalgada, que chegou por volta das 19h. Os foli\u00f5es foram animados pelo sertanejo Eduardo Brito e as bandas Forr\u00f3 dos Plays e Viola.<\/p>\n<p style=\"text-align: justify;\">A prefeita de Itaporanga, Maria das Gra\u00e7as (Gracinha), que acompanhou a Cavalgada, comemorou o sucesso do evento e reafirmou o compromisso da administra\u00e7\u00e3o municipal com a cultura sergipana.<\/p>\n<p style=\"text-align: justify;\">\u201cEssa \u00e9 uma festa cultural que j\u00e1 faz parte do nosso calend\u00e1rio junino e que cresce a cada ano. Mais uma vez milhares de pessoas acompanharam a Cavalgada mostrando a paix\u00e3o do nosso povo por esta cultura. E isso nos faz trabalhar ainda mais para valorizar a nossa cultura\u201d, salienta.<\/p>\n<p style=\"text-align: justify;\">A estudante Cristiane Barbosa, que acompanhou a Cavalgada ao lado de v\u00e1rios amigos, testemunhou o sucesso e a tranquilidade da festa.<\/p>\n<p style=\"text-align: justify;\">\u201cTodos os anos eu e meus a amigos fazemos quest\u00e3o de participar desta Cavalgada que para n\u00f3s \u00e9 a melhor do Nordeste. Al\u00e9m da organiza\u00e7\u00e3o e anima\u00e7\u00e3o, a seguran\u00e7a Cavalgada. Venham todos pra c\u00e1 por que o forr\u00f3 aqui \u00e9 bom demais\u201d, diz sorridente.<\/p>\n<div id=\"attachment_66279\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0483.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-66279\" class=\"size-medium wp-image-66279\" alt=\"Prefeita Gracinha, participou da Cavalgada.(Foto: Ascom)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0483-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0483-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0483-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/IMG_0483.jpg 653w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-66279\" class=\"wp-caption-text\">Prefeita Gracinha, participou da Cavalgada.(Foto: Ascom)<\/p><\/div>\n<p style=\"text-align: justify;\">A festa foi encerrada por volta das 2h da madrugada. No pr\u00f3ximo domingo, ser\u00e1 a vez do Povoado Nova Descoberta receber a Cavalgada, que ser\u00e1 puxada por Neguinho Aboiador. A concentra\u00e7\u00e3o, que ser\u00e1 no Povoado Costa, ter\u00e1 a Pra\u00e7a do Povoado Nova Descoberta como o ponto de chegada. \u00c0 noite, por volta das 07h, haver\u00e1 shows com as Bandas Mulheres Perdidas e Zuer\u00f5es do Forr\u00f3.<\/p>\n<p><strong>Policiamento<\/strong><\/p>\n<p>A Cavalgada contou com o refor\u00e7o da Pol\u00edcia Militar por meio da Cavalaria, GETAM, CPRv, R\u00e1dio Patrulha e da 1\u00aa Cia do 1\u00ba Batalh\u00e3o, al\u00e9m de seguran\u00e7as particulares da empresa Brava Seguran\u00e7a.<\/p>\n<p><strong>Presen\u00e7as<\/strong><\/p>\n<p style=\"text-align: justify;\">Al\u00e9m da prefeita Gracinha, estiveram presentes os vereadores Bruno Sobral, Gilson Me Ajude e Mariza da Mata, que acompanharam os 6 km de percurso da Cavalgada.<\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9m prestigiaram o evento os deputados: Gustinho Ribeiro (estadual) e M\u00e1rcio Mac\u00eado (federal) e os vereadores: Bruno Sobral, Professor Humberto, Renatinho de Z\u00e9 de Lili e Celinha Sobral, al\u00e9m de v\u00e1rias lideran\u00e7as pol\u00edticas e comunit\u00e1rias locais.<\/p>\n<p>Os secret\u00e1rios municipais C\u00e9sar de Beb\u00e9 (Agricultura, Com\u00e9rcio e Ind\u00fastria), Faustinho Sobral (Meio Ambiente), Rubens Murilo (Administra\u00e7\u00e3o), Erivalda Santana (Finan\u00e7as), Antonio Pedro (Controle Interno) e Thiago Luduvice (Governo) tamb\u00e9m compareceram ao evento.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Teve prosseguimento na ter\u00e7a-feira (24) o Circuito de Cavalgadas de Itaporanga D\u2019Ajuda, um dos eventos do calend\u00e1rio dos festejos juninos do munic\u00edpio mais importantes do interior do Estado. Saindo do Povoado Salvadorzinho, por volta das 17, a Cavalgada foi puxada pelo Trio Ospal ao som de Gal\u00e3 das Vaquejadas. Na Pra\u00e7a da Rodovi\u00e1ria, no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":66278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,1],"tags":[],"class_list":{"0":"post-66276","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/66276"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=66276"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/66276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/66278"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=66276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=66276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=66276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}