{"id":66270,"date":"2014-06-26T18:31:05","date_gmt":"2014-06-26T21:31:05","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=66270"},"modified":"2014-06-26T18:31:39","modified_gmt":"2014-06-26T21:31:39","slug":"deputado-joao-daniel-esclarece-ocupacao-da-radio-xodo-fm","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/deputado-joao-daniel-esclarece-ocupacao-da-radio-xodo-fm\/","title":{"rendered":"Deputado Jo\u00e3o Daniel esclarece ocupa\u00e7\u00e3o da r\u00e1dio Xod\u00f3 FM"},"content":{"rendered":"<p style=\"text-align: justify;\">Na tribuna da Assembleia Legislativa, na sess\u00e3o desta quinta-feira, dia 26, o deputado estadual Jo\u00e3o Daniel (PT) se pronunciou sobre o ocorrido na r\u00e1dio Xod\u00f3 FM, no sert\u00e3o sergipano. Sobre isso, o parlamentar disse que se h\u00e1 algu\u00e9m que \u00e9 v\u00edtima e tem sofrido naquela regi\u00e3o t\u00eam sido as lideran\u00e7as e os movimentos sociais e o Movimento Sem Terra (MST).<\/p>\n<p style=\"text-align: justify;\">\u201cFoi um movimento pac\u00edfico, tranquilo, que luta pelo direito de falar na emissora de r\u00e1dio\u201d, ressaltou. Jo\u00e3o Daniel disse que diferente de outros programas como o do deputado Gilmar Carvalho na regi\u00e3o, o do radialista Anselmo Tavares tem sido dirigido, com ofensas. \u201cEle j\u00e1 inicia o programa com chamadas: \u2018vou tratar do assunto da presidente ladra, do ex-presidente ladr\u00e3o\u2019. S\u00e3o duas horas de agress\u00e3o. Voc\u00ea liga para falar e corta\u201d, relato o parlamentar.<\/p>\n<p style=\"text-align: justify;\">Em seu pronunciamento, o deputado Jo\u00e3o Daniel fez um apelo ao propriet\u00e1rio da emissora Xod\u00f3 FM para que tome as provid\u00eancias necess\u00e1rias para oportunidade \u00e0s pessoas de se manifestarem e participarem do programa. O deputado disse que foram mais de 15 organiza\u00e7\u00f5es que participaram da ocupa\u00e7\u00e3o e, segundo ele, n\u00e3o houve depreda\u00e7\u00e3o do patrim\u00f4nio da emissora, nem desmaio.<\/p>\n<p style=\"text-align: justify;\">De acordo com o deputado, essa \u00e9 uma luta pela democratiza\u00e7\u00e3o dos meios de comunica\u00e7\u00e3o com os movimentos sociais que lutam e t\u00eam esse direito. \u201cO MST, o Movimento de Pequenos Agricultores, o Levante Popular da Juventude, entre outros, todos fizeram um ato muito consciente, tranquilo e sem problema e dou total apoio ao movimento\u201d, afirmou, acrescentando que n\u00e3o houve depreda\u00e7\u00e3o, xingamentos ou agress\u00e3o f\u00edsica.<\/p>\n<p>\u00a0<strong>Servidores p\u00fablicos<\/strong><\/p>\n<p style=\"text-align: justify;\">Em seu pronunciamento, o deputado estadual Jo\u00e3o Daniel disse da sua satisfa\u00e7\u00e3o com a negocia\u00e7\u00e3o que o governo do Estado tem feito com os servidores p\u00fablicos estaduais, a exemplo dos defensores p\u00fablicos, \u201ccategoria que formamos a Frente Parlamentar em Defesa da Defensoria P\u00fablica e esperamos que o governo possa atender as reivindica\u00e7\u00f5es\u201d, afirmou.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p><strong><em>Edjane Oliveira, da Assessoria de Imprensa<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tribuna da Assembleia Legislativa, na sess\u00e3o desta quinta-feira, dia 26, o deputado estadual Jo\u00e3o Daniel (PT) se pronunciou sobre o ocorrido na r\u00e1dio Xod\u00f3 FM, no sert\u00e3o sergipano. Sobre isso, o parlamentar disse que se h\u00e1 algu\u00e9m que \u00e9 v\u00edtima e tem sofrido naquela regi\u00e3o t\u00eam sido as lideran\u00e7as e os movimentos sociais e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-66270","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/66270"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=66270"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/66270\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=66270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=66270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=66270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}