{"id":65403,"date":"2014-06-09T18:51:17","date_gmt":"2014-06-09T21:51:17","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=65403"},"modified":"2014-06-09T18:51:17","modified_gmt":"2014-06-09T21:51:17","slug":"rede-cinemark-continua-com-a-sessao-desconto","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/rede-cinemark-continua-com-a-sessao-desconto\/","title":{"rendered":"Rede Cinemark continua com a &#8220;Sess\u00e3o Desconto&#8221;"},"content":{"rendered":"<div id=\"attachment_65404\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/grande-cinemark_reproducao_260214.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-65404\" class=\"size-medium wp-image-65404\" alt=\"Ingressos tem valores reduzidos para as sess\u00f5es de 14h (Foto: divulga\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/grande-cinemark_reproducao_260214-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/grande-cinemark_reproducao_260214-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/grande-cinemark_reproducao_260214-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/grande-cinemark_reproducao_260214.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-65404\" class=\"wp-caption-text\">Ingressos tem valores reduzidos para as sess\u00f5es de 14h (Foto: divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">A Rede Cinemark oferece aos espectadores da Rede de todo o Brasil ingressos com valores reduzidos para a sess\u00e3o das 14h, exclusivamente. A promo\u00e7\u00e3o \u00e9 v\u00e1lida de segunda a sexta-feira.<\/p>\n<p style=\"text-align: justify;\">A cada semana, a \u201cSess\u00e3o Desconto\u201d traz variados t\u00edtulos nacionais e estrangeiros nos valores de R$ 6 (inteira) e R$ 3 (meia). A promo\u00e7\u00e3o \u00e9 v\u00e1lida para todos os cinemas da Rede, com exce\u00e7\u00e3o do complexo do Shopping Village Mall, no Rio de Janeiro, e salas Prime.<\/p>\n<p style=\"text-align: justify;\">Para mais informa\u00e7\u00f5es, acesse o site da Rede (<strong><a href=\"https:\/\/www.facebook.com\/PortalSENoticias?ref=bookmarks\" target=\"_blank\">www.cinemark.com.br<\/a><\/strong>).<\/p>\n<p style=\"text-align: justify;\"><strong>Rede Cinemark no Brasil<\/strong><\/p>\n<p style=\"text-align: justify;\">L\u00edder no mercado exibidor, a Rede Cinemark representa cerca de 30% do mercado brasileiro de cinema e \u00e9 maior que seus tr\u00eas principais concorrentes juntos, com 535 salas de cinema em 68 complexos distribu\u00eddos por 16 estados e Distrito Federal: Mato Grosso do Sul, Mato Grosso, Minas Gerais, Paran\u00e1, Rio de Janeiro, Rio Grande do Sul, Rio Grande do Norte, S\u00e3o Paulo, Sergipe, Goi\u00e1s, Santa Catarina, Esp\u00edrito Santo, Bahia, Amazonas, Tocantins e Pernambuco. \u00c9 da Rede Cinemark a primeira sala de cinema em 3D da Am\u00e9rica do Sul, no Shopping Eldorado, em S\u00e3o Paulo, que segue o padr\u00e3o exigido pelos grandes est\u00fadios americanos.<\/p>\n<p style=\"text-align: justify;\">Atualmente, a Rede conta com 254 salas com a tecnologia de proje\u00e7\u00e3o digital em 3D no pa\u00eds. Recentemente, a Cinemark trouxe uma nova tecnologia, Extreme Digital Cinema &#8211; XD, com telas maiores que as convencionais e uma sonoriza\u00e7\u00e3o ainda mais potente, reunindo o que h\u00e1 de mais moderno em tecnologia 2D e 3D. As salas XD j\u00e1 est\u00e3o presentes em 28 complexos. A Rede tamb\u00e9m apresentou a primeira sala vip do pa\u00eds, com servi\u00e7os como card\u00e1pio especialmente criado pela chef Morena Leite, e atendimento diferenciado desde a bilheteria at\u00e9 o servi\u00e7o de snack bar, que pode ser entregue diretamente na sala. As salas vips Bradesco Prime oferecem tamb\u00e9m mais conforto com poltronas que seguem o conceito da classe executiva dos voos internacionais. Para usufruir das salas Cinemark em qualquer complexo da Rede, os espectadores podem comprar o ingresso pela internet, al\u00e9m de contar com os diversos aplicativos de consulta da programa\u00e7\u00e3o para Windows 8, Windows Phone, Android, iPhone e Blackberry, que fazem parte da plataforma mobile da Cinemark.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Cinemark\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Facebook\u00a0<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Rede Cinemark oferece aos espectadores da Rede de todo o Brasil ingressos com valores reduzidos para a sess\u00e3o das 14h, exclusivamente. A promo\u00e7\u00e3o \u00e9 v\u00e1lida de segunda a sexta-feira. A cada semana, a \u201cSess\u00e3o Desconto\u201d traz variados t\u00edtulos nacionais e estrangeiros nos valores de R$ 6 (inteira) e R$ 3 (meia). A promo\u00e7\u00e3o \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":65404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-65403","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultura"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/65403"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=65403"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/65403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/65404"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=65403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=65403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=65403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}