{"id":65210,"date":"2014-06-05T05:39:16","date_gmt":"2014-06-05T08:39:16","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=65210"},"modified":"2014-06-05T05:41:17","modified_gmt":"2014-06-05T08:41:17","slug":"sindicato-dos-jornalistas-se-reune-com-secretario-de-seguranca-e-cobra-punicao-a-policial-civil-agressor","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/sindicato-dos-jornalistas-se-reune-com-secretario-de-seguranca-e-cobra-punicao-a-policial-civil-agressor\/","title":{"rendered":"Sindicato dos Jornalistas se re\u00fane com secret\u00e1rio de Seguran\u00e7a e cobra puni\u00e7\u00e3o a policial civil agressor"},"content":{"rendered":"<div id=\"attachment_65212\" style=\"width: 350px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/diretores-sindijor-com-secret\u00e1rio.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-65212\" class=\"size-full wp-image-65212\" alt=\"SINDIJOR-SE se re\u00fane com secret\u00e1rio de Seguran\u00e7a.(Divulga\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/diretores-sindijor-com-secret\u00e1rio.jpg\" width=\"340\" height=\"255\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/diretores-sindijor-com-secret\u00e1rio.jpg 340w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/diretores-sindijor-com-secret\u00e1rio-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/diretores-sindijor-com-secret\u00e1rio-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/diretores-sindijor-com-secret\u00e1rio-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/06\/diretores-sindijor-com-secret\u00e1rio-269x201.jpg 269w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a><p id=\"caption-attachment-65212\" class=\"wp-caption-text\">SINDIJOR-SE se re\u00fane com secret\u00e1rio de Seguran\u00e7a.(Divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">O Sindicato dos Jornalistas Profissionais de Sergipe (SINDIJOR-SE) vem a p\u00fablico prestar solidariedade \u00e0 equipe de Jornalismo do Portal Infonet, que foi agredida por um policial civil no momento em que retornava para Aracaju, ap\u00f3s a produ\u00e7\u00e3o de uma reportagem no interior do Estado, na manh\u00e3 da ter\u00e7a-feira (3).<\/p>\n<p style=\"text-align: justify;\">A equipe foi amea\u00e7ada quando realizava uma reportagem em dois munic\u00edpios sergipanos. O epis\u00f3dio aconteceu pouco antes das 9h no munic\u00edpio de Salgado, onde produzia uma mat\u00e9ria sobre \u00cdtalo Bruno Ara\u00fajo Fonseca, enteado do secret\u00e1rio de Estado de Seguran\u00e7a P\u00fablica e suspeito de ter abordado um taxista com armamento e anunciado assalto na \u00faltima semana.<\/p>\n<p style=\"text-align: justify;\">Ao estacionar o ve\u00edculo na estrada, por determina\u00e7\u00e3o dos policiais que estavam em dois carros, a equipe foi surpreendida por um policial armado que amea\u00e7ou e tomou os aparelhos de telefone celular e a m\u00e1quina fotogr\u00e1fica. O policial jogou a m\u00e1quina fotogr\u00e1fica contra o ch\u00e3o, quebrando o equipamento. O policial suspeitava que a equipe jornal\u00edstica o seguia.<\/p>\n<p style=\"text-align: justify;\">A conduta do policial civil causa preocupa\u00e7\u00e3o, pois este n\u00e3o \u00e9 o primeiro caso em que um agente do Estado agride um jornalista. H\u00e1 menos de um ano, a jornalista Sayonara Higia foi agredida por um policial militar durante uma manifesta\u00e7\u00e3o. Essas a\u00e7\u00f5es deixam entrever que falta uma forma\u00e7\u00e3o continuada aos policiais para que tenham um melhor trato, seja com os profissionais da imprensa, seja com os trabalhadores em geral.<\/p>\n<p style=\"text-align: justify;\">O SINDIJOR, que foi recebido nesta quarta-feira (4) pelo secret\u00e1rio interino da Seguran\u00e7a P\u00fablica, Jo\u00e3o Batista, e pela corregedora da Pol\u00edcia Civil, Teonice Alexandre, espera que as autoridades cumpram com o prometido: investiga\u00e7\u00e3o transparente, rigorosa e puni\u00e7\u00e3o do respons\u00e1vel.<\/p>\n<p style=\"text-align: justify;\">O SINDIJOR, entidade de representa\u00e7\u00e3o dos jornalistas em Sergipe, torce para que a atitude irrespons\u00e1vel de um policial n\u00e3o contamine o comportamento decente da maioria dos que fazem a Seguran\u00e7a P\u00fablica em Sergipe. Policiais agressores precisam ser punidos para que situa\u00e7\u00f5es semelhantes n\u00e3o se repitam.<\/p>\n<p style=\"text-align: justify;\">O jornalista tem um papel social a cumprir. E do nosso exerc\u00edcio profissional, com liberdade de atua\u00e7\u00e3o, sustenta-se a democracia, e disso n\u00e3o abrimos m\u00e3o.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\"Twitter\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Sindicato dos Jornalistas Profissionais de Sergipe<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Sindicato dos Jornalistas Profissionais de Sergipe (SINDIJOR-SE) vem a p\u00fablico prestar solidariedade \u00e0 equipe de Jornalismo do Portal Infonet, que foi agredida por um policial civil no momento em que retornava para Aracaju, ap\u00f3s a produ\u00e7\u00e3o de uma reportagem no interior do Estado, na manh\u00e3 da ter\u00e7a-feira (3). A equipe foi amea\u00e7ada quando realizava [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":65212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,1],"tags":[],"class_list":{"0":"post-65210","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/65210"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=65210"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/65210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/65212"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=65210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=65210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=65210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}