{"id":64907,"date":"2014-05-29T22:35:53","date_gmt":"2014-05-30T01:35:53","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=64907"},"modified":"2014-05-29T22:37:18","modified_gmt":"2014-05-30T01:37:18","slug":"ex-prefeito-armando-batalha-tem-contas-de-2003-aprovadas-pelo-tce","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/ex-prefeito-armando-batalha-tem-contas-de-2003-aprovadas-pelo-tce\/","title":{"rendered":"Ex-prefeito, Armando Batalha tem contas de 2003 aprovadas pelo TCE"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Corte\u00a0decidiu pela aprova\u00e7\u00e3o das Contas Anuais da prefeitura de S\u00e3o Crist\u00f3v\u00e3o, referentes ao exerc\u00edcio 2003, de interesse de Armando Batalha de G\u00f3is.<\/strong><\/em><\/p>\n<div id=\"attachment_64908\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/PRP-ARMANDO-BATALHA0007.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-64908\" class=\"size-medium wp-image-64908\" alt=\" Ex-prefeito de S\u00e3o Crist\u00f3v\u00e3o e atual presidente estadual do (PRB), teve as contas do ano de 2003 aprovadas pelo  Tribunal de Contas do Estado.(Foto: Ascom\/PMSC)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/PRP-ARMANDO-BATALHA0007-300x293.jpg\" width=\"300\" height=\"293\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/PRP-ARMANDO-BATALHA0007-300x293.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/PRP-ARMANDO-BATALHA0007-50x50.jpg 50w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/PRP-ARMANDO-BATALHA0007-342x334.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/PRP-ARMANDO-BATALHA0007-55x55.jpg 55w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/PRP-ARMANDO-BATALHA0007.jpg 537w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-64908\" class=\"wp-caption-text\"><br \/>Ex-prefeito de S\u00e3o Crist\u00f3v\u00e3o e atual presidente estadual do (PRP), teve as contas do ano de 2003 aprovadas pelo Tribunal de Contas do Estado.(Foto: Ascom\/PMSC)<\/p><\/div>\n<p style=\"text-align: justify;\">Nesta quinta-feira, 29, foram julgados 34 processos e 3 protocolos na sess\u00e3o do Pleno do Tribunal de Contas do Estado de Sergipe (TCE\/SE). Sob a presid\u00eancia do conselheiro Carlos Pinna, tamb\u00e9m participaram os conselheiros Carlos Alberto Sobral, Cl\u00f3vis Barbosa, Luiz Augusto Ribeiro, Susana Azevedo e Ulices Andrade, os conselheiros substitutos Francisco Evanildo de Carvalho, Rafael Fons\u00eaca e Alexandre Lessa, al\u00e9m do procurador Jo\u00e3o Augusto Bandeira de Mello.<\/p>\n<p style=\"text-align: justify;\">Com voto de vista de Rafael Fons\u00eaca, permaneceu o voto do relator Carlos Alberto pela emiss\u00e3o de parecer pr\u00e9vio pela aprova\u00e7\u00e3o das Contas Anuais da prefeitura de Nossa Senhora Aparecida, referentes ao exerc\u00edcio 2006, de interesse de Ver\u00f4nica Santos Souza da Silva. Em processo referente \u00e0 Tomada de Contas Especial do Instituto de Promo\u00e7\u00e3o e de Assist\u00eancia \u00e0 Sa\u00fade dos Servidores do Estado de Sergipe, de interesse de Ant\u00f4nio Sizenando Menezes de Oliveira, Jos\u00e9 Lima Santana e Massashi Morita, Cl\u00f3vis Barbosa proferiu voto de vista acompanhando o relator Carlos Alberto pela ilegalidade, com multa de R$ 2 mil para cada gestor.<\/p>\n<p style=\"text-align: justify;\"><strong>Luiz Augusto, em voto de vista, decidiu pela aprova\u00e7\u00e3o das Contas Anuais da prefeitura de S\u00e3o Crist\u00f3v\u00e3o, referentes ao exerc\u00edcio 2003, de interesse de Armando Batalha de G\u00f3is, em processo de relatoria de Ulices Andrade.<\/strong> E acompanhou o relator Ulices Andrade pela regularidade, com ressalvas e recomenda\u00e7\u00e3o, das Contas Anuais da Secretaria de Estado da Agricultura e do Desenvolvimento Rural, referentes ao exerc\u00edcio de 01.01.2006 a 31.12.2006, de interesse de Artur S\u00e9rgio de Almeida Reis.<\/p>\n<p style=\"text-align: justify;\">Susana Azevedo acompanhou em voto de vista o relator Ulices Andrade pelo improvimento do Recurso de Reconsidera\u00e7\u00e3o interposto por Werner Gomes Siqueira, ex-presidente da C\u00e2mara de Japoat\u00e3, bem como acompanhou o relator Luiz Augusto pela irregularidade, com multa de R$ 2 mil, das Contas Anuais da c\u00e2mara de Areia Branca, referentes ao exerc\u00edcio 2010, de interesse de Adailton Santana.<\/p>\n<p style=\"text-align: justify;\">As Contas Anuais da Servi\u00e7os Gr\u00e1ficos de Sergipe, referentes ao exerc\u00edcio 2008, de interesse de Luiz Eduardo Oliva, de relatoria de Francisco Evanildo, foram consideradas regulares, com ressalvas, com voto de vista de Cl\u00f3vis Barbosa; ele tamb\u00e9m proferiu voto de vista em processo referente a Rescis\u00f3ria interposta por Elizeu Santos, ex-prefeito de Cristin\u00e1polis, de relatoria de Francisco Evanildo.<\/p>\n<p style=\"text-align: justify;\">Carlos Alberto votou pela regularidade das Contas Anuais da vice-governadoria do Estado, referentes ao exerc\u00edcio 2007, de interesse de Belivaldo Chagas Silva; das Contas Anuais do Fundo de Aval do Estado de Sergipe, referentes ao exerc\u00edcio 2008, de interesse de Nilson Nascimento Lima; das Contas Anuais do Fundo de Incentivo a Arrecada\u00e7\u00e3o, referentes ao exerc\u00edcio 2008, de interesse de Nilson Nascimento Lima; e das Contas Anuais da C\u00e2mara de Pedra Mole, referentes ao exerc\u00edcio 2008, de interesse de Jos\u00e9 Francisco Neto.<\/p>\n<p style=\"text-align: justify;\">O conselheiro decidiu ainda pela rejei\u00e7\u00e3o das Contas Anuais da prefeitura de Pedra Mole, referentes ao exerc\u00edcio 2008, de interesse de Milton Batista Carvalho; pela irregularidade, com multa de R$ 2 mil, das Contas Anuais da c\u00e2mara de Areia Branca, referentes ao exerc\u00edcio 2007, de interesse de Josias Teles; pela regularidade, com ressalvas, das Contas Anuais da Secretaria de Estado da Casa Civil, referentes ao exerc\u00edcio 2007, de interesse de Jos\u00e9 de Oliveira Junior; pelo provimento parcial de Rescis\u00f3ria interposta por Edileuza Santana Santos, da prefeitura de Maruim, e pelo arquivamento da Revis\u00e3o de Proventos de soldado da Secretaria de Estado da Casa Civil.<\/p>\n<p style=\"text-align: justify;\">Cl\u00f3vis Barbosa votou pela regularidade, com ressalvas, das Contas Anuais do Fundo Estadual de Sa\u00fade, referentes ao exerc\u00edcio 2007, de interesse de Rog\u00e9rio Carvalho Santos; e pela autua\u00e7\u00e3o de documentos da Secretaria de Estado da Seguran\u00e7a P\u00fablica; da Pol\u00edcia Militar do Estado de Sergipe e da prefeitura de Santa Luzia do Itanhy.<\/p>\n<p style=\"text-align: justify;\">Ulices Andrade decidiu pela regularidade das Contas Anuais do Fundo de Apoio \u00e0 Industrializa\u00e7\u00e3o, referentes ao exerc\u00edcio 2008, de interesse de Jorge Santana de Oliveira; pela emiss\u00e3o de parecer pr\u00e9vio pela aprova\u00e7\u00e3o, com ressalvas, das Contas Anuais da prefeitura de Nossa Senhora Aparecida, referentes ao exerc\u00edcio 2008, de interesse de Ver\u00f4nica Santos Souza da Silva; pela aprova\u00e7\u00e3o com ressalvas das Contas Anuais da prefeitura de Nossa Senhora do Socorro, referentes ao exerc\u00edcio 2008, de interesse de Jos\u00e9 do Prado Franco Sobrinho; pelo arquivamento de den\u00fancia da prefeitura de Po\u00e7o Redondo, de interesse de \u00c2ngela Maria de Melo Marques e Sintese, e pela proced\u00eancia, com multa de R$ 5 mil, de den\u00fancia da prefeitura de Santo Amaro das Brotas, de interesse de Jos\u00e9 Ivaldo Costa e Pol\u00edcia Federal.<\/p>\n<p style=\"text-align: justify;\">Luiz Augusto votou pela regularidade das Contas Anuais da Companhia de Desenvolvimento Industrial e Recursos Minerais, referentes ao exerc\u00edcio 2010, de interesse de Ancelmo de Oliveira; das Contas Anuais do Sergipe Parque Tecnol\u00f3gico, referentes ao exerc\u00edcio 2010, de interesse de Marcos Wandir Nery Lob\u00e3o; das Contas Anuais do Fundo Estadual de Recurso H\u00eddricos, referentes ao exerc\u00edcio 2009, de interesse de M\u00e1rcio Costa Macedo, e das Contas Anuais do Fundo Municipal de Sa\u00fade de Canind\u00e9 do S\u00e3o Francisco, referentes ao exerc\u00edcio 2010, de interesse de Murilo Porto de Andrade.<\/p>\n<p style=\"text-align: justify;\">Ele votou tamb\u00e9m pela emiss\u00e3o de parecer pr\u00e9vio pela rejei\u00e7\u00e3o das Contas Anuais da prefeitura de Indiaroba, referentes ao exerc\u00edcio 2005, de interesse de Jo\u00e3o Eduardo Viegas Mendon\u00e7a de Ara\u00fajo; pela aprova\u00e7\u00e3o com ressalvas das Contas Anuais da prefeitura de Nossa Senhora Aparecida, referentes ao exerc\u00edcio 2002, de interesse de Manoel Eronides dos Santos, e pela irregularidade, com multa de R$ 1 mil, da Presta\u00e7\u00e3o de Contas da Pol\u00edcia Militar de Sergipe, referentes ao exerc\u00edcio de 21.02.2006 a 31.12.2006.<\/p>\n<p style=\"text-align: justify;\">Susana Azevedo decidiu pela emiss\u00e3o de parecer pr\u00e9vio pela aprova\u00e7\u00e3o com ressalvas e recomenda\u00e7\u00e3o das Contas Anuais da prefeitura de Telha, referentes ao exerc\u00edcio 2003, de interesse de Luciano G\u00f3is de Gomes; e Francisco Evanildo pela improced\u00eancia de Rescis\u00f3ria interposta pelo Minist\u00e9rio P\u00fablico de Contas, e negou provimento ao Recurso de Reexame interposto por Jos\u00e9 Nivaldo de Carvalho, ex-prefeito de Areia Branca.<\/p>\n<p style=\"text-align: justify;\">Todos os votos foram aprovados por unanimidade pelo colegiado e, em alguns casos, ainda cabe recurso junto ao TCE.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p><em><strong>Da Assessoria de Imprensa\/TCE\/SE<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corte\u00a0decidiu pela aprova\u00e7\u00e3o das Contas Anuais da prefeitura de S\u00e3o Crist\u00f3v\u00e3o, referentes ao exerc\u00edcio 2003, de interesse de Armando Batalha de G\u00f3is. Nesta quinta-feira, 29, foram julgados 34 processos e 3 protocolos na sess\u00e3o do Pleno do Tribunal de Contas do Estado de Sergipe (TCE\/SE). Sob a presid\u00eancia do conselheiro Carlos Pinna, tamb\u00e9m participaram os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-64907","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/64907"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=64907"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/64907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/64908"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=64907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=64907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=64907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}