{"id":64423,"date":"2014-05-21T06:51:29","date_gmt":"2014-05-21T09:51:29","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=64423"},"modified":"2014-05-21T06:51:29","modified_gmt":"2014-05-21T09:51:29","slug":"eduardo-amorim-preside-audiencia-sobre-telefonia","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/eduardo-amorim-preside-audiencia-sobre-telefonia\/","title":{"rendered":"Eduardo Amorim preside audi\u00eancia sobre telefonia"},"content":{"rendered":"<div id=\"attachment_64424\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-audiencia_telefonia_amorim_200514.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-64424\" class=\"size-medium wp-image-64424\" alt=\"Eduardo Amorim amplia debate sobre servi\u00e7os de telefonia no Brasil (Foto: divulga\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-audiencia_telefonia_amorim_200514-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-audiencia_telefonia_amorim_200514-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-audiencia_telefonia_amorim_200514-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/05\/grande-audiencia_telefonia_amorim_200514.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-64424\" class=\"wp-caption-text\">Eduardo Amorim amplia debate sobre servi\u00e7os de telefonia no Brasil (Foto: divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">O senador Eduardo Amorim (PSC-SE), presidiu na manh\u00e3 da ter\u00e7a-feira, 20, a audi\u00eancia p\u00fablica com os presidentes das empresas de telecomunica\u00e7\u00f5es sobre a baixa qualidade dos servi\u00e7os de telefonia m\u00f3vel. Atenderam o requerimento do parlamentar os presidentes da TIM, Rodrigo Abreu; da Vivo, Antonio Carlos Valente da Silva; e da Claro, Carlos Zenteno.<\/p>\n<p style=\"text-align: justify;\">No segundo momento da audi\u00eancia participaram o presidente da Anatel, Jo\u00e3o Rezende, o presidente da SINDITELEBRASIL, Eduardo Levy, representaram a UNALE, os deputados estaduais Augusto Bezerra (DEM-SE) e Ven\u00e2ncio Fonseca (PP-SE), a promotora de Defesa dos Direitos do Consumidor do MP\/SE, Euza Missano e o jornalista da Folha de S\u00e3o Paulo, Le\u00e3o Serva.<\/p>\n<p>Os participantes debateram o tema com os senadores das Comiss\u00f5es de Meio Ambiente, Defesa do Consumidor e Fiscaliza\u00e7\u00e3o e Controle (CMA), de Ci\u00eancia, Tecnologia, Comunica\u00e7\u00e3o e Inform\u00e1tica (CCT) e de Servi\u00e7os de Infraestrutura (CI).<\/p>\n<p style=\"text-align: justify;\">O presidente da Vivo S.A., Antonio Carlos Valente, fez um breve relato em nome de todas as empresas. Segundo ele, h\u00e1 um conjunto de atividades sendo realizadas. S\u00e3o esfor\u00e7os do setor para manter o crescimento \u2013 a implanta\u00e7\u00e3o de infraestrutura, a redu\u00e7\u00e3o dos pre\u00e7os ao consumidor e o cumprimento de todas as metas impostas pelo \u00f3rg\u00e3o regulador. \u201cA Vivo investiu em 2013 R$ 29, 3 bilh\u00f5es, o que resulta em R$ 80 milh\u00f5es por dia, um crescimento bastante significativo entre 2010 e 2013\u201d, informou Valente.<\/p>\n<p style=\"text-align: justify;\">Ao mostrar os dados da Vivo, Valente informou ainda que h\u00e1 no Pa\u00eds 274 milh\u00f5es de chips ativados, o que significa aparelhos nas m\u00e3os dos consumidores ou modens, sendo que 45% desses celulares podem acessar a banda larga com velocidade. \u201cEsse crescimento representa uma cobertura de 85% no Brasil\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">Mesmo com os questionamentos dos servi\u00e7os com taxas elevadas e qualidade ruim o presidente da Vivo afirmou que o Brasil firma o compromisso de possuir um dos minutos mais baratos do mundo. Segundo ele, o custo m\u00e9dio entre as empresas \u00e9 de R$ 0,15. \u201cCom o crescimento avan\u00e7ado do Pa\u00eds nessa \u00e1rea \u00e9 preciso a instala\u00e7\u00e3o de mais antenas, com a quarta gera\u00e7\u00e3o a infraestrutura exigida \u00e9 maior. N\u00e3o h\u00e1 como d\u00e1 qualidade do servi\u00e7o sem a implanta\u00e7\u00e3o de infraestrutura\u201d, disse Valente.<\/p>\n<p style=\"text-align: justify;\">O senador Eduardo Amorim, voltou a reclamar dos baixos servi\u00e7os de telefonia m\u00f3vel e destacou a falta de cobertura no interior do Brasil, o parlamentar exemplificou com a situa\u00e7\u00e3o do povoado Col\u00f4nia Treze, Lagarto. \u201c\u00c9 lament\u00e1vel que a cobertura n\u00e3o seja ampla no interior. Que os servi\u00e7os sejam bons durante a Copa e ap\u00f3s, temos que ganhar esse legado\u201d, solicitou Amorim.<\/p>\n<p style=\"text-align: justify;\">O presidente da TIM S.A. Rodrigo Abreu afirmou que os \u00edndices de reclama\u00e7\u00f5es s\u00e3o altos porque se trata do setor com mais usu\u00e1rios. \u201cTemos sempre um destaque negativo entre os usu\u00e1rios, seja na Anatel ou no Procon, mas vale a pena analisar que esses \u00edndices quando estudados em percentual, s\u00e3o baixos\u201d, afirmou Abreu.<\/p>\n<p style=\"text-align: justify;\">Segundo o presidente da Claro S.A, Carlos Zenteno, a empresa est\u00e1 pronta para receber milhares de usu\u00e1rios internacionais durante a Copa do Mundo. &#8220;Toda a infra-estrutura foi desenhada por engenheiros internacionais. A nossa situa\u00e7\u00e3o mais urgente s\u00e3o quanto aos est\u00e1dios rec\u00e9m entregues&#8221;, informou ao dizer ainda &#8220;os usu\u00e1rios perceber\u00e3o um grande investimento da Claro nos pr\u00f3ximos anos&#8221;.<\/p>\n<p style=\"text-align: justify;\">O deputado estadual Augusto Bezerra, participou do segundo momento da audi\u00eancia com os presidentes das \u201cTeles\u201d, ele representou a UNALE. &#8220;A qualidade do servi\u00e7o \u00e9 ruim e a Anatel precisa investigar e aprimorar a qualidade. Depois de uma audi\u00eancia como essa precisamos de respostas mais claras&#8221;, afirmou Bezerra.<\/p>\n<p><strong>O telefone chamado n\u00e3o existe<\/strong><\/p>\n<p style=\"text-align: justify;\">O jornalista da Folha de S\u00e3o Paulo, Le\u00e3o Serva, questionou na audi\u00eancia ao presidente da Anatel, Jo\u00e3o Resende, sobre a famosa frase \u201co telefone chamado n\u00e3o existe\u201d. Segundo ele, essa situa\u00e7\u00e3o esconde um problema de congestionamento do sistema, na \u00e1rea em que o usu\u00e1rio est\u00e1 ou na opera\u00e7\u00e3o inteira. Para Serva \u201cS\u00f3 que as operadoras t\u00eam metas que devem ser cumpridas e uma delas \u00e9 que o n\u00famero de chamadas frustradas por congestionamento do sistema n\u00e3o pode ultrapassar cerca de 2% ou 3% de todas as chamadas\u201d, questionou.<\/p>\n<p style=\"text-align: justify;\">Para a promotora de Direitos do Consumidor do Minist\u00e9rio P\u00fablico de Sergipe, Euza Missano, os usu\u00e1rios precisam insistir nas den\u00fancias contra os p\u00e9ssimos servi\u00e7os, essa tamb\u00e9m \u00e9 uma maneira de promo\u00e7\u00e3o da qualidade disponibilizada.<\/p>\n<p><strong>Siga o SE Not\u00edcias pelo <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Assessoria parlamentar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O senador Eduardo Amorim (PSC-SE), presidiu na manh\u00e3 da ter\u00e7a-feira, 20, a audi\u00eancia p\u00fablica com os presidentes das empresas de telecomunica\u00e7\u00f5es sobre a baixa qualidade dos servi\u00e7os de telefonia m\u00f3vel. Atenderam o requerimento do parlamentar os presidentes da TIM, Rodrigo Abreu; da Vivo, Antonio Carlos Valente da Silva; e da Claro, Carlos Zenteno. No segundo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-64423","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/64423"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=64423"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/64423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/64424"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=64423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=64423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=64423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}