{"id":56976,"date":"2013-12-12T13:25:03","date_gmt":"2013-12-12T16:25:03","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=56976"},"modified":"2013-12-12T13:25:03","modified_gmt":"2013-12-12T16:25:03","slug":"gestante-e-agredida-pelo-ex-marido-em-sao-cristovao","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/gestante-e-agredida-pelo-ex-marido-em-sao-cristovao\/","title":{"rendered":"Gestante \u00e9 agredida pelo ex-marido em S\u00e3o Crist\u00f3v\u00e3o"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><em><strong>Denise Gomes, do G1 SE<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Uma gestante foi agredida fisicamente pelo ex-companheiro que estaria inconformado com o fim do relacionamento na \u00faltima ter\u00e7a-feira (10), na resid\u00eancia em que dividia com ele no Bairro Santa Cruz, mais conhecido por &#8220;Arrepiada&#8221;, no munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o (SE), regi\u00e3o metropolitana de Aracaju. Segundo a v\u00edtima, o casal se separou h\u00e1 um m\u00eas, ap\u00f3s dois anos de relacionamento. A mulher possui tr\u00eas filhos de outro relacionamento e est\u00e1 gr\u00e1vida do agressor.<\/p>\n<div id=\"attachment_56982\" style=\"width: 601px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/20120803_110501.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56982\" class=\"size-full wp-image-56982\" alt=\" A agress\u00e3o aconteceu no Bairro Santa Cruz em S\u00e3o Crist\u00f3v\u00e3o. (Foto de arquivo: SE Not\u00edcias)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/20120803_110501.jpg\" width=\"591\" height=\"443\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/20120803_110501.jpg 591w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/20120803_110501-300x224.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/20120803_110501-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/20120803_110501-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/20120803_110501-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/20120803_110501-269x201.jpg 269w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><\/a><p id=\"caption-attachment-56982\" class=\"wp-caption-text\"><br \/>A agress\u00e3o aconteceu no Bairro Santa Cruz em S\u00e3o Crist\u00f3v\u00e3o. (Foto de arquivo: SE Not\u00edcias)<\/p><\/div>\n<p style=\"text-align: justify;\">O motivo da separa\u00e7\u00e3o seria as agress\u00f5es sofridas constantemente pela mulher, toda vez que o marido consumia bebidas alco\u00f3licas. Em uma delas, segundo a v\u00edtima, o companheiro teria usado uma foice na tentativa de mat\u00e1-la. Ele chegou a ser preso, mas assim que ganhou a liberdade voltou a agredi-la.<\/p>\n<p style=\"text-align: justify;\">De acordo com o boletim de ocorr\u00eancia registrado por ela na Delegacia Plantonista, na capital, o ex-marido teria chegado \u00e0 resid\u00eancia por volta das 17h, e aparentava estar b\u00eabado. Ele pediu para entrar e assim que teve autoriza\u00e7\u00e3o pegou a chave, trancou a casa e saiu. A v\u00edtima, os filhos e a irm\u00e3 do suspeito, que estavam no im\u00f3vel, ficaram impedidos de sair e tiveram que pedir ajuda a uma vizinha, que conseguiu abrir o port\u00e3o uma hora depois do ocorrido.<\/p>\n<p style=\"text-align: justify;\">Horas mais tarde, por volta das 21h30, o homem retornou \u00e0 resid\u00eancia, pediu para entrar e foi autorizado pela v\u00edtima mais uma vez. Houve discuss\u00e3o e ele passou a ofender a v\u00edtima, bem como pegou uma faca de cozinha e fez novas amea\u00e7as de morte. Ela tamb\u00e9m foi agredida com tapas e conseguiu se defender utilizando um peda\u00e7o de madeira.<\/p>\n<p style=\"text-align: justify;\">A pol\u00edcia foi acionada e no percurso at\u00e9 a delegacia ele disse, segundo a v\u00edtima, que j\u00e1 havia amassado um carro de pol\u00edcia antes e poderia \u2018amass\u00e1-la\u2019 tamb\u00e9m. Ele foi autuado em flagrante por viol\u00eancia dom\u00e9stica e permanece detido, j\u00e1 que a fian\u00e7a arbitrada pelo delegado no valor de mil reais n\u00e3o foi paga.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><strong>Siga o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/senoticias\" target=\"_blank\">Twitter <\/a>e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Denise Gomes, do G1 SE Uma gestante foi agredida fisicamente pelo ex-companheiro que estaria inconformado com o fim do relacionamento na \u00faltima ter\u00e7a-feira (10), na resid\u00eancia em que dividia com ele no Bairro Santa Cruz, mais conhecido por &#8220;Arrepiada&#8221;, no munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o (SE), regi\u00e3o metropolitana de Aracaju. Segundo a v\u00edtima, o casal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-56976","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/56976"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=56976"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/56976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/56982"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=56976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=56976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=56976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}