{"id":56947,"date":"2013-12-11T23:16:32","date_gmt":"2013-12-12T02:16:32","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=56947"},"modified":"2013-12-13T10:10:34","modified_gmt":"2013-12-13T13:10:34","slug":"tribunal-de-justica-declara-ilegalidade-de-greve-dos-servidores-do-detran","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tribunal-de-justica-declara-ilegalidade-de-greve-dos-servidores-do-detran\/","title":{"rendered":"Tribunal de Justi\u00e7a declara ilegalidade de greve dos servidores do Detran"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_54140\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Detran.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-54140\" class=\"size-medium wp-image-54140\" alt=\" Justi\u00e7a declara ilegalidade de greve dos servidores do Detran. (Foto: Sergipe \u00e9 Not\u00edcia)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Detran-300x231.jpg\" width=\"300\" height=\"231\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Detran-300x231.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Detran-342x264.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Detran-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Detran.jpg 550w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-54140\" class=\"wp-caption-text\"><br \/>Justi\u00e7a declara ilegalidade de greve dos servidores do Detran. (Foto: Sergipe \u00e9 Not\u00edcia)<\/p><\/div>\n<p style=\"text-align: justify;\">O Pleno do Tribunal de Justi\u00e7a de Sergipe (TJSE), em sess\u00e3o realizada nesta quarta-feira, 11.12, julgou ilegal a greve dos servidores do Departamento Estadual de Tr\u00e2nsito \u2013 DETRAN\/SE. A decis\u00e3o de m\u00e9rito foi proferida nos autos da A\u00e7\u00e3o declarat\u00f3ria 0004\/2013 (Processo n\u00ba 2013110900) e n\u00e3o se refere \u00e0 nova decreta\u00e7\u00e3o de greve realizada ap\u00f3s o dia 30.09.2013.<\/p>\n<p style=\"text-align: justify;\">Segundo o Des. Cez\u00e1rio Siqueira Neto, relator do processo, a A\u00e7\u00e3o Declarat\u00f3ria 0004\/2013 tem como objeto a data de 30\/09\/2013 como termo final. \u201cConforme decidido pelo Juiz convocado Gilson Felix dos Santos, a nova paralisa\u00e7\u00e3o iniciada ap\u00f3s o dia 30 de setembro do corrente ano, trata-se de um novo movimento paredista e n\u00e3o faz parte do objeto desta demanda\u201d, esclareceu o relator.<\/p>\n<p style=\"text-align: justify;\">Com rela\u00e7\u00e3o ao m\u00e9rito da greve realizada pelo SINDETRAN antes do dia 30.09, objeto da A\u00e7\u00e3o Declarat\u00f3ria 0004\/2013, o relator informou que, por permanecer com o mesmo racioc\u00ednio da decis\u00e3o liminar, era de ser julgada procedente a a\u00e7\u00e3o para ser declarada a ilegalidade da greve deflagrada no dia 30.06.2013. \u201cAnalisando detidamente os autos, de logo, apesar de ter sido cumprido o requisito quanto ao prazo da notifica\u00e7\u00e3o acerca da paralisa\u00e7\u00e3o, verifica-se que n\u00e3o restou provado o encerramento das negocia\u00e7\u00f5es. Isto porque verificou-se que houve diversas reuni\u00f5es com o Governador do Estado, tendo o mesmo sinalizado que faria uma nova proposta salarial no m\u00eas de setembro, quando j\u00e1 se teria o resultado do pr\u00f3ximo quadrimestre fiscal. Desta maneira, nessa primeira an\u00e1lise dos autos, patente o fumus boni iures, mostrando-se ilegal o movimento grevista desencadeado pelo Sindicato, sendo desnecess\u00e1ria a an\u00e1lise dos demais requisitos legais, neste momento, posto que a aus\u00eancia de um deles j\u00e1 macula o movimento paredista\u201d, concluiu o desembargador.<\/p>\n<p style=\"text-align: justify;\"><strong>Siga o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/senoticias\" target=\"_blank\">Twitter<\/a> e curta no<a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\"> Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><em><strong>Da Ascom\/TJ\/SE<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O Pleno do Tribunal de Justi\u00e7a de Sergipe (TJSE), em sess\u00e3o realizada nesta quarta-feira, 11.12, julgou ilegal a greve dos servidores do Departamento Estadual de Tr\u00e2nsito \u2013 DETRAN\/SE. A decis\u00e3o de m\u00e9rito foi proferida nos autos da A\u00e7\u00e3o declarat\u00f3ria 0004\/2013 (Processo n\u00ba 2013110900) e n\u00e3o se refere \u00e0 nova decreta\u00e7\u00e3o de greve realizada ap\u00f3s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":54140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310],"tags":[],"class_list":{"0":"post-56947","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/56947"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=56947"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/56947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/54140"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=56947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=56947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=56947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}