{"id":56213,"date":"2013-11-28T14:50:36","date_gmt":"2013-11-28T17:50:36","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=56213"},"modified":"2013-11-28T15:06:13","modified_gmt":"2013-11-28T18:06:13","slug":"policia-prende-dupla-que-roubava-motos-em-sao-cristovao","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/policia-prende-dupla-que-roubava-motos-em-sao-cristovao\/","title":{"rendered":"Pol\u00edcia prende dupla que roubava motos em S\u00e3o Crist\u00f3v\u00e3o"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Foram presos na tarde desta quarta-feira (27), no Povoado Alto do Cristo, em S\u00e3o Crist\u00f3v\u00e3o por policiais civis e militares da 12\u00aa Delegacia e da 1\u00aa Cia de Pol\u00edcia Comunit\u00e1ria, Emerson Alves Santos, vulgo &#8220;Big Big&#8221; e Jos\u00e9 Rosevaldo dos Santos Ferreira, o &#8220;Pinto&#8221;. Segundo o delegado Luis Carlos Xavier, os dois vinham sendo investigados como sendo os principais suspeitos de roubos de moto na regi\u00e3o.<\/p>\n<div id=\"attachment_56214\" style=\"width: 411px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56214\" class=\"size-full wp-image-56214\" alt=\"De acordo com a Pol\u00edcia, a dupla \u00e9 acusada de roubar motos em S\u00e3o Crist\u00f3v\u00e3o.(Foto: sargento Madureira\/arquivo pessoal)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o.jpg\" width=\"401\" height=\"401\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o.jpg 401w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o-150x150.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o-300x300.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o-50x50.jpg 50w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o-342x342.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o-70x70.jpg 70w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/Motos-em-S\u00e3o-Crist\u00f3v\u00e3o-55x55.jpg 55w\" sizes=\"(max-width: 401px) 100vw, 401px\" \/><\/a><p id=\"caption-attachment-56214\" class=\"wp-caption-text\">De acordo com a Pol\u00edcia, a dupla \u00e9 acusada de roubar motos em S\u00e3o Crist\u00f3v\u00e3o.(Foto: sargento Madureira\/arquivo pessoal)<\/p><\/div>\n<p style=\"text-align: justify;\">V\u00e1rias dilig\u00eancias para prender a dupla foram realizadas at\u00e9 que na tarde desta quarta-feira, os dois suspeitos n\u00e3o obedeceram a ordem de parada da pol\u00edcia e empreenderam fuga, sendo perseguidos e presos. Com eles foram apreendidos um rev\u00f3lver calibre 32. Na delegacia, &#8216;Big Big&#8217; confessou que no momento da abordagem estava \u00e0 procura de uma moto CG Titan para roubar.<\/p>\n<p style=\"text-align: justify;\">\u201cA inten\u00e7\u00e3o era realizar um procedimento chamado \u201cvestir&#8221;, onde eles roubariam uma motocicleta nova, retirava as pe\u00e7as e colocaria na moto de Jos\u00e9 Rosevaldo\u201d, destacou Xavier. A pol\u00edcia agora investiga a participa\u00e7\u00e3o da dupla em outros assaltos ocorridos na regi\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Inicialmente a dupla foi abordada pela viatura comandada pelo sargento Mudureira, no Alto do Cristo em S\u00e3o Crist\u00f3v\u00e3o.<\/p>\n<p><span style=\"color: #0000ff;\"><em><strong>Siga o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/\" target=\"_blank\">Twitter<\/a> e curta no <a href=\"  https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/em><\/span><\/p>\n<p><em><strong>Reda\u00e7\u00e3o SE Not\u00edcias com informa\u00e7\u00f5es da SSP\/SE<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Foram presos na tarde desta quarta-feira (27), no Povoado Alto do Cristo, em S\u00e3o Crist\u00f3v\u00e3o por policiais civis e militares da 12\u00aa Delegacia e da 1\u00aa Cia de Pol\u00edcia Comunit\u00e1ria, Emerson Alves Santos, vulgo &#8220;Big Big&#8221; e Jos\u00e9 Rosevaldo dos Santos Ferreira, o &#8220;Pinto&#8221;. Segundo o delegado Luis Carlos Xavier, os dois vinham sendo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-56213","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/56213"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=56213"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/56213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/56214"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=56213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=56213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=56213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}