{"id":56207,"date":"2013-11-28T14:13:00","date_gmt":"2013-11-28T17:13:00","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=56207"},"modified":"2013-11-28T23:41:53","modified_gmt":"2013-11-29T02:41:53","slug":"vereador-iran-cobra-respeito-ambiental-na-obra-da-13-de-julho","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/vereador-iran-cobra-respeito-ambiental-na-obra-da-13-de-julho\/","title":{"rendered":"Vereador Iran cobra respeito ambiental na obra da 13 de Julho"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_56208\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/1483071_403049606494740_99038426_n.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56208\" class=\"size-medium wp-image-56208\" alt=\"Para o vereador, sem observar a quest\u00e3o ambiental, obras podem repetir erros do passado. (Divulga\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/1483071_403049606494740_99038426_n-300x206.jpg\" width=\"300\" height=\"206\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/1483071_403049606494740_99038426_n-300x206.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/1483071_403049606494740_99038426_n-342x235.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/11\/1483071_403049606494740_99038426_n.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-56208\" class=\"wp-caption-text\">Para o vereador, sem observar a quest\u00e3o ambiental, obras podem repetir erros do passado. (Divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">O vereador e professor Iran Barbosa, do PT, usou a tribuna da C\u00e2mara Municipal de Aracaju, nesta quinta-feira, 28\/11, para trazer uma reflex\u00e3o sobre a necessidade de avan\u00e7os na gest\u00e3o administrativa, no tocante \u00e0 engenharia utilizada nas obras p\u00fablicas. Para Iran, durante muito tempo prevaleceu o modelo de grandes obras feitas a partir de decis\u00f5es apenas da engenharia.<\/p>\n<p style=\"text-align: justify;\">Mas para o parlamentar, \u00e9 preciso associar a este modelo, que considera ultrapassado, o conceito ambiental, que \u00e9 uma conquista de direito mais recente na hist\u00f3ria da humanidade.<\/p>\n<p style=\"text-align: justify;\">\u201cEntendendo que a discuss\u00e3o que est\u00e1 sendo feita com rela\u00e7\u00e3o \u00e0s obras na 13 de Julho, precisa levar em considera\u00e7\u00e3o os dois aspectos: o da engenharia e o do meio ambiente\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">Segundo o petista, houve um tempo em que administradores, em Aracaju e no estado de Sergipe, achavam que dar resposta \u00e0s demandas da popula\u00e7\u00e3o era executar grandes obras de engenharia e grandes constru\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">\u201cIsso respondeu, num determinado momento, \u00e0s necessidades da popula\u00e7\u00e3o. Mas o grande desafio que temos que responder hoje \u00e9 tentar somar, de forma adequada, as respostas \u00e0s necessidade da popula\u00e7\u00e3o com obras, com constru\u00e7\u00f5es, com engenharia, atendendo tamb\u00e9m \u00e0s preocupa\u00e7\u00f5es ambientais, respeitando a quest\u00e3o do direito ambiental\u201d, ressaltou.<\/p>\n<p style=\"text-align: justify;\">Para Iran, as obras da Praia 13 de Julho precisam ir nesta linha, da resposta da engenharia sem abrir m\u00e3o da preocupa\u00e7\u00e3o ambiental. Com esta equa\u00e7\u00e3o solucionada, o vereador acredita que \u00e9 poss\u00edvel dar respostas \u00e0s demandas sociais naquela \u00e1rea com garantia da preserva\u00e7\u00e3o ambiental, respondendo \u00e0 quest\u00e3o de seguran\u00e7a e de mobilidade urbana sem avan\u00e7ar para a cria\u00e7\u00e3o de outros problemas no futuro, por causa de impactos ambientais mal estudados e n\u00e3o previstos.<\/p>\n<p style=\"text-align: justify;\">\u201cJ\u00e1 vivenciamos situa\u00e7\u00f5es desse tipo aqui mesmo na nossa cidade, com obras de engenharia que foram muito elogiadas em determinado momento, mas que a natureza depois veio cobrar o seu pre\u00e7o e o seu espa\u00e7o. \u00c9 preciso sempre ter cautela e sensibilidade com rela\u00e7\u00e3o a essas obras\u201d, disse, remetendo \u00e0 cria\u00e7\u00e3o do bairro Coroa do Meio.<\/p>\n<p style=\"text-align: justify;\">Para o petista, o papel que tem a rec\u00e9m-criada Secretaria Municipal de Meio Ambiente \u00e9 o de exatamente dialogar com os setores da \u00e1rea de infraestrutura e de engenharia do governo municipal para preservar, na hora da execu\u00e7\u00e3o de obras, os aspectos ambientais.<\/p>\n<p style=\"text-align: justify;\">\u201cSe esquecermos disso, estamos fadados a cometer erros que j\u00e1 foram cometidos no passado. E quando repetimos os erros, \u00e9 sintoma de ignor\u00e2ncia. Gostaria \u00e9 que acert\u00e1ssemos\u201d, enfatizou.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><strong>Siga o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/\" target=\"_blank\">Twitter <\/a>e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/span><\/p>\n<p><em><strong>George W. Silva, da Assessoria de Imprensa<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O vereador e professor Iran Barbosa, do PT, usou a tribuna da C\u00e2mara Municipal de Aracaju, nesta quinta-feira, 28\/11, para trazer uma reflex\u00e3o sobre a necessidade de avan\u00e7os na gest\u00e3o administrativa, no tocante \u00e0 engenharia utilizada nas obras p\u00fablicas. Para Iran, durante muito tempo prevaleceu o modelo de grandes obras feitas a partir de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6],"tags":[],"class_list":{"0":"post-56207","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/56207"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=56207"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/56207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/56208"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=56207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=56207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=56207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}