{"id":55443,"date":"2013-11-13T14:10:45","date_gmt":"2013-11-13T17:10:45","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=55443"},"modified":"2013-11-13T14:11:08","modified_gmt":"2013-11-13T17:11:08","slug":"jackson-autoriza-construcao-de-580-casas-inaugura-e-visita-obras","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/jackson-autoriza-construcao-de-580-casas-inaugura-e-visita-obras\/","title":{"rendered":"Jackson autoriza constru\u00e7\u00e3o de 580 casas, inaugura e visita obras"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Nesta quinta-feira, 14, o governador do Estado em exerc\u00edcio, Jackson Barreto, assina a Ordem de Servi\u00e7o para constru\u00e7\u00e3o de 580 casas populares no bairro Porto Dantas e inaugura o Centro Comunit\u00e1rio &#8216;Maria Ant\u00f4nia da Concei\u00e7\u00e3o&#8217; no mesmo bairro. Solenidades acontecem a partir das 8h, na avenida General Euclides Figueiredo.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<em><span style=\"color: #0000ff;\">Siga o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/\" target=\"_blank\">Twitter<\/a> e curta no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/span><\/em><\/strong><\/p>\n<div id=\"attachment_53664\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Jackson2.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-53664\" class=\"size-medium wp-image-53664\" alt=\"Solenidades acontecem a partir das 8h, na avenida General Euclides Figueiredo, bairro Porto Dantas. (Foto: Marcos Rodrigues\/ASN)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Jackson2-300x200.jpg\" width=\"300\" height=\"200\" \/><\/a><p id=\"caption-attachment-53664\" class=\"wp-caption-text\">Solenidades acontecem a partir das 8h, na avenida General Euclides Figueiredo, bairro Porto Dantas. (Foto: Marcos Rodrigues\/ASN)<\/p><\/div>\n<p style=\"text-align: justify;\">Fruto do programa Pr\u00f3-Moradia, que oferece acesso \u00e0 moradia adequada a fam\u00edlias de baixa renda, residentes em assentamentos prec\u00e1rios que recebem at\u00e9 tr\u00eas sal\u00e1rios m\u00ednimos. O Pr\u00f3-Moradia \u00e9 gerido pelo Minist\u00e9rio das Cidades e operacionalizado pela Caixa Econ\u00f4mica Federal para oferecer acesso \u00e0 moradia adequada \u00e0 popula\u00e7\u00e3o em situa\u00e7\u00e3o de vulnerabilidade social.<\/p>\n<p style=\"text-align: justify;\">Em Sergipe, a iniciativa consiste na constru\u00e7\u00e3o de 1.180 unidades habitacionais para fam\u00edlias que residem em situa\u00e7\u00f5es insalubres nas ocupa\u00e7\u00f5es da Avenida Euclides Figueiredo 580 unidades habitacionais, em Aracaju e do Rio do Sal 600 unidades habitacionais, emNossa Senhora do Socorro.<\/p>\n<p style=\"text-align: justify;\"><strong>Visita a obras<\/strong><\/p>\n<p style=\"text-align: justify;\">Na sequ\u00eancia, Jackson realiza vista a cinco obras estruturantes que v\u00eam sendo executadas pelo Governo do Estado em Aracaju. S\u00e3o elas: a reforma e amplia\u00e7\u00e3o da Escola Estadual Augusto Franco, o Complexo de Esporte do Santos Dumont, a Reforma do Instituto Educacional Rui Barbosa, a duplica\u00e7\u00e3o do Viaduto do Detran e a reforma do Batist\u00e3o.<\/p>\n<p style=\"text-align: justify;\">As visitas ter\u00e3o in\u00edcio por volta das 9h, na Escola Estadual Augusto Franco, situada no Bairro Santos Dumont. Na unidade, o governo est\u00e1 investindo R$ 1.097.998,86 para a reforma, amplia\u00e7\u00e3o e recupera\u00e7\u00e3o de uma \u00e1rea total de 3.309,28 m\u00b2. A unidade escolar atende a mil alunos, do 2\u00ba ano do ensino fundamental ao 3\u00ba ano do ensino m\u00e9dio.<\/p>\n<p style=\"text-align: justify;\">Em seguida Jackson ir\u00e1 at\u00e9 o Complexo de Esporte do Santos Dumont, que j\u00e1 est\u00e1 em fase de acabamento ap\u00f3s ter sido reformado e ampliado. Num investimento superior a R$ 1 milh\u00e3o, o novo Complexo abrange uma \u00e1rea de 6.532,00 m\u00b2, que inclui v\u00e1rios espa\u00e7os adequados \u00e0 pr\u00e1tica esportiva. Entre eles, um novo campo de futebol e uma quadra poliesportiva.<\/p>\n<p style=\"text-align: justify;\">A terceira obra a ser visitada pelo governador em Aracaju \u00e9 a reforma do Instituto Educacional Rui Barbosa, na Rua Laranjeiras. A proposta \u00e9 transformar a antiga Escola Normal num Centro de Educa\u00e7\u00e3o Continuada, que ofere\u00e7a cursos profissionalizantes nas \u00e1reas de Secretaria, Multimeios, Alimenta\u00e7\u00e3o e Infraestrutura Escolar. Nesse sentido, a unidade ser\u00e1 equipada com laborat\u00f3rios de qu\u00edmica, matem\u00e1tica, infraestrutura e multimeios, entre outros. O investimento chega a R$1.5milh\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Por fim, Jackson visitar\u00e1 duas das obras mais aguardadas pelos aracajuanos: a duplica\u00e7\u00e3o do viaduto do Detran e a reforma do Batist\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Prestes a ser conclu\u00edda, a duplica\u00e7\u00e3o do viaduto tem 220m de extens\u00e3o. A obra or\u00e7ada em R$ 21 milh\u00f5es faz parte dos investimentos em mobilidade urbana do Governo de Sergipe. Est\u00e3o em andamento ainda servi\u00e7os das novas vias de acesso em torno do Viaduto e os novos acessos aos conjuntos JK, Sol Nascente e Santa L\u00facia no Bairro Jabotiana, e ainda o revestimento do canal existente.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 a mais tradicional pra\u00e7a esportiva de Sergipe recebe investimento na ordem de R$ 15,5 milh\u00f5es, sendo R$ 1,6 milh\u00e3o do Governo do Estado e o restante do Governo Federal, por meio do Minist\u00e9rio do Esporte. O Est\u00e1dio Lourival Baptista ter\u00e1 amplia\u00e7\u00e3o de tr\u00eas degraus das arquibancadas com a cria\u00e7\u00e3o de 1.813 novos lugares sentados com cadeira, ampliando, assim, sua capacidade para 14.500 lugares.<\/p>\n<p style=\"text-align: justify;\"><strong>Jo\u00e3o Augusto Freitas<\/strong><br \/>\n<strong> Diretor de Imprensa\/Governo de Sergipe<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Nesta quinta-feira, 14, o governador do Estado em exerc\u00edcio, Jackson Barreto, assina a Ordem de Servi\u00e7o para constru\u00e7\u00e3o de 580 casas populares no bairro Porto Dantas e inaugura o Centro Comunit\u00e1rio &#8216;Maria Ant\u00f4nia da Concei\u00e7\u00e3o&#8217; no mesmo bairro. Solenidades acontecem a partir das 8h, na avenida General Euclides Figueiredo. \u00a0Siga o SE Not\u00edcias no [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":53664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-55443","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/55443"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=55443"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/55443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/53664"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=55443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=55443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=55443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}